{"id":11617,"date":"2024-11-10T08:13:48","date_gmt":"2024-11-10T02:43:48","guid":{"rendered":"https:\/\/aiyoit.com\/tutorial\/?p=11617"},"modified":"2024-11-10T08:14:13","modified_gmt":"2024-11-10T02:44:13","slug":"basic-word-excel-quiz","status":"publish","type":"post","link":"https:\/\/aiyoit.com\/tutorial\/basic-word-excel-quiz\/","title":{"rendered":"Basic, Word &#038; Excel -Quiz"},"content":{"rendered":"\n            <div class='ays-quiz-container ays_quiz_classic_light   ays-quiz-keyboard-active' data-quest-effect='none'  data-bg-gradient='linear-gradient(to bottom, rgba(165,104,226,0.26), #fff)'  data-hide-bg-image='false' id='ays-quiz-container-46'>\n                \n                \n                <div class='ays-questions-container'>\n                    <div class=\"ays-quiz-full-screen-wrap\">\n                <a class=\"ays-quiz-full-screen-container\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24\" fill=\"#fff\" viewBox=\"0 0 24 24\" width=\"24\" class=\"ays-quiz-close-full-screen\">\n                        <path d=\"M0 0h24v24H0z\" fill=\"none\"\/>\n                        <path d=\"M5 16h3v3h2v-5H5v2zm3-8H5v2h5V5H8v3zm6 11h2v-3h3v-2h-5v5zm2-11V5h-2v5h5V8h-3z\"\/>\n                    <\/svg>\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24\" fill=\"#fff\" viewBox=\"0 0 24 24\" width=\"24\" class=\"ays-quiz-open-full-screen\">\n                        <path d=\"M0 0h24v24H0z\" fill=\"none\"\/>\n                        <path d=\"M7 14H5v5h5v-2H7v-3zm-2-4h2V7h3V5H5v5zm12 7h-3v2h5v-5h-2v3zM14 5v2h3v3h2V5h-5z\"\/>\n                    <\/svg>\n                <\/a>\n            <\/div>\n                    \n                    \n                    <form action='' method='post' id='ays_finish_quiz_46' \n                        class='ays-quiz-form  enable_questions_result '\n                    >\n            <input type='hidden' value='list' class='answer_view_class'>\n            <input type='hidden' value='' class='ays_qm_enable_arrows'><section  class='ays_quiz_timer_container'>\n                <div class='ays-quiz-timer ' data-timer='3000'><p>Do not waste your time on only one question<\/p>\n<\/div>\n                <div class='ays-quiz-after-timer  empty_after_timer_text '><\/div>\n                <hr style='height:1px;'>\n            <\/section>\n            \n            \n            <div class='step active-step'>\n                <div class='ays-abs-fs ays-start-page'>\n                    \n                    <img src='https:\/\/aiyoit.com\/tutorial\/wp-content\/uploads\/2022\/12\/cropped-Fave-Icon.png' alt='Test_1' class='ays_quiz_image'>\n                    <p class='ays-fs-title'>Fundamental, Word and Excel - Quiz<\/p>\n                    <div class='ays-fs-subtitle'><p>Hello friend, welcome to this computer quiz \u2013 AIYO IT ,You have 100 questions and 50 minutes for the whole questions, Hope you have come prepared beforehand, I wish you good luck, you will do well..<\/p>\n<\/div>\n                    <input type='hidden' name='ays_quiz_id' value='46'\/>\n                    <input type='hidden' name='ays_quiz_finish_nonce' value='f85f6be96a'>\n                    <input type='hidden' name='ays_quiz_curent_page_link' class='ays-quiz-curent-page-link' value='https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts\/11617'\/>\n                    <input type='hidden' name='ays_quiz_questions' value='773,772,771,770,768,767,766,765,764,699,697,695,693,691,689,688,686,685,682,681,680,679,653,647,646,645,644,643,642,641,640,639,638,637,631,630,629,628,627,626,625,619,618,617,616,614,612,42,41,40,39,38,37,36,33,32,31,30,29,28,27,26,25,24,23,22,21,20,19,18,17,16,15,14,13,12,11,10,9,8,7,6,1057,1058,1059,1056,1054,1053,1052,1051,1044,1042,1043,1041,1034,1030,1031,1023,1022,1021'>\n                    \n                    \n                    <input type='button'   class='ays_next start_button action-button ays-quiz-keyboard-active' value='Start' data-enable-leave-page=\"false\" \/>\n                    \n                    <\/div>\n                <\/div><div class='step'>\n                                    <div class='ays-abs-fs ays-start-page information_form'>\n                                    <div class='ays-form-title'><p>Please fill your required* information<\/p>\n<\/div>\n                                        <input type='text' id='ays_form_field_user_name_46' name='ays_user_name' placeholder='Name' class='ays_quiz_form_input ays_animated_x5ms' required><input type='text' id='ays_form_field_user_email_46' name='ays_user_email' placeholder='Email' class='ays_quiz_form_input ays_animated_x5ms' ><input type='text' id='ays_form_field_user_phone_46' name='ays_user_phone' placeholder='Phone Number' class='ays_quiz_form_input ays_animated_x5ms' required>\n                                        <div class='ays_buttons_div'>\n                                            <i class='ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none'><\/i>\n                                            <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                                        <\/div>\n                                    <\/div>\n                                  <\/div><div class='step ' data-question-id='40' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>1 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>1. <span style=\"font-weight: 400\">MS Paint \u092e\u0947\u0902 \u0915\u093f\u0938\u0940 \u092d\u0940 Document \u0915\u094b Print \u0915\u0930\u0928\u0947 \u0915\u0940 Shortcut Keys \u0939\u0948\u0902 ?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-40]' id='ays-answer-154-46' value='154'\/>\n\n                <label for='ays-answer-154-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Ctrl + S<\/label><label for='ays-answer-154-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-40]' id='ays-answer-155-46' value='155'\/>\n\n                <label for='ays-answer-155-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Ctrl + J<\/label><label for='ays-answer-155-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-40]' id='ays-answer-156-46' value='156'\/>\n\n                <label for='ays-answer-156-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Alt + P<\/label><label for='ays-answer-156-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-40]' id='ays-answer-157-46' value='157'\/>\n\n                <label for='ays-answer-157-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Ctrl + P<\/label><label for='ays-answer-157-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['40'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='630' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>2 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>2. Ms. Word \u0915\u0947 \u092e\u0947\u0928\u0942\u092c\u093e\u0930 \u092e\u0947\u0902 \u0907\u0928\u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928\u0938\u093e Tab \u0928\u0939\u0940\u0902 \u0939\u094b\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-630]' id='ays-answer-2335-46' value='2335'\/>\n\n                <label for='ays-answer-2335-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Insert<\/label><label for='ays-answer-2335-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-630]' id='ays-answer-2336-46' value='2336'\/>\n\n                <label for='ays-answer-2336-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Page Layout<\/label><label for='ays-answer-2336-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-630]' id='ays-answer-2337-46' value='2337'\/>\n\n                <label for='ays-answer-2337-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Animation<\/label><label for='ays-answer-2337-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-630]' id='ays-answer-2338-46' value='2338'\/>\n\n                <label for='ays-answer-2338-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. View<\/label><label for='ays-answer-2338-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['630'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='766' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>3 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>3. Notepad \u092e\u0947\u0902 \u0915\u093f\u0924\u0928\u0947 \u092e\u0947\u0928\u094d\u092f\u0942 \u0939\u094b\u0924\u0947 \u0939\u0948\u0902?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-766]' id='ays-answer-2880-46' value='2880'\/>\n\n                <label for='ays-answer-2880-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 3<\/label><label for='ays-answer-2880-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-766]' id='ays-answer-2881-46' value='2881'\/>\n\n                <label for='ays-answer-2881-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 4<\/label><label for='ays-answer-2881-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-766]' id='ays-answer-2882-46' value='2882'\/>\n\n                <label for='ays-answer-2882-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 5<\/label><label for='ays-answer-2882-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-766]' id='ays-answer-2883-46' value='2883'\/>\n\n                <label for='ays-answer-2883-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 6<\/label><label for='ays-answer-2883-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['766'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='33' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>4 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>4. <span style=\"font-weight: 400\">\u0928\u093f\u092e\u094d\u0928 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928 \u0938\u093e \u092c\u093e\u0930 <\/span><span style=\"font-weight: 400\">MS<\/span> <span style=\"font-weight: 400\">Word<\/span><span style=\"font-weight: 400\"> \u092e\u0947\u0902 \u0928\u0939\u0940 \u0939\u094b\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-33]' id='ays-answer-126-46' value='126'\/>\n\n                <label for='ays-answer-126-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. View Bar<\/label><label for='ays-answer-126-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-33]' id='ays-answer-127-46' value='127'\/>\n\n                <label for='ays-answer-127-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Insert Bar<\/label><label for='ays-answer-127-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-33]' id='ays-answer-128-46' value='128'\/>\n\n                <label for='ays-answer-128-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Formula Bar<\/label><label for='ays-answer-128-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-33]' id='ays-answer-129-46' value='129'\/>\n\n                <label for='ays-answer-129-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0938\u092d\u0940<\/label><label for='ays-answer-129-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['33'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='22' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>5 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>5. <span style=\"font-weight: 400\">\u00a0\u0915\u093f\u0938\u0940 <\/span><span style=\"font-weight: 400\">cell<\/span><span style=\"font-weight: 400\"> \u092e\u0947\u0902 <\/span><span style=\"font-weight: 400\">correction<\/span><span style=\"font-weight: 400\"> (\u0938\u0941\u0927\u093e\u0930) \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-22]' id='ays-answer-82-46' value='82'\/>\n\n                <label for='ays-answer-82-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. F1<\/label><label for='ays-answer-82-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-22]' id='ays-answer-83-46' value='83'\/>\n\n                <label for='ays-answer-83-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. F7<\/label><label for='ays-answer-83-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-22]' id='ays-answer-84-46' value='84'\/>\n\n                <label for='ays-answer-84-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. F2<\/label><label for='ays-answer-84-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-22]' id='ays-answer-85-46' value='85'\/>\n\n                <label for='ays-answer-85-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. F12<\/label><label for='ays-answer-85-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['22'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='768' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>6 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>6. WordPad \u0915\u093f\u0938 \u092a\u094d\u0930\u0915\u093e\u0930 \u0915\u093e \u090f\u092a\u094d\u0932\u093f\u0915\u0947\u0936\u0928 \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-768]' id='ays-answer-2888-46' value='2888'\/>\n\n                <label for='ays-answer-2888-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0917\u0947\u092e \u0921\u0947\u0935\u0932\u092a\u092e\u0947\u0902\u091f (Game Development)<\/label><label for='ays-answer-2888-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-768]' id='ays-answer-2889-46' value='2889'\/>\n\n                <label for='ays-answer-2889-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0935\u0930\u094d\u0921 \u092a\u094d\u0930\u094b\u0938\u0947\u0938\u093f\u0902\u0917 (Word Processing)<\/label><label for='ays-answer-2889-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-768]' id='ays-answer-2890-46' value='2890'\/>\n\n                <label for='ays-answer-2890-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0917\u094d\u0930\u093e\u092b\u093f\u0915\u094d\u0938 \u0921\u093f\u091c\u093c\u093e\u0907\u0928 (Graphics Design)<\/label><label for='ays-answer-2890-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-768]' id='ays-answer-2891-46' value='2891'\/>\n\n                <label for='ays-answer-2891-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0935\u0940\u0921\u093f\u092f\u094b \u090f\u0921\u093f\u091f\u093f\u0902\u0917 (Video Editing)<\/label><label for='ays-answer-2891-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['768'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1056' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>7 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>7. \u0915\u0902\u092a\u094d\u092f\u0942\u091f\u0930 \u0915\u0947 \u0938\u0947\u0902\u091f\u094d\u0930\u0932 \u092a\u094d\u0930\u094b\u0938\u0948\u0938\u093f\u0902\u0917 \u092f\u0942\u0928\u093f\u091f \u0915\u093e Function \u0915\u094d\u092f\u093e \u0915\u0930\u0924\u093e \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1056]' id='ays-answer-4028-46' value='4028'\/>\n\n                <label for='ays-answer-4028-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0921\u0947\u091f\u093e \u0921\u093f\u0932\u0940\u091f \u0915\u0930\u0924\u093e \u0939\u0948<\/label><label for='ays-answer-4028-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1056]' id='ays-answer-4029-46' value='4029'\/>\n\n                <label for='ays-answer-4029-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0907\u0928\u0935\u093e\u0907\u0938 \u092c\u0928\u093e\u0924\u093e \u0939\u0948<\/label><label for='ays-answer-4029-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1056]' id='ays-answer-4030-46' value='4030'\/>\n\n                <label for='ays-answer-4030-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0917\u0923\u0928\u093e\u090f\u0901 \u0914\u0930 \u092a\u094d\u0930\u094b\u0938\u0948\u0938\u093f\u0902\u0917 \u0915\u0930\u0924\u093e \u0939\u0948<\/label><label for='ays-answer-4030-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1056]' id='ays-answer-4031-46' value='4031'\/>\n\n                <label for='ays-answer-4031-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947\u0902 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-4031-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1056'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='629' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>8 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>8. Word \u092e\u0947\u0902 \u0928\u092f\u093e Doc. File\u00a0 \u0932\u0947\u0928\u0947 \u0915\u0940 \u2014\u2014\u2014\u2014\u2014\u2013Shortcut Key \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-629]' id='ays-answer-2331-46' value='2331'\/>\n\n                <label for='ays-answer-2331-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. CTRL + N<\/label><label for='ays-answer-2331-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-629]' id='ays-answer-2332-46' value='2332'\/>\n\n                <label for='ays-answer-2332-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. CTRL + Enter<\/label><label for='ays-answer-2332-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-629]' id='ays-answer-2333-46' value='2333'\/>\n\n                <label for='ays-answer-2333-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. CTRL + H<\/label><label for='ays-answer-2333-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-629]' id='ays-answer-2334-46' value='2334'\/>\n\n                <label for='ays-answer-2334-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. CTRL + B<\/label><label for='ays-answer-2334-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['629'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='642' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>9 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>9. <strong>\u0938\u092c\u0938\u0947 \u092a\u0939\u0932\u093e \u0915\u0902\u092a\u094d\u092f\u0942\u091f\u0930 \u0915\u093e \u0928\u093e\u092e \u0915\u094d\u092f\u093e \u0925\u093e ?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-642]' id='ays-answer-2383-46' value='2383'\/>\n\n                <label for='ays-answer-2383-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. ATARIS<\/label><label for='ays-answer-2383-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-642]' id='ays-answer-2384-46' value='2384'\/>\n\n                <label for='ays-answer-2384-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. ENIAC<\/label><label for='ays-answer-2384-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-642]' id='ays-answer-2385-46' value='2385'\/>\n\n                <label for='ays-answer-2385-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. TANDY<\/label><label for='ays-answer-2385-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-642]' id='ays-answer-2386-46' value='2386'\/>\n\n                <label for='ays-answer-2386-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. NOVELLA<\/label><label for='ays-answer-2386-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['642'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='679' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>10 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>10. MS Word \u092e\u0947\u0902 Similar Formatting \u0915\u093f\u0938 Tab \u092e\u0947 \u092e\u093f\u0932\u0924\u093e \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-679]' id='ays-answer-2531-46' value='2531'\/>\n\n                <label for='ays-answer-2531-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Insert<\/label><label for='ays-answer-2531-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-679]' id='ays-answer-2532-46' value='2532'\/>\n\n                <label for='ays-answer-2532-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Design<\/label><label for='ays-answer-2532-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-679]' id='ays-answer-2533-46' value='2533'\/>\n\n                <label for='ays-answer-2533-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Layout<\/label><label for='ays-answer-2533-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-679]' id='ays-answer-2534-46' value='2534'\/>\n\n                <label for='ays-answer-2534-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-2534-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['679'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1022' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>11 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>11. MS Excel \u092e\u0947\u0902 \u091a\u092f\u0928\u093f\u0924 \u0938\u0947\u0932\u094d\u0938 \u0915\u094b \u092b\u093c\u093f\u0932\u094d\u091f\u0930 \u0915\u0930\u0928\u0947 \u0915\u094b \u0938\u0915\u094d\u0937\u092e \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0936\u0949\u0930\u094d\u091f\u0915\u091f \u0915\u092e\u093e\u0902\u0921 \u0915\u094d\u092f\u093e \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1022]' id='ays-answer-3892-46' value='3892'\/>\n\n                <label for='ays-answer-3892-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Ctrl+Shift+L<\/label><label for='ays-answer-3892-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1022]' id='ays-answer-3893-46' value='3893'\/>\n\n                <label for='ays-answer-3893-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Ctrl+F<\/label><label for='ays-answer-3893-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1022]' id='ays-answer-3894-46' value='3894'\/>\n\n                <label for='ays-answer-3894-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Ctrl+L<\/label><label for='ays-answer-3894-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1022]' id='ays-answer-3895-46' value='3895'\/>\n\n                <label for='ays-answer-3895-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. None<\/label><label for='ays-answer-3895-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1022'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='6' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>12 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>12. \u0938\u093f\u0932\u0947\u0915\u094d\u091f\u0947\u0921 \u0932\u093e\u0907\u0928 \u0915\u094b \u092c\u094b\u0932\u094d\u0921 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0936\u0949\u0930\u094d\u091f\u0915\u091f Key \u0915\u094d\u092f\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-6]' id='ays-answer-18-46' value='18'\/>\n\n                <label for='ays-answer-18-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Ctrl + B<\/label><label for='ays-answer-18-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-6]' id='ays-answer-19-46' value='19'\/>\n\n                <label for='ays-answer-19-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Ctrl + D<\/label><label for='ays-answer-19-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-6]' id='ays-answer-20-46' value='20'\/>\n\n                <label for='ays-answer-20-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Shift + B<\/label><label for='ays-answer-20-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-6]' id='ays-answer-21-46' value='21'\/>\n\n                <label for='ays-answer-21-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Alt + B<\/label><label for='ays-answer-21-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['6'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='23' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>13 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>13. <span style=\"font-weight: 400\">\u091a\u094c\u095c\u0947 <\/span><span style=\"font-weight: 400\">format<\/span><span style=\"font-weight: 400\"> \u092e\u0947\u0902 <\/span><span style=\"font-weight: 400\">print<\/span><span style=\"font-weight: 400\"> \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f <\/span><span style=\"font-weight: 400\">orientation<\/span><span style=\"font-weight: 400\"> \u0939\u094b\u0917\u093e?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-23]' id='ays-answer-86-46' value='86'\/>\n\n                <label for='ays-answer-86-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. landscape<\/label><label for='ays-answer-86-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-23]' id='ays-answer-87-46' value='87'\/>\n\n                <label for='ays-answer-87-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. vertical<\/label><label for='ays-answer-87-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-23]' id='ays-answer-88-46' value='88'\/>\n\n                <label for='ays-answer-88-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. portrait<\/label><label for='ays-answer-88-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-23]' id='ays-answer-89-46' value='89'\/>\n\n                <label for='ays-answer-89-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. horizontal<\/label><label for='ays-answer-89-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['23'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='695' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>14 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>14. Print Preview \u0915\u0947 \u0932\u093f\u090f \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u0940 \u091c\u093e\u0928\u0947 \u0935\u093e\u0932\u0940 \u0936\u0949\u0930\u094d\u091f\u0915\u091f \u0915\u0940 \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-695]' id='ays-answer-2595-46' value='2595'\/>\n\n                <label for='ays-answer-2595-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Ctrl + F1<\/label><label for='ays-answer-2595-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-695]' id='ays-answer-2596-46' value='2596'\/>\n\n                <label for='ays-answer-2596-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Ctrl + F2<\/label><label for='ays-answer-2596-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-695]' id='ays-answer-2597-46' value='2597'\/>\n\n                <label for='ays-answer-2597-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Ctrl + F5<\/label><label for='ays-answer-2597-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-695]' id='ays-answer-2598-46' value='2598'\/>\n\n                <label for='ays-answer-2598-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Ctrl + F10<\/label><label for='ays-answer-2598-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['695'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='770' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>15 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>15. \u092a\u094d\u0930\u0938\u094d\u0924\u093e\u0935\u0928\u093e \u0915\u0947 \u0932\u093f\u090f WordPad \u0915\u093e \u0915\u094c\u0928 \u0938\u093e \u0930\u0942\u092a \u0938\u093e\u092e\u093e\u0928\u094d\u092f \u0930\u0942\u092a \u0938\u0947 \u0916\u0941\u0932\u0924\u093e \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-770]' id='ays-answer-2896-46' value='2896'\/>\n\n                <label for='ays-answer-2896-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. .wpf<\/label><label for='ays-answer-2896-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-770]' id='ays-answer-2897-46' value='2897'\/>\n\n                <label for='ays-answer-2897-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. .txt<\/label><label for='ays-answer-2897-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-770]' id='ays-answer-2898-46' value='2898'\/>\n\n                <label for='ays-answer-2898-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. .wpd<\/label><label for='ays-answer-2898-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-770]' id='ays-answer-2899-46' value='2899'\/>\n\n                <label for='ays-answer-2899-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. .doc<\/label><label for='ays-answer-2899-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['770'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='691' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>16 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>16. \u092a\u0939\u0932\u093e \u092e\u093f\u0928\u0940 \u0915\u0902\u092a\u094d\u092f\u0942\u091f\u0930 \u0915\u092c \u092c\u0928\u093e\u092f\u093e \u0917\u092f\u093e \u0925\u093e?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-691]' id='ays-answer-2579-46' value='2579'\/>\n\n                <label for='ays-answer-2579-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1954<\/label><label for='ays-answer-2579-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-691]' id='ays-answer-2580-46' value='2580'\/>\n\n                <label for='ays-answer-2580-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1965<\/label><label for='ays-answer-2580-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-691]' id='ays-answer-2581-46' value='2581'\/>\n\n                <label for='ays-answer-2581-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 1972<\/label><label for='ays-answer-2581-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-691]' id='ays-answer-2582-46' value='2582'\/>\n\n                <label for='ays-answer-2582-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 1981<\/label><label for='ays-answer-2582-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['691'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='30' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>17 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>17. <span style=\"font-weight: 400\">LCD <\/span><span style=\"font-weight: 400\">\u0915\u093e \u092b\u0942\u0932 \u092b\u0949\u0930\u094d\u092e -<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-30]' id='ays-answer-114-46' value='114'\/>\n\n                <label for='ays-answer-114-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Liqued Creystal Display<\/label><label for='ays-answer-114-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-30]' id='ays-answer-115-46' value='115'\/>\n\n                <label for='ays-answer-115-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Liquid Creystal Display<\/label><label for='ays-answer-115-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-30]' id='ays-answer-116-46' value='116'\/>\n\n                <label for='ays-answer-116-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Liquid Crystal Display<\/label><label for='ays-answer-116-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-30]' id='ays-answer-117-46' value='117'\/>\n\n                <label for='ays-answer-117-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Liqued Creyastal Display<\/label><label for='ays-answer-117-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['30'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='16' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>18 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>18. <span style=\"font-weight: 400\">Bookmark<\/span> <span style=\"font-weight: 400\">option<\/span> MS <span style=\"font-weight: 400\">word<\/span><span style=\"font-weight: 400\"> \u092e\u0947\u0902 \u0915\u093f\u0938 Group<\/span><span style=\"font-weight: 400\">\u00a0\u092e\u0947\u0902 \u092e\u093f\u0932\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-16]' id='ays-answer-58-46' value='58'\/>\n\n                <label for='ays-answer-58-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Clipboard<\/label><label for='ays-answer-58-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-16]' id='ays-answer-59-46' value='59'\/>\n\n                <label for='ays-answer-59-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Links<\/label><label for='ays-answer-59-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-16]' id='ays-answer-60-46' value='60'\/>\n\n                <label for='ays-answer-60-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Bookmark<\/label><label for='ays-answer-60-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-16]' id='ays-answer-61-46' value='61'\/>\n\n                <label for='ays-answer-61-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940<\/label><label for='ays-answer-61-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['16'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='32' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>19 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>19. <span style=\"font-weight: 400\">\u0926\u094b Word \u0915\u0947 \u092c\u093f\u091a \u0926\u0941\u0930\u0940 \u092c\u0928\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f <\/span><span style=\"font-weight: 400\">Keyboard<\/span><span style=\"font-weight: 400\">\u00a0 \u0915\u0947 \u0915\u093f\u0938 <\/span><span style=\"font-weight: 400\">Key<\/span><span style=\"font-weight: 400\"> \u0915\u093e \u0909\u0938 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-32]' id='ays-answer-122-46' value='122'\/>\n\n                <label for='ays-answer-122-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Shift Key<\/label><label for='ays-answer-122-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-32]' id='ays-answer-123-46' value='123'\/>\n\n                <label for='ays-answer-123-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Delete<\/label><label for='ays-answer-123-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-32]' id='ays-answer-124-46' value='124'\/>\n\n                <label for='ays-answer-124-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Space Button<\/label><label for='ays-answer-124-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-32]' id='ays-answer-125-46' value='125'\/>\n\n                <label for='ays-answer-125-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. F1<\/label><label for='ays-answer-125-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['32'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='618' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>20 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>20. <strong>\u0915\u0902\u092a\u094d\u092f\u0942\u091f\u0930 \u092e\u0947\u0902 \u0938\u0941\u091a\u0928\u093e \u0915\u093f\u0938\u0947 \u0915\u0939\u093e \u091c\u093e\u0924\u093e \u0939\u0948 <\/strong><strong>?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-618]' id='ays-answer-2287-46' value='2287'\/>\n\n                <label for='ays-answer-2287-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0921\u0947\u091f\u093e \u0915\u094b<\/label><label for='ays-answer-2287-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-618]' id='ays-answer-2288-46' value='2288'\/>\n\n                <label for='ays-answer-2288-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u0902\u0916\u094d\u092f\u093e\u0913\u0902 \u0915\u094b<\/label><label for='ays-answer-2288-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-618]' id='ays-answer-2289-46' value='2289'\/>\n\n                <label for='ays-answer-2289-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u090f\u0915\u0924\u094d\u0930\u093f\u0924 \u0921\u0947\u091f\u093e \u0915\u094b<\/label><label for='ays-answer-2289-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-618]' id='ays-answer-2290-46' value='2290'\/>\n\n                <label for='ays-answer-2290-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092f\u0947 \u0938\u092d\u0940<\/label><label for='ays-answer-2290-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['618'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='8' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>21 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>21. \u0915\u093f\u0938\u0940 \u092a\u0948\u0930\u093e\u0917\u094d\u0930\u093e\u092b \u0915\u0940 \u0932\u093e\u0907\u0928\u094b\u0902 \u0915\u0947 \u092c\u093f\u091a \u0938\u094d\u092a\u0947\u0938 \u0915\u094b \u092c\u095d\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0938 \u0915\u092e\u093e\u0902\u0921 \u0915\u093e \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-8]' id='ays-answer-26-46' value='26'\/>\n\n                <label for='ays-answer-26-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Alignment<\/label><label for='ays-answer-26-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-8]' id='ays-answer-27-46' value='27'\/>\n\n                <label for='ays-answer-27-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. indent<\/label><label for='ays-answer-27-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-8]' id='ays-answer-28-46' value='28'\/>\n\n                <label for='ays-answer-28-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Line space<\/label><label for='ays-answer-28-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-8]' id='ays-answer-29-46' value='29'\/>\n\n                <label for='ays-answer-29-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-29-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['8'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='638' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>22 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>22. Help Option \u0915\u094b \u0916\u094b\u0932\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u0940\u092c\u094b\u0930\u094d\u0921 \u092e\u0947\u0902 \u092a\u094d\u0930\u0947\u0938 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-638]' id='ays-answer-2367-46' value='2367'\/>\n\n                <label for='ays-answer-2367-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. F3<\/label><label for='ays-answer-2367-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-638]' id='ays-answer-2368-46' value='2368'\/>\n\n                <label for='ays-answer-2368-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. F12<\/label><label for='ays-answer-2368-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-638]' id='ays-answer-2369-46' value='2369'\/>\n\n                <label for='ays-answer-2369-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. F11<\/label><label for='ays-answer-2369-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-638]' id='ays-answer-2370-46' value='2370'\/>\n\n                <label for='ays-answer-2370-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. F1<\/label><label for='ays-answer-2370-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['638'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='693' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>23 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>23. \u091f\u094d\u0930\u093e\u0902\u091c\u093f\u0938\u094d\u091f\u0930 \u0915\u093e \u0905\u0935\u093f\u0937\u094d\u0915\u093e\u0930 \u0915\u092c \u0939\u0941\u0906 \u0925\u093e?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-693]' id='ays-answer-2587-46' value='2587'\/>\n\n                <label for='ays-answer-2587-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1938<\/label><label for='ays-answer-2587-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-693]' id='ays-answer-2588-46' value='2588'\/>\n\n                <label for='ays-answer-2588-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1990<\/label><label for='ays-answer-2588-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-693]' id='ays-answer-2589-46' value='2589'\/>\n\n                <label for='ays-answer-2589-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 1980<\/label><label for='ays-answer-2589-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-693]' id='ays-answer-2590-46' value='2590'\/>\n\n                <label for='ays-answer-2590-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 1948<\/label><label for='ays-answer-2590-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['693'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='617' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>24 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>24. <strong>\u0938\u0940 \u092a\u0940 \u092f\u0942 \u0915\u093e \u092e\u0941\u0916\u094d\u092f \u0918\u091f\u0915 \u0939\u0948 ?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-617]' id='ays-answer-2283-46' value='2283'\/>\n\n                <label for='ays-answer-2283-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0915\u0902\u091f\u094d\u0930\u094b\u0932 \u092f\u0942\u0928\u093f\u091f<\/label><label for='ays-answer-2283-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-617]' id='ays-answer-2284-46' value='2284'\/>\n\n                <label for='ays-answer-2284-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092e\u0947\u092e\u094b\u0930\u0940<\/label><label for='ays-answer-2284-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-617]' id='ays-answer-2285-46' value='2285'\/>\n\n                <label for='ays-answer-2285-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0930\u094d\u0925\u092e\u0948\u091f\u093f\u0915 \u0932\u0949\u091c\u093f\u0915 \u092f\u0942\u0928\u093f\u091f<\/label><label for='ays-answer-2285-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-617]' id='ays-answer-2286-46' value='2286'\/>\n\n                <label for='ays-answer-2286-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092f\u0947 \u0938\u092d\u0940<\/label><label for='ays-answer-2286-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['617'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='685' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>25 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>25. \u0938\u0930\u094d\u091a \u092c\u0949\u0915\u094d\u0938 \u0932\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f _____ \u0926\u092c\u093e\u090f\u0902?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-685]' id='ays-answer-2555-46' value='2555'\/>\n\n                <label for='ays-answer-2555-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Shift + F2<\/label><label for='ays-answer-2555-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-685]' id='ays-answer-2556-46' value='2556'\/>\n\n                <label for='ays-answer-2556-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Shift + F5<\/label><label for='ays-answer-2556-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-685]' id='ays-answer-2557-46' value='2557'\/>\n\n                <label for='ays-answer-2557-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Shift + F9<\/label><label for='ays-answer-2557-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-685]' id='ays-answer-2558-46' value='2558'\/>\n\n                <label for='ays-answer-2558-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Shift + F10<\/label><label for='ays-answer-2558-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['685'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1051' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>26 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>26. \u092e\u093e\u0909\u0938 \u0915\u0940 \u0915\u094d\u0930\u093f\u092f\u093e \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1051]' id='ays-answer-4008-46' value='4008'\/>\n\n                <label for='ays-answer-4008-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0938\u093f\u0902\u0917\u0932 \u0915\u094d\u0932\u093f\u0915<\/label><label for='ays-answer-4008-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1051]' id='ays-answer-4009-46' value='4009'\/>\n\n                <label for='ays-answer-4009-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0921\u092c\u0932 \u0915\u094d\u0932\u093f\u0915<\/label><label for='ays-answer-4009-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1051]' id='ays-answer-4010-46' value='4010'\/>\n\n                <label for='ays-answer-4010-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0921\u094d\u0930\u0948\u0917 \u090f\u0902\u0921 \u0921\u094d\u0930\u093e\u092a<\/label><label for='ays-answer-4010-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1051]' id='ays-answer-4011-46' value='4011'\/>\n\n                <label for='ays-answer-4011-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0909\u092a\u0930\u094b\u0915\u094d\u0924 \u0938\u092d\u0940<\/label><label for='ays-answer-4011-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1051'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='639' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>27 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>27. Ctrl + Shift +\u00a0 &gt; \u0938\u0947 \u0939\u094b\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-639]' id='ays-answer-2371-46' value='2371'\/>\n\n                <label for='ays-answer-2371-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Increase Font Size<\/label><label for='ays-answer-2371-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-639]' id='ays-answer-2372-46' value='2372'\/>\n\n                <label for='ays-answer-2372-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Decrease Font Size<\/label><label for='ays-answer-2372-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-639]' id='ays-answer-2373-46' value='2373'\/>\n\n                <label for='ays-answer-2373-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Change Text Style<\/label><label for='ays-answer-2373-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-639]' id='ays-answer-2374-46' value='2374'\/>\n\n                <label for='ays-answer-2374-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. None<\/label><label for='ays-answer-2374-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['639'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='31' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>28 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>28. <span style=\"font-weight: 400\">Word \u092e\u0947\u0902 Hyphenation \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0938 Tab \u0915\u093e \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u0930\u0924\u0947 \u0939\u0948?\u00a0 <\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-31]' id='ays-answer-118-46' value='118'\/>\n\n                <label for='ays-answer-118-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Page Setup<\/label><label for='ays-answer-118-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-31]' id='ays-answer-119-46' value='119'\/>\n\n                <label for='ays-answer-119-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Insert<\/label><label for='ays-answer-119-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-31]' id='ays-answer-120-46' value='120'\/>\n\n                <label for='ays-answer-120-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Layout<\/label><label for='ays-answer-120-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-31]' id='ays-answer-121-46' value='121'\/>\n\n                <label for='ays-answer-121-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Mailing<\/label><label for='ays-answer-121-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['31'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1059' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>29 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>29. \u092c\u093e\u0907\u0928\u0930\u0940 \u0928\u0902\u092c\u0930 \u092a\u094d\u0930\u0923\u093e\u0932\u0940 \u092e\u0947\u0902 \u0915\u093f\u0924\u0928\u0947 \u0905\u0902\u0915 \u0939\u094b\u0924\u0947 \u0939\u0948\u0902?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1059]' id='ays-answer-4040-46' value='4040'\/>\n\n                <label for='ays-answer-4040-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1<\/label><label for='ays-answer-4040-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1059]' id='ays-answer-4041-46' value='4041'\/>\n\n                <label for='ays-answer-4041-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 2<\/label><label for='ays-answer-4041-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1059]' id='ays-answer-4042-46' value='4042'\/>\n\n                <label for='ays-answer-4042-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 4<\/label><label for='ays-answer-4042-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1059]' id='ays-answer-4043-46' value='4043'\/>\n\n                <label for='ays-answer-4043-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 8<\/label><label for='ays-answer-4043-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1059'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1034' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>30 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>30. \u090f\u092e.\u090f\u0938. \u0935\u0930\u094d\u0921 \u092e\u0947\u0902 \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928-\u0938\u093e \u092a\u0947\u091c \u092e\u093e\u0930\u094d\u091c\u093f\u0928 \u0915\u093e \u090f\u0915 \u092a\u094d\u0930\u0915\u093e\u0930 \u0928\u0939\u0940\u0902 \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1034]' id='ays-answer-3940-46' value='3940'\/>\n\n                <label for='ays-answer-3940-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0938\u0947\u0928\u094d\u091f\u0930<\/label><label for='ays-answer-3940-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1034]' id='ays-answer-3941-46' value='3941'\/>\n\n                <label for='ays-answer-3941-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092c\u0949\u091f\u092e<\/label><label for='ays-answer-3941-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1034]' id='ays-answer-3942-46' value='3942'\/>\n\n                <label for='ays-answer-3942-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0932\u0947\u092b\u094d\u091f<\/label><label for='ays-answer-3942-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1034]' id='ays-answer-3943-46' value='3943'\/>\n\n                <label for='ays-answer-3943-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0930\u093e\u0907\u091f<\/label><label for='ays-answer-3943-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1034'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='697' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>31 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>31. \u092e\u0947\u092e\u094b\u0930\u0940 \u092e\u0947\u0902 kb \u0915\u093e \u092a\u0942\u0930\u093e \u0928\u093e\u092e?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-697]' id='ays-answer-2603-46' value='2603'\/>\n\n                <label for='ays-answer-2603-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Kilobit<\/label><label for='ays-answer-2603-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-697]' id='ays-answer-2604-46' value='2604'\/>\n\n                <label for='ays-answer-2604-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Kilobyte<\/label><label for='ays-answer-2604-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-697]' id='ays-answer-2605-46' value='2605'\/>\n\n                <label for='ays-answer-2605-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Knowbit<\/label><label for='ays-answer-2605-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-697]' id='ays-answer-2606-46' value='2606'\/>\n\n                <label for='ays-answer-2606-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Kneebyte<\/label><label for='ays-answer-2606-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['697'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='20' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>32 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>32. <span style=\"font-weight: 400\">\u00a0\u0915\u093f\u0938 <\/span><span style=\"font-weight: 400\">function<\/span><span style=\"font-weight: 400\"> \u0915\u0947 \u0926\u094d\u0935\u093e\u0930\u093e<\/span><span style=\"font-weight: 400\"> current<\/span> <span style=\"font-weight: 400\">date and time<\/span> <span style=\"font-weight: 400\">insert<\/span><span style=\"font-weight: 400\"> \u0939\u094b \u091c\u093e\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-20]' id='ays-answer-74-46' value='74'\/>\n\n                <label for='ays-answer-74-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. =yesterday day( )<\/label><label for='ays-answer-74-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-20]' id='ays-answer-75-46' value='75'\/>\n\n                <label for='ays-answer-75-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. =tomorrow()<\/label><label for='ays-answer-75-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-20]' id='ays-answer-76-46' value='76'\/>\n\n                <label for='ays-answer-76-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. =today()<\/label><label for='ays-answer-76-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-20]' id='ays-answer-77-46' value='77'\/>\n\n                <label for='ays-answer-77-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. =now()<\/label><label for='ays-answer-77-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['20'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='12' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>33 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>33. <span style=\"font-weight: 400\">MS word <\/span><span style=\"font-weight: 400\">\u0915\u093e \u092e\u093e\u0928\u094d\u092f \u092a\u094d\u0930\u093e\u0930\u0942\u092a (<\/span><span style=\"font-weight: 400\">Extension Name)<\/span><span style=\"font-weight: 400\"> \u0915\u094d\u092f\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-12]' id='ays-answer-42-46' value='42'\/>\n\n                <label for='ays-answer-42-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. .xls<\/label><label for='ays-answer-42-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-12]' id='ays-answer-43-46' value='43'\/>\n\n                <label for='ays-answer-43-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. .docux<\/label><label for='ays-answer-43-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-12]' id='ays-answer-44-46' value='44'\/>\n\n                <label for='ays-answer-44-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. .docx<\/label><label for='ays-answer-44-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-12]' id='ays-answer-45-46' value='45'\/>\n\n                <label for='ays-answer-45-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. .dac<\/label><label for='ays-answer-45-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['12'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='767' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>34 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>34. \u0935\u0930\u094d\u0921\u092a\u0948\u0921 \u092e\u0947\u0902 \u0939\u094b\u092e \u0914\u0930 \u0935\u094d\u092f\u0942 \u0915\u094b \u0915\u094d\u092f\u093e \u0915\u0939\u0924\u0947 \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-767]' id='ays-answer-2884-46' value='2884'\/>\n\n                <label for='ays-answer-2884-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0921\u0947\u091f\u093e<\/label><label for='ays-answer-2884-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-767]' id='ays-answer-2885-46' value='2885'\/>\n\n                <label for='ays-answer-2885-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u091f\u0948\u092c<\/label><label for='ays-answer-2885-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-767]' id='ays-answer-2886-46' value='2886'\/>\n\n                <label for='ays-answer-2886-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0932\u093f\u0928\u094d\u092e\u0947\u0902\u091f<\/label><label for='ays-answer-2886-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-767]' id='ays-answer-2887-46' value='2887'\/>\n\n                <label for='ays-answer-2887-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092b\u093e\u0907\u0932<\/label><label for='ays-answer-2887-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['767'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='42' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>35 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>35. <b>Magnifier, Eraser \u0914\u0930 Fill color \u0915\u0939\u093e\u0901 \u0939\u094b\u0924\u0947 \u0939\u0948 ?<\/b><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-42]' id='ays-answer-162-46' value='162'\/>\n\n                <label for='ays-answer-162-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Tools<\/label><label for='ays-answer-162-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-42]' id='ays-answer-163-46' value='163'\/>\n\n                <label for='ays-answer-163-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Menu bar<\/label><label for='ays-answer-163-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-42]' id='ays-answer-164-46' value='164'\/>\n\n                <label for='ays-answer-164-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Ribbon<\/label><label for='ays-answer-164-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-42]' id='ays-answer-165-46' value='165'\/>\n\n                <label for='ays-answer-165-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Color box<\/label><label for='ays-answer-165-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['42'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='625' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>36 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>36. Text Formatting \u0915\u094d\u092f\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-625]' id='ays-answer-2315-46' value='2315'\/>\n\n                <label for='ays-answer-2315-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0936\u092c\u094d\u0926 \u092e\u0947\u0902 Colour \u0926\u0947\u0928\u093e \u0914\u0930 \u0936\u092c\u094d\u0926 \u0915\u094b underline \u0915\u0930\u0928\u093e<\/label><label for='ays-answer-2315-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-625]' id='ays-answer-2316-46' value='2316'\/>\n\n                <label for='ays-answer-2316-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0936\u092c\u094d\u0926 \u0915\u0947 \u092b\u0949\u0923\u094d\u091f \u092c\u0926\u0932\u0928\u093e<\/label><label for='ays-answer-2316-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-625]' id='ays-answer-2317-46' value='2317'\/>\n\n                <label for='ays-answer-2317-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0936\u092c\u094d\u0926 \u0915\u094b Bold \u0914\u0930 Italic \u0915\u0930\u0928\u093e<\/label><label for='ays-answer-2317-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-625]' id='ays-answer-2318-46' value='2318'\/>\n\n                <label for='ays-answer-2318-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0909\u092a\u0930\u094b\u0915\u094d\u0924 \u0938\u092d\u0940<\/label><label for='ays-answer-2318-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['625'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='643' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>37 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>37. \u0906\u0927\u0941\u0928\u093f\u0915 \u0915\u092e\u094d\u092a\u094d\u092f\u0942\u091f\u0930 \u0915\u0940 \u0916\u094b\u091c \u0938\u0930\u094d\u0935\u092a\u094d\u0930\u0925\u092e \u0915\u092c \u0939\u0941\u0908 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-643]' id='ays-answer-2387-46' value='2387'\/>\n\n                <label for='ays-answer-2387-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1949<\/label><label for='ays-answer-2387-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-643]' id='ays-answer-2388-46' value='2388'\/>\n\n                <label for='ays-answer-2388-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1951<\/label><label for='ays-answer-2388-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-643]' id='ays-answer-2389-46' value='2389'\/>\n\n                <label for='ays-answer-2389-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 1946<\/label><label for='ays-answer-2389-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-643]' id='ays-answer-2390-46' value='2390'\/>\n\n                <label for='ays-answer-2390-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 1947<\/label><label for='ays-answer-2390-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['643'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='773' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>38 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>38. MS \u090f\u0915\u094d\u0938\u0947\u0932 \u092e\u0947\u0902 \u0938\u092c\u0938\u0947 \u092c\u095c\u0940 \u0935\u0948\u0932\u094d\u092f\u0942 \u0928\u093f\u0915\u093e\u0932\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0938 \u092b\u093e\u0930\u094d\u092e\u0942\u0932\u093e \u0915\u093e \u0909\u092a\u092f\u094b\u0917 \u0915\u093f\u092f\u093e \u091c\u093e\u092f\u0947\u0917\u093e ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-773]' id='ays-answer-2908-46' value='2908'\/>\n\n                <label for='ays-answer-2908-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. =sum<\/label><label for='ays-answer-2908-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-773]' id='ays-answer-2909-46' value='2909'\/>\n\n                <label for='ays-answer-2909-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. =Max<\/label><label for='ays-answer-2909-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-773]' id='ays-answer-2910-46' value='2910'\/>\n\n                <label for='ays-answer-2910-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. =Abs<\/label><label for='ays-answer-2910-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-773]' id='ays-answer-2911-46' value='2911'\/>\n\n                <label for='ays-answer-2911-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. =Min<\/label><label for='ays-answer-2911-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['773'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='641' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>39 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>39. Format Painter \u0915\u093f\u0938 Menu \u092e\u0947\u0902 \u0906\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-641]' id='ays-answer-2379-46' value='2379'\/>\n\n                <label for='ays-answer-2379-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Home Menu<\/label><label for='ays-answer-2379-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-641]' id='ays-answer-2380-46' value='2380'\/>\n\n                <label for='ays-answer-2380-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Insert Menu<\/label><label for='ays-answer-2380-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-641]' id='ays-answer-2381-46' value='2381'\/>\n\n                <label for='ays-answer-2381-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Page Layout<\/label><label for='ays-answer-2381-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-641]' id='ays-answer-2382-46' value='2382'\/>\n\n                <label for='ays-answer-2382-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. None<\/label><label for='ays-answer-2382-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['641'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1058' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>40 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>40. \u0915\u094c\u0928-\u0938\u093e \u0906\u0909\u091f\u092a\u0941\u091f \u0921\u093f\u0935\u093e\u0907\u0938 \u0928\u0939\u0940\u0902 \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1058]' id='ays-answer-4036-46' value='4036'\/>\n\n                <label for='ays-answer-4036-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092a\u094d\u0930\u093f\u0928\u094d\u091f\u0930<\/label><label for='ays-answer-4036-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1058]' id='ays-answer-4037-46' value='4037'\/>\n\n                <label for='ays-answer-4037-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092e\u0949\u0928\u093f\u091f\u0930<\/label><label for='ays-answer-4037-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1058]' id='ays-answer-4038-46' value='4038'\/>\n\n                <label for='ays-answer-4038-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u092a\u094d\u0932\u0949\u091f\u0930<\/label><label for='ays-answer-4038-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1058]' id='ays-answer-4039-46' value='4039'\/>\n\n                <label for='ays-answer-4039-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u091f\u091a\u0938\u094d\u0915\u094d\u0930\u0940\u0928<\/label><label for='ays-answer-4039-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1058'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='764' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>41 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>41. Notepad \u0915\u093f\u0938 \u0911\u092a\u0930\u0947\u091f\u093f\u0902\u0917 \u0938\u093f\u0938\u094d\u091f\u092e \u0915\u0947 \u0938\u093e\u0925 \u0906\u0924\u093e \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-764]' id='ays-answer-2872-46' value='2872'\/>\n\n                <label for='ays-answer-2872-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Linux<\/label><label for='ays-answer-2872-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-764]' id='ays-answer-2873-46' value='2873'\/>\n\n                <label for='ays-answer-2873-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Windows<\/label><label for='ays-answer-2873-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-764]' id='ays-answer-2874-46' value='2874'\/>\n\n                <label for='ays-answer-2874-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. MacOS<\/label><label for='ays-answer-2874-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-764]' id='ays-answer-2875-46' value='2875'\/>\n\n                <label for='ays-answer-2875-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Android<\/label><label for='ays-answer-2875-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['764'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='25' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>42 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>42. <span style=\"font-weight: 400\">Shift F3 \u0938\u0947 \u0915\u094d\u092f\u093e \u0939\u094b\u0924\u093e \u0939\u0948\u0902?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-25]' id='ays-answer-94-46' value='94'\/>\n\n                <label for='ays-answer-94-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Font Style<\/label><label for='ays-answer-94-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-25]' id='ays-answer-95-46' value='95'\/>\n\n                <label for='ays-answer-95-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Spacing<\/label><label for='ays-answer-95-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-25]' id='ays-answer-96-46' value='96'\/>\n\n                <label for='ays-answer-96-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Change Case<\/label><label for='ays-answer-96-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-25]' id='ays-answer-97-46' value='97'\/>\n\n                <label for='ays-answer-97-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Fill Color<\/label><label for='ays-answer-97-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['25'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='39' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>43 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>43. <span style=\"font-weight: 400\">\u0906\u0915\u0943\u0924\u093f\u092f\u094b\u0902 \u0915\u094b \u0930\u0902\u0917 \u0926\u0947\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0938 \u0909\u092a\u0915\u0930\u0923 \u0915\u093e \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-39]' id='ays-answer-150-46' value='150'\/>\n\n                <label for='ays-answer-150-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Fill Color<\/label><label for='ays-answer-150-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-39]' id='ays-answer-151-46' value='151'\/>\n\n                <label for='ays-answer-151-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Spray Paint<\/label><label for='ays-answer-151-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-39]' id='ays-answer-152-46' value='152'\/>\n\n                <label for='ays-answer-152-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Eraser<\/label><label for='ays-answer-152-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-39]' id='ays-answer-153-46' value='153'\/>\n\n                <label for='ays-answer-153-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Text<\/label><label for='ays-answer-153-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['39'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1052' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>44 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>44. \u092a\u094d\u0930\u093f\u0902\u091f\u0930 \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u093f\u0938\u0938\u0947 \u0938\u0902\u092c\u0927\u093f\u0924 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1052]' id='ays-answer-4012-46' value='4012'\/>\n\n                <label for='ays-answer-4012-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Input Device<\/label><label for='ays-answer-4012-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1052]' id='ays-answer-4013-46' value='4013'\/>\n\n                <label for='ays-answer-4013-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Pointing Device<\/label><label for='ays-answer-4013-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1052]' id='ays-answer-4014-46' value='4014'\/>\n\n                <label for='ays-answer-4014-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Storage Device<\/label><label for='ays-answer-4014-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1052]' id='ays-answer-4015-46' value='4015'\/>\n\n                <label for='ays-answer-4015-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Output Device<\/label><label for='ays-answer-4015-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1052'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='619' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>45 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>45. <strong>\u0915\u0902\u092a\u094d\u092f\u0942\u091f\u0930 \u092e\u0947\u0902 \u091c\u093e\u0928\u0947 \u0935\u093e\u0932\u0947 \u0921\u0947\u091f\u093e \u0915\u094b \u0915\u094d\u092f\u093e \u0915\u0939\u0924\u0947 \u0939\u0948\u0902 ?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-619]' id='ays-answer-2291-46' value='2291'\/>\n\n                <label for='ays-answer-2291-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u090f\u0932\u094d\u0917\u094b\u0930\u093f\u0925\u094d\u092e<\/label><label for='ays-answer-2291-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-619]' id='ays-answer-2292-46' value='2292'\/>\n\n                <label for='ays-answer-2292-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0907\u0928\u092a\u0941\u091f<\/label><label for='ays-answer-2292-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-619]' id='ays-answer-2293-46' value='2293'\/>\n\n                <label for='ays-answer-2293-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0906\u0909\u091f\u092a\u0941\u091f<\/label><label for='ays-answer-2293-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-619]' id='ays-answer-2294-46' value='2294'\/>\n\n                <label for='ays-answer-2294-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0915\u0948\u0932\u0915\u094d\u092f\u0941\u0932\u0947\u0936\u0928\u094d\u0938<\/label><label for='ays-answer-2294-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['619'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1031' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>46 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>46. \u092b\u094b\u091f\u094b\u0936\u0949\u092a \u0915\u093e \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u093f\u0938 \u0915\u093e\u0930\u094d\u092f \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1031]' id='ays-answer-3928-46' value='3928'\/>\n\n                <label for='ays-answer-3928-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0917\u094d\u0930\u093e\u092b\u093f\u0915\u094d\u0938 \u0915\u0947 \u0932\u093f\u090f<\/label><label for='ays-answer-3928-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1031]' id='ays-answer-3929-46' value='3929'\/>\n\n                <label for='ays-answer-3929-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u090f\u0928\u0940\u092e\u0947\u0936\u0928 \u0915\u0947 \u0932\u093f\u090f<\/label><label for='ays-answer-3929-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1031]' id='ays-answer-3930-46' value='3930'\/>\n\n                <label for='ays-answer-3930-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u092a\u094d\u0930\u094b\u0917\u094d\u0930\u093e\u092e\u093f\u0902\u0917 \u0915\u0947 \u0932\u093f\u090f<\/label><label for='ays-answer-3930-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1031]' id='ays-answer-3931-46' value='3931'\/>\n\n                <label for='ays-answer-3931-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u091f\u093e\u0907\u092a\u093f\u0902\u0917 \u0915\u0947 \u0932\u093f\u090f<\/label><label for='ays-answer-3931-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1031'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1054' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>47 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>47. \u0907\u0928\u092e\u0947 \u0938\u0947 \u0915\u094c\u0928 \u0938\u093f\u0938\u094d\u091f\u092e \u0938\u0949\u092b\u094d\u091f\u0935\u0947\u0930 \u0928\u0939\u0940 \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1054]' id='ays-answer-4020-46' value='4020'\/>\n\n                <label for='ays-answer-4020-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Paint<\/label><label for='ays-answer-4020-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1054]' id='ays-answer-4021-46' value='4021'\/>\n\n                <label for='ays-answer-4021-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Word-pad<\/label><label for='ays-answer-4021-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1054]' id='ays-answer-4022-46' value='4022'\/>\n\n                <label for='ays-answer-4022-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Notepad<\/label><label for='ays-answer-4022-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1054]' id='ays-answer-4023-46' value='4023'\/>\n\n                <label for='ays-answer-4023-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. LibreOffice<\/label><label for='ays-answer-4023-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1054'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1021' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>48 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>48. What is the extension of Excel file?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1021]' id='ays-answer-3888-46' value='3888'\/>\n\n                <label for='ays-answer-3888-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. .xlsx<\/label><label for='ays-answer-3888-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1021]' id='ays-answer-3889-46' value='3889'\/>\n\n                <label for='ays-answer-3889-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. .jpg<\/label><label for='ays-answer-3889-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1021]' id='ays-answer-3890-46' value='3890'\/>\n\n                <label for='ays-answer-3890-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. .txt<\/label><label for='ays-answer-3890-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1021]' id='ays-answer-3891-46' value='3891'\/>\n\n                <label for='ays-answer-3891-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. None<\/label><label for='ays-answer-3891-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1021'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1043' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>49 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>49. <strong>\u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0928\u094b\u091f\u092a\u0948\u0921 \u0915\u093e extension \u0915\u094d\u092f\u093e \u0939\u0948?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1043]' id='ays-answer-3976-46' value='3976'\/>\n\n                <label for='ays-answer-3976-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. .txt<\/label><label for='ays-answer-3976-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1043]' id='ays-answer-3977-46' value='3977'\/>\n\n                <label for='ays-answer-3977-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. .xls<\/label><label for='ays-answer-3977-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1043]' id='ays-answer-3978-46' value='3978'\/>\n\n                <label for='ays-answer-3978-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. .ppt<\/label><label for='ays-answer-3978-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1043]' id='ays-answer-3979-46' value='3979'\/>\n\n                <label for='ays-answer-3979-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. .bmp<\/label><label for='ays-answer-3979-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1043'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='772' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>50 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>50. wordpad \u092e\u0947\u0902 \u0939\u092e \u0905\u0927\u093f\u0915\u0924\u092e \u0915\u093f\u0924\u0928\u093e zoom \u0915\u0930 \u0938\u0915\u0924\u0947 \u0939\u0948<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-772]' id='ays-answer-2904-46' value='2904'\/>\n\n                <label for='ays-answer-2904-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 400 %<\/label><label for='ays-answer-2904-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-772]' id='ays-answer-2905-46' value='2905'\/>\n\n                <label for='ays-answer-2905-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 500 %<\/label><label for='ays-answer-2905-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-772]' id='ays-answer-2906-46' value='2906'\/>\n\n                <label for='ays-answer-2906-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 200 %<\/label><label for='ays-answer-2906-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-772]' id='ays-answer-2907-46' value='2907'\/>\n\n                <label for='ays-answer-2907-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. all<\/label><label for='ays-answer-2907-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['772'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='640' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>51 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>51. Ctrl + D =\u00a0 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-640]' id='ays-answer-2375-46' value='2375'\/>\n\n                <label for='ays-answer-2375-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Increase Font Size<\/label><label for='ays-answer-2375-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-640]' id='ays-answer-2376-46' value='2376'\/>\n\n                <label for='ays-answer-2376-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Font Setting<\/label><label for='ays-answer-2376-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-640]' id='ays-answer-2377-46' value='2377'\/>\n\n                <label for='ays-answer-2377-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Superscript<\/label><label for='ays-answer-2377-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-640]' id='ays-answer-2378-46' value='2378'\/>\n\n                <label for='ays-answer-2378-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. None<\/label><label for='ays-answer-2378-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['640'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1057' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>52 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>52. \u090f\u0928\u093e\u0932\u093f\u091f\u093f\u0915 \u0907\u0902\u091c\u0928 \u0915\u093e \u0928\u093f\u0930\u094d\u092e\u093e\u0923 \u0915\u093f\u0938\u0928\u0947 \u0915\u093f\u092f\u093e \u0925\u093e?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1057]' id='ays-answer-4032-46' value='4032'\/>\n\n                <label for='ays-answer-4032-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u091c\u0940. \u090f\u0915\u0932<\/label><label for='ays-answer-4032-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1057]' id='ays-answer-4033-46' value='4033'\/>\n\n                <label for='ays-answer-4033-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u090f\u0935\u093e \u0932\u0935\u0932\u0947\u0938<\/label><label for='ays-answer-4033-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1057]' id='ays-answer-4034-46' value='4034'\/>\n\n                <label for='ays-answer-4034-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u091a\u093e\u0930\u094d\u0932\u094d\u0938 \u092c\u0948\u092c\u0947\u091c<\/label><label for='ays-answer-4034-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1057]' id='ays-answer-4035-46' value='4035'\/>\n\n                <label for='ays-answer-4035-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0938\u0940\u092e\u0947\u0928 \u0915\u094b\u0930\u094d\u0938\u0915\u094b\u092c<\/label><label for='ays-answer-4035-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1057'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='627' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>53 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>53. Ms. Word \u092e\u0947\u0902 Selection Pane Option \u0909\u092a\u092f\u094b\u0917 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-627]' id='ays-answer-2323-46' value='2323'\/>\n\n                <label for='ays-answer-2323-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Text \u092a\u0930<\/label><label for='ays-answer-2323-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-627]' id='ays-answer-2324-46' value='2324'\/>\n\n                <label for='ays-answer-2324-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Object \u092a\u0930<\/label><label for='ays-answer-2324-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-627]' id='ays-answer-2325-46' value='2325'\/>\n\n                <label for='ays-answer-2325-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Text Formatting \u0915\u0947 \u0932\u093f\u090f<\/label><label for='ays-answer-2325-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-627]' id='ays-answer-2326-46' value='2326'\/>\n\n                <label for='ays-answer-2326-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-2326-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['627'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='11' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>54 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>54. <span style=\"font-weight: 400\">MS word <\/span><span style=\"font-weight: 400\">\u092e\u0947\u0902 <\/span><span style=\"font-weight: 400\">Aa<\/span><span style=\"font-weight: 400\"> tool<\/span><span style=\"font-weight: 400\"> \u0915\u093f\u0938 \u0932\u093f\u090f \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-11]' id='ays-answer-38-46' value='38'\/>\n\n                <label for='ays-answer-38-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. style change<\/label><label for='ays-answer-38-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-11]' id='ays-answer-39-46' value='39'\/>\n\n                <label for='ays-answer-39-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. colour<\/label><label for='ays-answer-39-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-11]' id='ays-answer-40-46' value='40'\/>\n\n                <label for='ays-answer-40-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. change case<\/label><label for='ays-answer-40-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-11]' id='ays-answer-41-46' value='41'\/>\n\n                <label for='ays-answer-41-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. down<\/label><label for='ays-answer-41-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['11'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='37' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>55 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>55. <span style=\"font-weight: 400\">MS Word \u092e\u0947\u0902 minimum \u0914\u0930 maximum \u0915\u093f\u0924\u0928\u093e zoom \u0915\u0930 \u0938\u0915\u0924\u0947 \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-37]' id='ays-answer-142-46' value='142'\/>\n\n                <label for='ays-answer-142-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 10-100<\/label><label for='ays-answer-142-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-37]' id='ays-answer-143-46' value='143'\/>\n\n                <label for='ays-answer-143-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 10-500<\/label><label for='ays-answer-143-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-37]' id='ays-answer-144-46' value='144'\/>\n\n                <label for='ays-answer-144-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 12.50-800<\/label><label for='ays-answer-144-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-37]' id='ays-answer-145-46' value='145'\/>\n\n                <label for='ays-answer-145-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. All<\/label><label for='ays-answer-145-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['37'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='686' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>56 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>56. \u0907\u0902\u091f\u0930\u0928\u0947\u091f \u0915\u093e \u0909\u092a\u092f\u094b\u0917 \u0938\u0930\u094d\u0935\u092a\u094d\u0930\u0925\u092e \u0915\u092c \u0939\u0941\u0906 \u0925\u093e?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-686]' id='ays-answer-2559-46' value='2559'\/>\n\n                <label for='ays-answer-2559-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1969<\/label><label for='ays-answer-2559-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-686]' id='ays-answer-2560-46' value='2560'\/>\n\n                <label for='ays-answer-2560-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1970<\/label><label for='ays-answer-2560-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-686]' id='ays-answer-2561-46' value='2561'\/>\n\n                <label for='ays-answer-2561-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 1981<\/label><label for='ays-answer-2561-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-686]' id='ays-answer-2562-46' value='2562'\/>\n\n                <label for='ays-answer-2562-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 1989<\/label><label for='ays-answer-2562-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['686'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='27' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>57 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>57. <span style=\"font-weight: 400\">Borders \u0915\u093f\u0938\u00a0 Group \u092e\u0947\u0902 \u092e\u093f\u0932\u0924\u093e \u0939\u0948\u0902 ?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-27]' id='ays-answer-102-46' value='102'\/>\n\n                <label for='ays-answer-102-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Home<\/label><label for='ays-answer-102-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-27]' id='ays-answer-103-46' value='103'\/>\n\n                <label for='ays-answer-103-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Insert<\/label><label for='ays-answer-103-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-27]' id='ays-answer-104-46' value='104'\/>\n\n                <label for='ays-answer-104-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Paragraph<\/label><label for='ays-answer-104-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-27]' id='ays-answer-105-46' value='105'\/>\n\n                <label for='ays-answer-105-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Font<\/label><label for='ays-answer-105-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['27'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='653' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>58 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>58. Page Formatting \u0915\u094d\u092f\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-653]' id='ays-answer-2427-46' value='2427'\/>\n\n                <label for='ays-answer-2427-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Page \u092e\u0947\u0902 Color \u0926\u0947\u0928\u093e<\/label><label for='ays-answer-2427-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-653]' id='ays-answer-2428-46' value='2428'\/>\n\n                <label for='ays-answer-2428-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Page \u0915\u0940 Margin \u0915\u094b Set \u0915\u0930\u0928\u093e<\/label><label for='ays-answer-2428-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-653]' id='ays-answer-2429-46' value='2429'\/>\n\n                <label for='ays-answer-2429-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Page \u092e\u0947\u0902 Header \u0914\u0930 Footer \u0926\u0947\u0928\u093e<\/label><label for='ays-answer-2429-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-653]' id='ays-answer-2430-46' value='2430'\/>\n\n                <label for='ays-answer-2430-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0909\u092a\u0930\u094b\u0915\u094d\u0924 \u0938\u092d\u0940<\/label><label for='ays-answer-2430-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['653'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='24' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>59 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>59. <span style=\"font-weight: 400\">\u00a0<\/span><span style=\"font-weight: 400\">excel<\/span><span style=\"font-weight: 400\"> \u0915\u093f\u0938\u0915\u093e \u0938\u092e\u0942\u0939 \u0939\u094b\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-24]' id='ays-answer-90-46' value='90'\/>\n\n                <label for='ays-answer-90-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. box<\/label><label for='ays-answer-90-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-24]' id='ays-answer-91-46' value='91'\/>\n\n                <label for='ays-answer-91-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. text<\/label><label for='ays-answer-91-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-24]' id='ays-answer-92-46' value='92'\/>\n\n                <label for='ays-answer-92-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. cell<\/label><label for='ays-answer-92-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-24]' id='ays-answer-93-46' value='93'\/>\n\n                <label for='ays-answer-93-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. formula<\/label><label for='ays-answer-93-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['24'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='631' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>60 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>60. Ms. Word \u0915\u0947 \u092e\u0947\u0928\u0942\u092c\u093e\u0930 \u092e\u0947\u0902 \u0907\u0928\u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928\u0938\u093e Tab \u0928\u0939\u0940\u0902 \u0939\u094b\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-631]' id='ays-answer-2339-46' value='2339'\/>\n\n                <label for='ays-answer-2339-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Insert<\/label><label for='ays-answer-2339-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-631]' id='ays-answer-2340-46' value='2340'\/>\n\n                <label for='ays-answer-2340-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Page Layout<\/label><label for='ays-answer-2340-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-631]' id='ays-answer-2341-46' value='2341'\/>\n\n                <label for='ays-answer-2341-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Animation<\/label><label for='ays-answer-2341-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-631]' id='ays-answer-2342-46' value='2342'\/>\n\n                <label for='ays-answer-2342-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. View<\/label><label for='ays-answer-2342-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['631'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='9' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>61 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>61. <span style=\"font-weight: 400\">Font Dialog box <\/span><span style=\"font-weight: 400\">\u0916\u094b\u0932\u0928\u0947 \u0915\u093e <\/span><span style=\"font-weight: 400\">shortcut<\/span> <span style=\"font-weight: 400\">key<\/span><span style=\"font-weight: 400\"> \u0915\u094d\u092f\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-9]' id='ays-answer-30-46' value='30'\/>\n\n                <label for='ays-answer-30-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Ctrl + F<\/label><label for='ays-answer-30-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-9]' id='ays-answer-31-46' value='31'\/>\n\n                <label for='ays-answer-31-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Ctrl + D<\/label><label for='ays-answer-31-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-9]' id='ays-answer-32-46' value='32'\/>\n\n                <label for='ays-answer-32-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Ctrl + B<\/label><label for='ays-answer-32-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-9]' id='ays-answer-33-46' value='33'\/>\n\n                <label for='ays-answer-33-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Ctrl + M<\/label><label for='ays-answer-33-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['9'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='699' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>62 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>62. \u0905\u0917\u0930 Excel \u0915\u0947 Select Range \u092a\u0930 All Border Apply \u0915\u0930\u0928\u093e \u0939\u094b \u0924\u094b \u0939\u092e Alt \u0915\u0947 \u0938\u093e\u0925 \u0915\u094c\u0928\u0938\u093e Key Press \u0915\u0930\u0924\u0947 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-699]' id='ays-answer-2611-46' value='2611'\/>\n\n                <label for='ays-answer-2611-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Alt,H,A,B<\/label><label for='ays-answer-2611-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-699]' id='ays-answer-2612-46' value='2612'\/>\n\n                <label for='ays-answer-2612-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Alt,A,H,A<\/label><label for='ays-answer-2612-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-699]' id='ays-answer-2613-46' value='2613'\/>\n\n                <label for='ays-answer-2613-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Alt,H,B,A<\/label><label for='ays-answer-2613-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-699]' id='ays-answer-2614-46' value='2614'\/>\n\n                <label for='ays-answer-2614-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Alt,H,A,Border<\/label><label for='ays-answer-2614-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['699'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1044' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>63 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>63. <strong>\u092b\u093e\u0907\u0932 \u0915\u094b delete \u0915\u0930\u0928\u0947 \u0915\u0947 \u092c\u093e\u0926 \u0935\u0939 \u0915\u0939\u093e\u0901 \u0938\u094d\u091f\u094b\u0930 \u0939\u094b\u0924\u0940 \u0939\u0948?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1044]' id='ays-answer-3980-46' value='3980'\/>\n\n                <label for='ays-answer-3980-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u091f\u093e\u0938\u094d\u0915 \u092c\u093e\u0930 \u092e\u0947\u0902<\/label><label for='ays-answer-3980-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1044]' id='ays-answer-3981-46' value='3981'\/>\n\n                <label for='ays-answer-3981-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0915\u0939\u0940 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-3981-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1044]' id='ays-answer-3982-46' value='3982'\/>\n\n                <label for='ays-answer-3982-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0939\u093e\u0930\u094d\u0921 \u0921\u093f\u0938\u094d\u0915 \u092e\u0947\u0902<\/label><label for='ays-answer-3982-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1044]' id='ays-answer-3983-46' value='3983'\/>\n\n                <label for='ays-answer-3983-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. recycle bin \u092e\u0947\u0902<\/label><label for='ays-answer-3983-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1044'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='680' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>64 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>64. MS Word \u092e\u0947\u0902 Document Formatting Group \u00a0\u0915\u093f\u0938 Tab \u092e\u0947 \u092e\u093f\u0932\u0924\u093e \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-680]' id='ays-answer-2535-46' value='2535'\/>\n\n                <label for='ays-answer-2535-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Insert<\/label><label for='ays-answer-2535-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-680]' id='ays-answer-2536-46' value='2536'\/>\n\n                <label for='ays-answer-2536-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Design<\/label><label for='ays-answer-2536-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-680]' id='ays-answer-2537-46' value='2537'\/>\n\n                <label for='ays-answer-2537-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Layout<\/label><label for='ays-answer-2537-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-680]' id='ays-answer-2538-46' value='2538'\/>\n\n                <label for='ays-answer-2538-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-2538-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['680'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='682' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>65 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>65. Line and Pragrapgh Specing \u00a0\u092e\u0947 \u00a01.5 \u0915\u0947 \u0932\u093f\u090f Shortcut Keys|<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-682]' id='ays-answer-2543-46' value='2543'\/>\n\n                <label for='ays-answer-2543-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. CTRL + 1<\/label><label for='ays-answer-2543-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-682]' id='ays-answer-2544-46' value='2544'\/>\n\n                <label for='ays-answer-2544-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. CTRL + 2<\/label><label for='ays-answer-2544-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-682]' id='ays-answer-2545-46' value='2545'\/>\n\n                <label for='ays-answer-2545-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. CTRL + 5<\/label><label for='ays-answer-2545-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-682]' id='ays-answer-2546-46' value='2546'\/>\n\n                <label for='ays-answer-2546-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. CTRL + 1.5<\/label><label for='ays-answer-2546-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['682'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='29' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>66 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>66. <span style=\"font-weight: 400\">MS Word \u092e\u0947\u0902\u00a0 Change Case \u0915\u093f\u0924\u0928\u0947\u00a0 \u092a\u094d\u0930\u0915\u093e\u0930 \u0915\u0947 \u0939\u094b\u0924\u0947 \u0939\u0948\u0902?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-29]' id='ays-answer-110-46' value='110'\/>\n\n                <label for='ays-answer-110-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 6<\/label><label for='ays-answer-110-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-29]' id='ays-answer-111-46' value='111'\/>\n\n                <label for='ays-answer-111-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 4<\/label><label for='ays-answer-111-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-29]' id='ays-answer-112-46' value='112'\/>\n\n                <label for='ays-answer-112-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 8<\/label><label for='ays-answer-112-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-29]' id='ays-answer-113-46' value='113'\/>\n\n                <label for='ays-answer-113-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 5<\/label><label for='ays-answer-113-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['29'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='644' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>67 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>67. \u0915\u0902\u092a\u094d\u092f\u0942\u091f\u0930 \u0915\u093e \u0939\u093f\u0928\u094d\u0926\u0940 \u0928\u093e\u092e \u0915\u094d\u092f\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-644]' id='ays-answer-2391-46' value='2391'\/>\n\n                <label for='ays-answer-2391-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0917\u0923\u0928\u093e \u0915\u0930\u0928\u0947\u0935\u093e\u0932\u093e<\/label><label for='ays-answer-2391-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-644]' id='ays-answer-2392-46' value='2392'\/>\n\n                <label for='ays-answer-2392-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u0902\u0917\u0923\u0915<\/label><label for='ays-answer-2392-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-644]' id='ays-answer-2393-46' value='2393'\/>\n\n                <label for='ays-answer-2393-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0939\u093f\u0938\u093e\u092c \u0932\u0917\u093e\u0928\u0947\u0935\u093e\u0932\u093e<\/label><label for='ays-answer-2393-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-644]' id='ays-answer-2394-46' value='2394'\/>\n\n                <label for='ays-answer-2394-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092a\u0930\u093f\u0917\u0923\u0915<\/label><label for='ays-answer-2394-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['644'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='19' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>68 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>68. <span style=\"font-weight: 400\">hyperlink<\/span><span style=\"font-weight: 400\"> \u092f\u093e <\/span><span style=\"font-weight: 400\">link<\/span><span style=\"font-weight: 400\"> \u0915\u093e <\/span><span style=\"font-weight: 400\">shortcut<\/span> <span style=\"font-weight: 400\">key<\/span><span style=\"font-weight: 400\"> \u0915\u094d\u092f\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-19]' id='ays-answer-70-46' value='70'\/>\n\n                <label for='ays-answer-70-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Ctrl + G<\/label><label for='ays-answer-70-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-19]' id='ays-answer-71-46' value='71'\/>\n\n                <label for='ays-answer-71-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Ctrl + K<\/label><label for='ays-answer-71-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-19]' id='ays-answer-72-46' value='72'\/>\n\n                <label for='ays-answer-72-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Ctrl + H<\/label><label for='ays-answer-72-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-19]' id='ays-answer-73-46' value='73'\/>\n\n                <label for='ays-answer-73-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Ctrl + J<\/label><label for='ays-answer-73-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['19'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='26' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>69 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>69. <span style=\"font-weight: 400\">Margins \u0915\u093f\u0938\u00a0 Group \u092e\u0947\u0902 \u092e\u093f\u0932\u0924\u093e \u0939\u0948\u0902 ?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-26]' id='ays-answer-98-46' value='98'\/>\n\n                <label for='ays-answer-98-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Design<\/label><label for='ays-answer-98-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-26]' id='ays-answer-99-46' value='99'\/>\n\n                <label for='ays-answer-99-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Layout<\/label><label for='ays-answer-99-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-26]' id='ays-answer-100-46' value='100'\/>\n\n                <label for='ays-answer-100-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Page Setup<\/label><label for='ays-answer-100-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-26]' id='ays-answer-101-46' value='101'\/>\n\n                <label for='ays-answer-101-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. insert<\/label><label for='ays-answer-101-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['26'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='15' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>70 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>70. <span style=\"font-weight: 400\">Format painter MS Word\u00a0 <\/span><span style=\"font-weight: 400\">\u092e\u0947\u0902\u00a0 \u0915\u093f\u0938\u00a0 <\/span><span style=\"font-weight: 400\">Group<\/span><span style=\"font-weight: 400\"> \u092e\u0947\u0902 \u0939\u094b\u0924\u093e \u0939\u0948 ?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-15]' id='ays-answer-54-46' value='54'\/>\n\n                <label for='ays-answer-54-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Font<\/label><label for='ays-answer-54-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-15]' id='ays-answer-55-46' value='55'\/>\n\n                <label for='ays-answer-55-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Editing<\/label><label for='ays-answer-55-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-15]' id='ays-answer-56-46' value='56'\/>\n\n                <label for='ays-answer-56-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Clipboard<\/label><label for='ays-answer-56-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-15]' id='ays-answer-57-46' value='57'\/>\n\n                <label for='ays-answer-57-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Home<\/label><label for='ays-answer-57-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['15'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='628' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>71 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>71. Ms. Word \u092e\u0947\u0902 Spelling &amp; Grammar Check \u0915\u0930\u0928\u0947 \u0915\u0940 Shortcut Keys \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-628]' id='ays-answer-2327-46' value='2327'\/>\n\n                <label for='ays-answer-2327-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. F2<\/label><label for='ays-answer-2327-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-628]' id='ays-answer-2328-46' value='2328'\/>\n\n                <label for='ays-answer-2328-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. F7<\/label><label for='ays-answer-2328-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-628]' id='ays-answer-2329-46' value='2329'\/>\n\n                <label for='ays-answer-2329-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. F10<\/label><label for='ays-answer-2329-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-628]' id='ays-answer-2330-46' value='2330'\/>\n\n                <label for='ays-answer-2330-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. F9<\/label><label for='ays-answer-2330-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['628'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='765' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>72 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>72. Notepad \u092e\u0947\u0902 \u091f\u0947\u0915\u094d\u0938\u094d\u091f \u0915\u094b \u0915\u091f\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u094c\u0928-\u0938\u093e \u0936\u0949\u0930\u094d\u091f\u0915\u091f \u0939\u094b\u0924\u093e \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-765]' id='ays-answer-2876-46' value='2876'\/>\n\n                <label for='ays-answer-2876-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Ctrl + X<\/label><label for='ays-answer-2876-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-765]' id='ays-answer-2877-46' value='2877'\/>\n\n                <label for='ays-answer-2877-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Ctrl + C<\/label><label for='ays-answer-2877-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-765]' id='ays-answer-2878-46' value='2878'\/>\n\n                <label for='ays-answer-2878-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Ctrl + V<\/label><label for='ays-answer-2878-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-765]' id='ays-answer-2879-46' value='2879'\/>\n\n                <label for='ays-answer-2879-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Ctrl + S<\/label><label for='ays-answer-2879-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['765'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='647' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>73 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>73. \u090f\u0915 \u0915\u094d\u0930\u0947\u0921\u093f\u091f \u0928\u094b\u091f _______ \u0926\u094d\u0935\u093e\u0930\u093e _______ \u0915\u094b \u092d\u0947\u091c\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-647]' id='ays-answer-2403-46' value='2403'\/>\n\n                <label for='ays-answer-2403-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0935\u093f\u0915\u094d\u0930\u0947\u0924\u093e, \u0915\u094d\u0930\u0947\u0924\u093e<\/label><label for='ays-answer-2403-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-647]' id='ays-answer-2404-46' value='2404'\/>\n\n                <label for='ays-answer-2404-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0915\u094d\u0930\u0947\u0924\u093e, \u0935\u093f\u0915\u094d\u0930\u0947\u0924\u093e<\/label><label for='ays-answer-2404-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-647]' id='ays-answer-2405-46' value='2405'\/>\n\n                <label for='ays-answer-2405-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0917\u094d\u0930\u093e\u0939\u0915, \u0935\u093f\u0915\u094d\u0930\u0947\u0924\u093e<\/label><label for='ays-answer-2405-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-647]' id='ays-answer-2406-46' value='2406'\/>\n\n                <label for='ays-answer-2406-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0932\u0947\u0928\u0926\u093e\u0930, \u0935\u093f\u0915\u094d\u0930\u0947\u0924\u093e<\/label><label for='ays-answer-2406-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['647'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='637' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>74 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>74. MS.Word \u092e\u0947\u0902 \u0915\u093f\u0938\u0940 \u092d\u0940 Particular Word \u0915\u094b \u0916\u094b\u091c\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0907\u0938\u094d\u0924\u0947\u092e\u093e\u0932 \u0915\u093f\u092f\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-637]' id='ays-answer-2363-46' value='2363'\/>\n\n                <label for='ays-answer-2363-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Find<\/label><label for='ays-answer-2363-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-637]' id='ays-answer-2364-46' value='2364'\/>\n\n                <label for='ays-answer-2364-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Replace<\/label><label for='ays-answer-2364-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-637]' id='ays-answer-2365-46' value='2365'\/>\n\n                <label for='ays-answer-2365-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Go to<\/label><label for='ays-answer-2365-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-637]' id='ays-answer-2366-46' value='2366'\/>\n\n                <label for='ays-answer-2366-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Left Indent<\/label><label for='ays-answer-2366-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['637'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='681' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>75 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>75. Themes \u0915\u093f\u0938 Group \u092e\u0947 \u092e\u093f\u0932\u0924\u093e \u0939\u0948\u0902 |<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-681]' id='ays-answer-2539-46' value='2539'\/>\n\n                <label for='ays-answer-2539-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Page Backgraund<\/label><label for='ays-answer-2539-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-681]' id='ays-answer-2540-46' value='2540'\/>\n\n                <label for='ays-answer-2540-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Pragrapgh<\/label><label for='ays-answer-2540-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-681]' id='ays-answer-2541-46' value='2541'\/>\n\n                <label for='ays-answer-2541-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Editing<\/label><label for='ays-answer-2541-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-681]' id='ays-answer-2542-46' value='2542'\/>\n\n                <label for='ays-answer-2542-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-2542-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['681'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='17' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>76 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>76. <span style=\"font-weight: 400\">\u0915\u093f\u0938 <\/span><span style=\"font-weight: 400\">shortcut<\/span> <span style=\"font-weight: 400\">key<\/span><span style=\"font-weight: 400\"> \u0938\u0947 <\/span><span style=\"font-weight: 400\">font<\/span> <span style=\"font-weight: 400\">size<\/span><span style=\"font-weight: 400\"> \u092c\u095d\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-17]' id='ays-answer-62-46' value='62'\/>\n\n                <label for='ays-answer-62-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. ctrl+]<\/label><label for='ays-answer-62-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-17]' id='ays-answer-63-46' value='63'\/>\n\n                <label for='ays-answer-63-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. ctrl+[<\/label><label for='ays-answer-63-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-17]' id='ays-answer-64-46' value='64'\/>\n\n                <label for='ays-answer-64-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. ctrl+(<\/label><label for='ays-answer-64-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-17]' id='ays-answer-65-46' value='65'\/>\n\n                <label for='ays-answer-65-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. ctrl+}<\/label><label for='ays-answer-65-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['17'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='646' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>77 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>77. MS Word \u0915\u093f\u0938\u0915\u093e \u0909\u0926\u093e\u0939\u0930\u0923 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-646]' id='ays-answer-2399-46' value='2399'\/>\n\n                <label for='ays-answer-2399-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0911\u092a\u0930\u0947\u091f\u093f\u0902\u0917 \u0938\u093f\u0938\u094d\u091f\u092e<\/label><label for='ays-answer-2399-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-646]' id='ays-answer-2400-46' value='2400'\/>\n\n                <label for='ays-answer-2400-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092a\u094d\u0930\u094b\u0938\u0947\u0938\u093f\u0902\u0917 \u0921\u093f\u0935\u093e\u0907\u0938<\/label><label for='ays-answer-2400-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-646]' id='ays-answer-2401-46' value='2401'\/>\n\n                <label for='ays-answer-2401-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u090f\u092a\u094d\u0932\u0940\u0915\u0947\u0936\u0928 \u0938\u0949\u092b\u094d\u091f\u0935\u0947\u092f\u0930<\/label><label for='ays-answer-2401-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-646]' id='ays-answer-2402-46' value='2402'\/>\n\n                <label for='ays-answer-2402-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092a\u0941\u091f \u0921\u093f\u0935\u093e\u0907\u0938<\/label><label for='ays-answer-2402-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['646'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='14' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>78 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>78. MS <span style=\"font-weight: 400\">word<\/span><span style=\"font-weight: 400\"> \u092e\u0947\u0902 <\/span><span style=\"font-weight: 400\">default<\/span> <span style=\"font-weight: 400\">zoom<\/span><span style=\"font-weight: 400\"> \u0915\u093f\u0924\u0928\u093e <\/span><span style=\"font-weight: 400\">percent<\/span><span style=\"font-weight: 400\">(%) \u0939\u094b\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-14]' id='ays-answer-50-46' value='50'\/>\n\n                <label for='ays-answer-50-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 200%<\/label><label for='ays-answer-50-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-14]' id='ays-answer-51-46' value='51'\/>\n\n                <label for='ays-answer-51-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 120%<\/label><label for='ays-answer-51-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-14]' id='ays-answer-52-46' value='52'\/>\n\n                <label for='ays-answer-52-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 100%<\/label><label for='ays-answer-52-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-14]' id='ays-answer-53-46' value='53'\/>\n\n                <label for='ays-answer-53-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 150%<\/label><label for='ays-answer-53-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['14'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='612' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>79 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>79. <strong>CPU \u092e\u0947\u0902 \u0915\u0902\u091f\u094d\u0930\u094b\u0932, \u092e\u0947\u092e\u094b\u0930\u0940 \u0914\u0930 \u0924\u0940\u0938\u0930\u093e \u0915\u094c\u0928 \u0938\u093e \u092f\u0942\u0928\u093f\u091f \u0939\u094b\u0924\u0947 \u0939\u0948\u0902 ?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-612]' id='ays-answer-2263-46' value='2263'\/>\n\n                <label for='ays-answer-2263-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092e\u093e\u0907\u0915\u094d\u0930\u094b<\/label><label for='ays-answer-2263-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-612]' id='ays-answer-2264-46' value='2264'\/>\n\n                <label for='ays-answer-2264-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092a\u094d\u0930\u094b\u0938\u0947\u0938\u0930<\/label><label for='ays-answer-2264-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-612]' id='ays-answer-2265-46' value='2265'\/>\n\n                <label for='ays-answer-2265-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0906\u0909\u091f\u092a\u0941\u091f<\/label><label for='ays-answer-2265-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-612]' id='ays-answer-2266-46' value='2266'\/>\n\n                <label for='ays-answer-2266-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0905\u0930\u094d\u0925\u092e\u0948\u091f\u093f\u0915\/\u0932\u0949\u091c\u093f\u0915<\/label><label for='ays-answer-2266-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['612'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='38' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>80 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>80. <span style=\"font-weight: 400\">MS Word \u092e\u0947\u0902 \u0915\u093f\u0938 \u0915\u093f\u0938 Paper Size \u0915\u093e \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u093f\u092f\u093e \u091c\u093e \u0938\u0915\u0924\u093e \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-38]' id='ays-answer-146-46' value='146'\/>\n\n                <label for='ays-answer-146-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Letter<\/label><label for='ays-answer-146-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-38]' id='ays-answer-147-46' value='147'\/>\n\n                <label for='ays-answer-147-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. A4<\/label><label for='ays-answer-147-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-38]' id='ays-answer-148-46' value='148'\/>\n\n                <label for='ays-answer-148-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Legal<\/label><label for='ays-answer-148-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-38]' id='ays-answer-149-46' value='149'\/>\n\n                <label for='ays-answer-149-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. All<\/label><label for='ays-answer-149-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['38'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='689' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>81 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>81. WWW \u0915\u093e \u0906\u0935\u093f\u0937\u094d\u0915\u093e\u0930 \u0915\u093f\u0938\u0928\u0947 \u0915\u093f\u092f\u093e \u0925\u093e?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-689]' id='ays-answer-2571-46' value='2571'\/>\n\n                <label for='ays-answer-2571-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u091f\u093f\u092e \u092c\u0948\u0930\u0928\u0930\u094d\u0938 \u2013 \u0932\u0940 (Tim Berners-Lee)<\/label><label for='ays-answer-2571-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-689]' id='ays-answer-2572-46' value='2572'\/>\n\n                <label for='ays-answer-2572-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0935\u093f\u0902\u091f \u0938\u0930\u094d\u092b\u093c (Vint Cerf)<\/label><label for='ays-answer-2572-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-689]' id='ays-answer-2573-46' value='2573'\/>\n\n                <label for='ays-answer-2573-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u090f\u0932\u0928 \u091f\u094d\u092f\u0942\u0930\u093f\u0902\u0917 (Alan Turing)<\/label><label for='ays-answer-2573-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-689]' id='ays-answer-2574-46' value='2574'\/>\n\n                <label for='ays-answer-2574-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u091c\u0949\u0928 \u092e\u0948\u0915\u093e\u0930\u094d\u0925\u0940 (John McCarthy)<\/label><label for='ays-answer-2574-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['689'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1041' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>82 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>82. <strong>\u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0915\u094c\u0928 \u090f\u0915 \u0911\u092a\u0930\u0947\u091f\u093f\u0902\u0917 \u0938\u093f\u0938\u094d\u091f\u092e \u0928\u0939\u0940\u0902 \u0939\u0948?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1041]' id='ays-answer-3968-46' value='3968'\/>\n\n                <label for='ays-answer-3968-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0935\u093f\u0902\u0921\u094b\u091c<\/label><label for='ays-answer-3968-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1041]' id='ays-answer-3969-46' value='3969'\/>\n\n                <label for='ays-answer-3969-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Linux<\/label><label for='ays-answer-3969-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1041]' id='ays-answer-3970-46' value='3970'\/>\n\n                <label for='ays-answer-3970-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. oracle<\/label><label for='ays-answer-3970-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1041]' id='ays-answer-3971-46' value='3971'\/>\n\n                <label for='ays-answer-3971-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. DOS<\/label><label for='ays-answer-3971-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1041'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='28' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>83 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>83. <span style=\"font-weight: 400\">MS Word \u092e\u0947\u0902\u00a0 Alignment \u0915\u093f\u0924\u0928\u0947\u00a0 \u092a\u094d\u0930\u0915\u093e\u0930 \u0915\u0947 \u0939\u094b\u0924\u0947 \u0939\u0948\u0902?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-28]' id='ays-answer-106-46' value='106'\/>\n\n                <label for='ays-answer-106-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 4<\/label><label for='ays-answer-106-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-28]' id='ays-answer-107-46' value='107'\/>\n\n                <label for='ays-answer-107-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 5<\/label><label for='ays-answer-107-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-28]' id='ays-answer-108-46' value='108'\/>\n\n                <label for='ays-answer-108-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 3<\/label><label for='ays-answer-108-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-28]' id='ays-answer-109-46' value='109'\/>\n\n                <label for='ays-answer-109-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 6<\/label><label for='ays-answer-109-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['28'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='771' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>84 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>84. Justify \u0915\u093f\u0938 block \u0915\u0947 \u0905\u0902\u0924\u0930\u094d\u0917\u0924 \u0906\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-771]' id='ays-answer-2900-46' value='2900'\/>\n\n                <label for='ays-answer-2900-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. paragraph block<\/label><label for='ays-answer-2900-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-771]' id='ays-answer-2901-46' value='2901'\/>\n\n                <label for='ays-answer-2901-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u090f\u0921\u093f\u091f\u093f\u0902\u0917 block<\/label><label for='ays-answer-2901-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-771]' id='ays-answer-2902-46' value='2902'\/>\n\n                <label for='ays-answer-2902-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u091f\u0949\u092a block<\/label><label for='ays-answer-2902-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-771]' id='ays-answer-2903-46' value='2903'\/>\n\n                <label for='ays-answer-2903-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. none of the above<\/label><label for='ays-answer-2903-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['771'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1053' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>85 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>85. \u0928\u093f\u092e\u094d\u0928 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928\u0938\u093e System Software \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1053]' id='ays-answer-4016-46' value='4016'\/>\n\n                <label for='ays-answer-4016-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. MS Word<\/label><label for='ays-answer-4016-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1053]' id='ays-answer-4017-46' value='4017'\/>\n\n                <label for='ays-answer-4017-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Windows 7<\/label><label for='ays-answer-4017-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1053]' id='ays-answer-4018-46' value='4018'\/>\n\n                <label for='ays-answer-4018-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Excel<\/label><label for='ays-answer-4018-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1053]' id='ays-answer-4019-46' value='4019'\/>\n\n                <label for='ays-answer-4019-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Power Point<\/label><label for='ays-answer-4019-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1053'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='36' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>86 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>86. <span style=\"font-weight: 400\">MS Word \u092e\u0947\u0902 \u0938\u092c\u0938\u0947 \u0928\u093f\u091a\u0947 \u0915\u0940 \u0924\u0930\u092b \u0915\u094c\u0928 \u0938\u0940 Bar \u0939\u094b\u0924\u0940 \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-36]' id='ays-answer-138-46' value='138'\/>\n\n                <label for='ays-answer-138-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Title Bar<\/label><label for='ays-answer-138-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-36]' id='ays-answer-139-46' value='139'\/>\n\n                <label for='ays-answer-139-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Task Bar<\/label><label for='ays-answer-139-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-36]' id='ays-answer-140-46' value='140'\/>\n\n                <label for='ays-answer-140-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Scroll Bar<\/label><label for='ays-answer-140-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-36]' id='ays-answer-141-46' value='141'\/>\n\n                <label for='ays-answer-141-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. All<\/label><label for='ays-answer-141-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['36'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='41' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>87 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>87. <b>MS Paint \u0915\u093e \u0921\u093f\u095e\u0949\u0932\u094d\u091f \u092c\u0948\u0915\u0917\u094d\u0930\u093e\u0909\u0902\u0921 \u0930\u0902\u0917 \u0915\u094c\u0928\u0938\u093e \u0939\u0948 ?<\/b><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-41]' id='ays-answer-158-46' value='158'\/>\n\n                <label for='ays-answer-158-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Yellow<\/label><label for='ays-answer-158-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-41]' id='ays-answer-159-46' value='159'\/>\n\n                <label for='ays-answer-159-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Red<\/label><label for='ays-answer-159-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-41]' id='ays-answer-160-46' value='160'\/>\n\n                <label for='ays-answer-160-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. White<\/label><label for='ays-answer-160-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-41]' id='ays-answer-161-46' value='161'\/>\n\n                <label for='ays-answer-161-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Black<\/label><label for='ays-answer-161-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['41'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1030' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>88 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>88. \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928 \u0938\u093e \u0908-\u092e\u0947\u0932 \u0915\u093e \u092d\u093e\u0917 \u0939\u0948?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1030]' id='ays-answer-3924-46' value='3924'\/>\n\n                <label for='ays-answer-3924-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0909\u092a\u092f\u094b\u0917\u0915\u0930\u094d\u0924\u093e \u0928\u093e\u092e<\/label><label for='ays-answer-3924-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1030]' id='ays-answer-3925-46' value='3925'\/>\n\n                <label for='ays-answer-3925-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0921\u094b\u092e\u0947\u0928 \u0928\u093e\u092e<\/label><label for='ays-answer-3925-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1030]' id='ays-answer-3926-46' value='3926'\/>\n\n                <label for='ays-answer-3926-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. A \u0914\u0930 B \u0926\u094b\u0928\u094b\u0902<\/label><label for='ays-answer-3926-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1030]' id='ays-answer-3927-46' value='3927'\/>\n\n                <label for='ays-answer-3927-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0909\u092a\u0930\u094b\u0915\u094d\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-3927-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1030'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='614' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>89 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>89. <strong>\u092a\u094d\u0930\u094b\u0938\u0947\u0938\u0930 \u0915\u0947 \u0924\u0940\u0928 \u092e\u0941\u0916\u094d\u092f \u092d\u093e\u0917 \u0939\u0948 ?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-614]' id='ays-answer-2271-46' value='2271'\/>\n\n                <label for='ays-answer-2271-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. ALU, \u0915\u0902\u091f\u094d\u0930\u094b\u0932 \u092f\u0942\u0928\u093f\u091f \u0914\u0930 RAM<\/label><label for='ays-answer-2271-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-614]' id='ays-answer-2272-46' value='2272'\/>\n\n                <label for='ays-answer-2272-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. ALU, \u0915\u0902\u091f\u094d\u0930\u094b\u0932 \u092f\u0942\u0928\u093f\u091f \u0914\u0930 \u0930\u091c\u093f\u0938\u094d\u091f\u0930<\/label><label for='ays-answer-2272-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-614]' id='ays-answer-2273-46' value='2273'\/>\n\n                <label for='ays-answer-2273-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0915\u0948\u0936, \u0915\u0902\u091f\u094d\u0930\u094b\u0932 \u092f\u0942\u0928\u093f\u091f \u0914\u0930 \u0930\u091c\u093f\u0938\u094d\u091f\u0930<\/label><label for='ays-answer-2273-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-614]' id='ays-answer-2274-46' value='2274'\/>\n\n                <label for='ays-answer-2274-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947\u0902 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-2274-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['614'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='10' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>90 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>90. <span style=\"font-weight: 400\">H<\/span><span style=\"font-weight: 400\">2O<\/span><span style=\"font-weight: 400\">\u00a0<\/span><span style=\"font-weight: 400\">\u0932\u093f\u0916\u0924\u0947 \u0938\u092e\u092f 2 \u0915\u094b \u0915\u093f\u0938\u0938\u0947 \u0926\u0930\u094d\u0936\u093e\u0924\u0947 \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-10]' id='ays-answer-34-46' value='34'\/>\n\n                <label for='ays-answer-34-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Subscript<\/label><label for='ays-answer-34-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-10]' id='ays-answer-35-46' value='35'\/>\n\n                <label for='ays-answer-35-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Superscript<\/label><label for='ays-answer-35-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-10]' id='ays-answer-36-46' value='36'\/>\n\n                <label for='ays-answer-36-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Down<\/label><label for='ays-answer-36-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-10]' id='ays-answer-37-46' value='37'\/>\n\n                <label for='ays-answer-37-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Arrow<\/label><label for='ays-answer-37-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['10'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='13' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>91 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>91. <span style=\"font-weight: 400\">\u0928\u093f\u092e\u0902\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928 \u0938\u093e <\/span><span style=\"font-weight: 400\">save<\/span> <span style=\"font-weight: 400\">As<\/span><span style=\"font-weight: 400\"> \u0915\u093e <\/span><span style=\"font-weight: 400\">shortcut<\/span> <span style=\"font-weight: 400\">key<\/span><span style=\"font-weight: 400\"> \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-13]' id='ays-answer-46-46' value='46'\/>\n\n                <label for='ays-answer-46-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. ctrl + s<\/label><label for='ays-answer-46-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-13]' id='ays-answer-47-46' value='47'\/>\n\n                <label for='ays-answer-47-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. ctrl + F12<\/label><label for='ays-answer-47-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-13]' id='ays-answer-48-46' value='48'\/>\n\n                <label for='ays-answer-48-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. ctrl + O<\/label><label for='ays-answer-48-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-13]' id='ays-answer-49-46' value='49'\/>\n\n                <label for='ays-answer-49-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. F12<\/label><label for='ays-answer-49-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['13'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='688' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>92 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>92. \u092d\u093e\u0930\u0924 \u092e\u0947\u0902 \u091c\u0928\u0924\u093e \u0915\u0947 \u0932\u093f\u090f \u0907\u0902\u091f\u0930\u0928\u0947\u091f \u0915\u092c \u0909\u092a\u0932\u092c\u094d\u0927 \u0939\u0941\u0906\u00a0\u0925\u093e?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-688]' id='ays-answer-2567-46' value='2567'\/>\n\n                <label for='ays-answer-2567-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 26 \u091c\u0928\u0935\u0930\u0940 1990<\/label><label for='ays-answer-2567-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-688]' id='ays-answer-2568-46' value='2568'\/>\n\n                <label for='ays-answer-2568-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1 \u0905\u0915\u094d\u091f\u0942\u092c\u0930 1980<\/label><label for='ays-answer-2568-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-688]' id='ays-answer-2569-46' value='2569'\/>\n\n                <label for='ays-answer-2569-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 7 \u0905\u092a\u094d\u0930\u0948\u0932 1998<\/label><label for='ays-answer-2569-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-688]' id='ays-answer-2570-46' value='2570'\/>\n\n                <label for='ays-answer-2570-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 15 \u0905\u0917\u0938\u094d\u0924 1995<\/label><label for='ays-answer-2570-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['688'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='645' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>93 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>93. \u0928\u093f\u092e\u094d\u0928 \u092e\u0947\u0902 \u0915\u094c\u0928 \u0907\u0928\u092a\u0941\u091f \u0907\u0915\u093e\u0908 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-645]' id='ays-answer-2395-46' value='2395'\/>\n\n                <label for='ays-answer-2395-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092e\u093e\u090a\u0938<\/label><label for='ays-answer-2395-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-645]' id='ays-answer-2396-46' value='2396'\/>\n\n                <label for='ays-answer-2396-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0915\u0940-\u092c\u094b\u0930\u094d\u0921<\/label><label for='ays-answer-2396-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-645]' id='ays-answer-2397-46' value='2397'\/>\n\n                <label for='ays-answer-2397-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0938\u094d\u0915\u0948\u0928\u0930<\/label><label for='ays-answer-2397-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-645]' id='ays-answer-2398-46' value='2398'\/>\n\n                <label for='ays-answer-2398-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947\u0902 \u0938\u0947 \u0938\u092d\u0940<\/label><label for='ays-answer-2398-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['645'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1023' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>94 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>94. \u092e\u093e\u0907\u0915\u094d\u0930\u094b\u0938\u0949\u092b\u094d\u091f \u090f\u0915\u094d\u0938\u0947\u0938 \u091f\u0947\u092c\u0932 \u0915\u0947 \u0915\u0949\u0932\u092e \u0915\u094b \u0907\u0938 \u0930\u0942\u092a \u092e\u0947\u0902 \u091c\u093e\u0928\u093e \u091c\u093e\u0924\u093e \u0939\u0948:<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1023]' id='ays-answer-3896-46' value='3896'\/>\n\n                <label for='ays-answer-3896-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Inverted row<\/label><label for='ays-answer-3896-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1023]' id='ays-answer-3897-46' value='3897'\/>\n\n                <label for='ays-answer-3897-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Vertical cell<\/label><label for='ays-answer-3897-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1023]' id='ays-answer-3898-46' value='3898'\/>\n\n                <label for='ays-answer-3898-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Record<\/label><label for='ays-answer-3898-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1023]' id='ays-answer-3899-46' value='3899'\/>\n\n                <label for='ays-answer-3899-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Field<\/label><label for='ays-answer-3899-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1023'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='21' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>95 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>95. <span style=\"font-weight: 400\">\u0928\u093f\u092e\u0902\u0932\u093e\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928 \u0938\u093e <\/span><span style=\"font-weight: 400\">excel<\/span><span style=\"font-weight: 400\"> \u0915\u093e <\/span><span style=\"font-weight: 400\">term<\/span><span style=\"font-weight: 400\"> \u0928\u0939\u0940\u0902 \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-21]' id='ays-answer-78-46' value='78'\/>\n\n                <label for='ays-answer-78-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. cell<\/label><label for='ays-answer-78-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-21]' id='ays-answer-79-46' value='79'\/>\n\n                <label for='ays-answer-79-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Rows<\/label><label for='ays-answer-79-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-21]' id='ays-answer-80-46' value='80'\/>\n\n                <label for='ays-answer-80-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Document<\/label><label for='ays-answer-80-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-21]' id='ays-answer-81-46' value='81'\/>\n\n                <label for='ays-answer-81-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. column<\/label><label for='ays-answer-81-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['21'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='1042' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>96 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>96. <strong>MS \u0935\u093f\u0902\u0921\u094b\u091c \u0911\u092a\u0930\u0947\u091f\u093f\u0902\u0917 \u0938\u093f\u0938\u094d\u091f\u092e \u0915\u092c \u092a\u094d\u0930\u0938\u094d\u0924\u093e\u0935\u093f\u0924 \u0939\u0941\u0906 \u0925\u093e?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1042]' id='ays-answer-3972-46' value='3972'\/>\n\n                <label for='ays-answer-3972-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1992<\/label><label for='ays-answer-3972-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1042]' id='ays-answer-3973-46' value='3973'\/>\n\n                <label for='ays-answer-3973-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1995<\/label><label for='ays-answer-3973-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1042]' id='ays-answer-3974-46' value='3974'\/>\n\n                <label for='ays-answer-3974-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 1994<\/label><label for='ays-answer-3974-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-1042]' id='ays-answer-3975-46' value='3975'\/>\n\n                <label for='ays-answer-3975-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 1990<\/label><label for='ays-answer-3975-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['1042'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='18' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>97 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>97. <span style=\"font-weight: 400\">Excel<\/span><span style=\"font-weight: 400\"> \u0915\u0940 <\/span><span style=\"font-weight: 400\">sheet<\/span><span style=\"font-weight: 400\"> \u0915\u094b \u0915\u094d\u092f\u093e \u0915\u0939\u0924\u0947 \u0939\u0948?<\/span><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-18]' id='ays-answer-66-46' value='66'\/>\n\n                <label for='ays-answer-66-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. spreadsheet<\/label><label for='ays-answer-66-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-18]' id='ays-answer-67-46' value='67'\/>\n\n                <label for='ays-answer-67-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Document sheet<\/label><label for='ays-answer-67-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-18]' id='ays-answer-68-46' value='68'\/>\n\n                <label for='ays-answer-68-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. File sheet<\/label><label for='ays-answer-68-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-18]' id='ays-answer-69-46' value='69'\/>\n\n                <label for='ays-answer-69-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. folder sheet<\/label><label for='ays-answer-69-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['18'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='7' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>98 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>98. View Menu \u092e\u0947\u0902 Split \u0906\u092a\u094d\u0936\u0928 \u0915\u093e \u0915\u094d\u092f\u093e \u0915\u093e\u0930\u094d\u092f \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-7]' id='ays-answer-22-46' value='22'\/>\n\n                <label for='ays-answer-22-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0935\u093f\u0902\u0921\u094b \u092c\u0902\u0926 \u0915\u0930\u0928\u093e<\/label><label for='ays-answer-22-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-7]' id='ays-answer-23-46' value='23'\/>\n\n                <label for='ays-answer-23-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0928\u092f\u0940 \u0935\u093f\u0902\u0921\u094b \u0916\u094b\u0932\u0928\u093e<\/label><label for='ays-answer-23-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-7]' id='ays-answer-24-46' value='24'\/>\n\n                <label for='ays-answer-24-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0938\u092d\u0940 \u0935\u093f\u0902\u0921\u094b \u0915\u094b \u0905\u0930\u0947\u0902\u091c \u0915\u0930\u0928\u093e<\/label><label for='ays-answer-24-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-7]' id='ays-answer-25-46' value='25'\/>\n\n                <label for='ays-answer-25-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u090f\u0915 \u0935\u093f\u0902\u0921\u094b \u0915\u094b \u0926\u094b \u092d\u093e\u0917\u094b \u092e\u0947\u0902 \u092c\u093e\u091f\u0928\u093e<\/label><label for='ays-answer-25-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['7'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='626' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>99 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>99. <strong>MS Office \u092e\u0947\u0902 Default Print mode \u0915\u094d\u092f\u093e \u0939\u0948 ?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-626]' id='ays-answer-2319-46' value='2319'\/>\n\n                <label for='ays-answer-2319-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Portrait<\/label><label for='ays-answer-2319-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-626]' id='ays-answer-2320-46' value='2320'\/>\n\n                <label for='ays-answer-2320-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Web Layout<\/label><label for='ays-answer-2320-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-626]' id='ays-answer-2321-46' value='2321'\/>\n\n                <label for='ays-answer-2321-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Landscape<\/label><label for='ays-answer-2321-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-626]' id='ays-answer-2322-46' value='2322'\/>\n\n                <label for='ays-answer-2322-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Full Screen<\/label><label for='ays-answer-2322-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['626'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='616' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>100 \/ 100<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>100. <strong>\u092e\u093e\u0907\u0915\u094d\u0930\u094b\u092a\u094d\u0930\u094b\u0938\u0947\u0938\u0930 \u091c\u094b \u0915\u0902\u092a\u094d\u092f\u0942\u091f\u0930 \u0915\u093e \u092e\u0938\u094d\u0924\u093f\u0937\u094d\u0915 \u0939\u094b\u0924\u093e \u0939\u0948<\/strong><strong>, \u0909\u0938\u0947 \u0915\u0939\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/strong><\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-616]' id='ays-answer-2279-46' value='2279'\/>\n\n                <label for='ays-answer-2279-46' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0938\u0949\u092b\u094d\u091f\u0935\u0947\u092f\u0930<\/label><label for='ays-answer-2279-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-616]' id='ays-answer-2280-46' value='2280'\/>\n\n                <label for='ays-answer-2280-46' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092e\u093e\u0907\u0915\u094d\u0930\u094b\u091a\u093f\u092a<\/label><label for='ays-answer-2280-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-616]' id='ays-answer-2281-46' value='2281'\/>\n\n                <label for='ays-answer-2281-46' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u092e\u0945\u0915\u094d\u0930\u094b\u091a\u093f\u092a<\/label><label for='ays-answer-2281-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-616]' id='ays-answer-2282-46' value='2282'\/>\n\n                <label for='ays-answer-2282-46' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0938\u092d\u0940 \u0915\u0925\u0928 \u0938\u0924\u094d\u092f \u0939\u0948<\/label><label for='ays-answer-2282-46' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_46 === 'undefined'){\n                window.quizOptions_46 = [];\n            }\n            window.quizOptions_46['616'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                            \n                            <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                            <input type='button' class='ays_previous action-button ays-quiz-keyboard-active '  value='Prev' \/>\n                            <i class='ays_display_none ays_fa ays_fa_flag_checkered ays_finish action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active' tabindex='0'><\/i><input type='submit' name='ays_finish_quiz' class='  ays_next ays_finish action-button ays-quiz-keyboard-active' value='See Result'\/>\n                        <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ays_thank_you_fs'>\n            <div class='ays-abs-fs ays-end-page'><div data-class='lds-ellipsis' data-role='loader' class='ays-loader'><div><\/div><div><\/div><div><\/div><div><\/div><\/div><div class='ays_quiz_results_page'><div class='ays_score_message'><\/div><div class='ays_message'><\/div><p class='ays_score ays_score_display_none animated'>Your score is<\/p><p class='ays_average'>The average score is 48%<\/p><div class='ays-progress first'>\n                <span class='ays-progress-value first'>0%<\/span>\n                <div class='ays-progress-bg first'>\n                    <div class='ays-progress-bar first' style='width:0%;'><\/div>\n                <\/div>\n            <\/div><p class='ays_restart_button_p'><button type='button' class='action-button ays_restart_button ays-quiz-keyboard-active'>\n                    <i class='ays_fa ays_fa_undo'><\/i>\n                    <span>Restart quiz<\/span>\n                <\/button><\/p><\/div>\n            <\/div>\n        <\/div><style>\n            div#ays-quiz-container-46 * {\n                box-sizing: border-box;\n            }\n\n            #ays-quiz-container-46 [id^='ays_finish_quiz_'] div.step div.ays-abs-fs {\n                width: 90%;\n            }\n\n            \/* Styles for Internet Explorer start *\/\n            #ays-quiz-container-46 #ays_finish_quiz_46 {\n                \n            }\n\n            \/* Styles for Quiz container *\/\n            #ays-quiz-container-46{\n                min-height: 400px;\n                width:100%;\n                background-color:rgba(212,120,226,0.31);\n                background-position:center center;background-image: linear-gradient(to bottom, rgba(165,104,226,0.26), #fff);border-radius:0px;box-shadow: 0px 0px 15px  1px rgba(0,0,0,0.4);border: none;}\n\n            \/* Styles for questions *\/\n            #ays-quiz-container-46 #ays_finish_quiz_46 div.step {\n                min-height: 400px;\n            }\n\n            \/* Styles for text inside quiz container *\/\n            #ays-quiz-container-46 .ays-start-page *:not(input):not([class^='enlighter']),\n            #ays-quiz-container-46 .ays_question_hint,\n            #ays-quiz-container-46 label[for^=\"ays-answer-\"],\n            #ays-quiz-container-46 #ays_finish_quiz_46 p,\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-fs-title,\n            #ays-quiz-container-46 .ays-fs-subtitle,\n            #ays-quiz-container-46 .logged_in_message,\n            #ays-quiz-container-46 .ays_score_message,\n            #ays-quiz-container-46 .ays_message{\n               color: #000;\n               outline: none;\n            }\n\n            div#ays-quiz-container-46 .ays_question_hint.ays-quiz-keyboard-active,\n            div#ays-quiz-container-46 .ays_restart_button.ays-quiz-keyboard-active {\n                outline: revert;\n            }\n\n            #ays-quiz-container-46 .ays-quiz-password-message-box,\n            #ays-quiz-container-46 .ays-quiz-question-note-message-box,\n            #ays-quiz-container-46 .ays_quiz_question,\n            #ays-quiz-container-46 .ays-quiz-question-category-box,\n            #ays-quiz-container-46 .ays_quiz_question *:not([class^='enlighter']) {\n                color: #000;\n            }\n\n            #ays-quiz-container-46 .ays-quiz-question-category-box em {\n                color: #000;\n            }\n\n            #ays-quiz-container-46 textarea,\n            #ays-quiz-container-46 input::first-letter,\n            #ays-quiz-container-46 select::first-letter,\n            #ays-quiz-container-46 option::first-letter {\n                color: initial !important;\n            }\n            \n            #ays-quiz-container-46 p::first-letter:not(.ays_no_questions_message) {\n                color: #000 !important;\n                background-color: transparent !important;\n                font-size: inherit !important;\n                font-weight: inherit !important;\n                float: none !important;\n                line-height: inherit !important;\n                margin: 0 !important;\n                padding: 0 !important;\n            }\n            \n            \n            #ays-quiz-container-46 .select2-container,\n            #ays-quiz-container-46 .ays-field * {\n                font-size: 18px !important;\n            }\n    \n            #ays-quiz-container-46 .ays_quiz_question p {\n                font-size: 18px;\n                text-align: inherit;\n            }\n\n            #ays-quiz-container-46 .ays-fs-subtitle p {\n                text-align:  center ;\n            }\n\n            #ays-quiz-container-46 .ays_quiz_question {\n                text-align:  center ;\n                margin-bottom: 10px;\n            }\n\n            #ays-quiz-container-46 .ays_quiz_question pre {\n                max-width: 100%;\n                white-space: break-spaces;\n            }\n\n            \/* Mango theme (Version: 1.4.202301041836) | tid=32449 | Start *\/\n            #ays-quiz-container-46 .ays_quiz_question img {\n                float: unset;\n                margin: 0;\n            }\n            \/* Mango theme (Version: 1.4.202301041836) | End *\/\n\n            #ays-quiz-container-46 .ays-quiz-timer p {\n                font-size: 16px;\n            }\n\n            #ays-quiz-container-46 section.ays_quiz_redirection_timer_container hr,\n            #ays-quiz-container-46 section.ays_quiz_timer_container hr {\n                margin: 0;\n            }\n\n            #ays-quiz-container-46 section.ays_quiz_timer_container.ays_quiz_timer_red_warning .ays-quiz-timer {\n                color: #ff0000;\n            }\n\n            #ays-quiz-container-46 .ays_thank_you_fs p {\n                text-align: center;\n            }\n\n            #ays-quiz-container-46 .ays_quiz_results_page .ays_score span {\n                visibility: visible;\n            }\n\n            #ays-quiz-container-46 input[type='button'],\n            #ays-quiz-container-46 input[type='submit'] {\n                color: #000000 !important;\n            }\n\n            #ays-quiz-container-46 input[type='button']{\n                outline: none;\n            }\n\n            #ays-quiz-container-46 .information_form input[type='text'],\n            #ays-quiz-container-46 .information_form input[type='url'],\n            #ays-quiz-container-46 .information_form input[type='number'],\n            #ays-quiz-container-46 .information_form input[type='email'],\n            #ays-quiz-container-46 .information_form input[type='checkbox'],\n            #ays-quiz-container-46 .information_form input[type='tel'],\n            #ays-quiz-container-46 .information_form textarea,\n            #ays-quiz-container-46 .information_form select,\n            #ays-quiz-container-46 .information_form option {\n                color: initial !important;\n                outline: none;\n                background-image: unset;\n            }\n\n            #ays-quiz-container-46 .wrong_answer_text{\n                color:#ff4d4d;\n            }\n            #ays-quiz-container-46 .right_answer_text{\n                color:#33cc33;\n            }\n\n            #ays-quiz-container-46 .wrong_answer_text p {\n                font-size:18px;\n            }\n\n            #ays-quiz-container-46 .ays_questtion_explanation p {\n                font-size:18px;\n            }\n\n            #ays-quiz-container-46 .wrong_answer_text *:not(strong) {\n                text-transform:none;\n                text-decoration: none;\n                letter-spacing: 0px;\n                font-weight: normal;\n            }\n\n            #ays-quiz-container-46 .ays_questtion_explanation *:not(strong) {\n                text-transform:none;\n                text-decoration: none;\n                letter-spacing: 0px;\n                font-weight: normal;\n            }\n\n            #ays-quiz-container-46 .right_answer_text *:not(strong) {\n                text-transform:none;\n                text-decoration: none;\n                letter-spacing: 0px;\n                font-weight: normal;\n            }\n\n            #ays-quiz-container-46 .right_answer_text p {\n                font-size:16px;\n            }\n\n            #ays-quiz-container-46 .ays-quiz-question-note-message-box p {\n                font-size:14px;\n            }\n\n            #ays-quiz-container-46 .ays-quiz-question-note-message-box *:not(strong) {\n                text-transform:none;\n                text-decoration: none;\n                letter-spacing: 0px;\n                font-weight: normal;\n            }\n            \n            #ays-quiz-container-46 .ays_cb_and_a,\n            #ays-quiz-container-46 .ays_cb_and_a * {\n                color: rgb(0,0,0);\n                text-align: center;\n            }\n\n            \/* Quiz textarea height *\/\n            #ays-quiz-container-46 textarea {\n                height: 100px;\n                min-height: 100px;\n            }\n\n            \/* Quiz rate and passed users count *\/\n            #ays-quiz-container-46 .ays_quizn_ancnoxneri_qanak,\n            #ays-quiz-container-46 .ays_quiz_rete_avg {\n                color:rgba(212,120,226,0.31) !important;\n                background-color:#000;   \n            }\n\n            #ays-quiz-container-46 .ays-questions-container > .ays_quizn_ancnoxneri_qanak {\n                padding: 5px 20px;\n            }\n            #ays-quiz-container-46 div.for_quiz_rate.ui.star.rating .icon {\n                color: rgba(0,0,0,0.35);\n            }\n            #ays-quiz-container-46 .ays_quiz_rete_avg div.for_quiz_rate_avg.ui.star.rating .icon {\n                color: rgba(212,120,226,0.31);\n            }\n\n            #ays-quiz-container-46 .ays_quiz_rete .ays-quiz-rate-link-box .ays-quiz-rate-link {\n                color: #000;\n            }\n\n            \/* Loaders *\/            \n            #ays-quiz-container-46 div.lds-spinner,\n            #ays-quiz-container-46 div.lds-spinner2 {\n                color: #000;\n            }\n            #ays-quiz-container-46 div.lds-spinner div:after,\n            #ays-quiz-container-46 div.lds-spinner2 div:after {\n                background-color: #000;\n            }\n            #ays-quiz-container-46 .lds-circle,\n            #ays-quiz-container-46 .lds-facebook div,\n            #ays-quiz-container-46 .lds-ellipsis div{\n                background: #000;\n            }\n            #ays-quiz-container-46 .lds-ripple div{\n                border-color: #000;\n            }\n            #ays-quiz-container-46 .lds-dual-ring::after,\n            #ays-quiz-container-46 .lds-hourglass::after{\n                border-color: #000 transparent #000 transparent;\n            }\n\n            \/* Stars *\/\n            #ays-quiz-container-46 .ui.rating .icon,\n            #ays-quiz-container-46 .ui.rating .icon:before {\n                font-family: Rating !important;\n            }\n\n            \/* Progress bars *\/\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-progress {\n                border-color: rgba(0,0,0,0.8);\n            }\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-progress-bg {\n                background-color: rgba(0,0,0,0.3);\n            }    \n            #ays-quiz-container-46 .ays-progress-value {\n                color: #000;\n                text-align: center;\n            }\n            #ays-quiz-container-46 .ays-progress-bar {\n                background-color: rgba(118,0,244,0.63);\n            }\n            #ays-quiz-container-46 .ays-question-counter .ays-live-bar-wrap {\n                direction:ltr !important;\n            }\n            #ays-quiz-container-46 .ays-live-bar-fill{\n                color: #000;\n                border-bottom: 2px solid rgba(0,0,0,0.8);\n                text-shadow: 0px 0px 5px rgba(212,120,226,0.31);\n            }\n            #ays-quiz-container-46 .ays-live-bar-fill.ays-live-fourth,\n            #ays-quiz-container-46 .ays-live-bar-fill.ays-live-third,\n            #ays-quiz-container-46 .ays-live-bar-fill.ays-live-second {\n                text-shadow: unset;\n            }\n            #ays-quiz-container-46 .ays-live-bar-percent{\n                display:none;\n            }\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays_average {\n                text-align: center;\n            }\n            \n            \/* Music, Sound *\/\n            #ays-quiz-container-46 .ays_music_sound {\n                color:rgb(0,0,0);\n            }\n\n            \/* Dropdown questions scroll bar *\/\n            #ays-quiz-container-46 blockquote {\n                border-left-color: #000 !important;                                      \n            }\n\n            \/* Quiz Password *\/\n            #ays-quiz-container-46 .ays-start-page > input[id^='ays_quiz_password_val_'],\n            #ays-quiz-container-46 .ays-quiz-password-toggle-visibility-box {\n                width: 100%;\n            }\n\n\n            \/* Question hint *\/\n            #ays-quiz-container-46 .ays_question_hint_container .ays_question_hint_text {\n                background-color:rgba(212,120,226,0.31);\n                box-shadow: 0 0 15px 3px rgba(0,0,0,0.6);\n                max-width: 270px;\n            }\n\n            #ays-quiz-container-46 .ays_question_hint_container .ays_question_hint_text p {\n                max-width: unset;\n            }\n\n            #ays-quiz-container-46 .ays-quiz-additonal-box {\n                display: flex;\n                justify-content: flex-end;\n                align-items: center;\n                position: relative;  \n            }\n\n            #ays-quiz-container-46 .ays_questions_hint_max_width_class {\n                max-width: 80%;\n            }\n\n            \/* Information form *\/\n            #ays-quiz-container-46 .ays-form-title{\n                color:rgb(0,0,0);\n            }\n\n            \/* Quiz timer *\/\n            #ays-quiz-container-46 div.ays-quiz-redirection-timer,\n            #ays-quiz-container-46 div.ays-quiz-timer{\n                color: #000;\n                text-align: center;\n            }\n\n            #ays-quiz-container-46 div.ays-quiz-timer.ays-quiz-message-before-timer:before {\n                font-weight: 500;\n            }\n\n            \/* Quiz title \/ transformation *\/\n            #ays-quiz-container-46 .ays-fs-title{\n                text-transform: capitalize;\n                font-size: 22px;\n                text-align: center;\n                    text-shadow: none;\n            }\n            \n            \/* Quiz buttons *\/\n            #ays-quiz-container-46 .ays_arrow {\n                color:#000000!important;\n            }\n            #ays-quiz-container-46 input#ays-submit,\n            #ays-quiz-container-46 #ays_finish_quiz_46 .action-button,\n            div#ays-quiz-container-46 #ays_finish_quiz_46 .action-button.ays_restart_button,\n            #ays-quiz-container-46 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn,\n            #ays-quiz-container-46 .ays-quiz-category-selective-submit-bttn {\n                background: none;\n                background-color: rgba(118,0,244,0.63);\n                color:#000000;\n                font-size: 20px;\n                padding: 13px 30px;\n                border-radius: 14px;\n                height: auto;\n                letter-spacing: 0;\n                box-shadow: unset;\n                width: auto;\n                \/* border: unset; *\/\n                min-height: unset;\n                line-height: normal;\n                text-shadow: unset;\n            }\n            #ays-quiz-container-46 input#ays-submit,\n            #ays-quiz-container-46 #ays_finish_quiz_46 input.action-button,\n            #ays-quiz-container-46 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn,\n            #ays-quiz-container-46 .ays-quiz-category-selective-submit-bttn {\n                \n            }\n\n            #ays-quiz-container-46 #ays_finish_quiz_46 .action-button.ays_check_answer {\n                padding: 5px 10px;\n                font-size: 20px !important;\n            }\n            #ays-quiz-container-46 #ays_finish_quiz_46 .action-button.ays_restart_button {\n                white-space: nowrap;\n                padding: 5px 10px;\n                white-space: normal;\n            }\n            #ays-quiz-container-46 input#ays-submit:hover,\n            #ays-quiz-container-46 input#ays-submit:focus,\n            #ays-quiz-container-46 #ays_finish_quiz_46 .action-button:hover,\n            #ays-quiz-container-46 #ays_finish_quiz_46 .action-button:focus,\n            #ays-quiz-container-46 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn:hover,\n            #ays-quiz-container-46 .ays-quiz-category-selective-submit-bttn:hover {\n                background: none;\n                box-shadow: 0 0 0 2px #000000;\n                background-color: rgba(118,0,244,0.63);\n            }\n            #ays-quiz-container-46 .ays_restart_button {\n                color: #000000;\n            }\n            \n            #ays-quiz-container-46 .ays_restart_button_p,\n            #ays-quiz-container-46 .ays_buttons_div {\n                justify-content: center;\n            }\n\n            #ays-quiz-container-46 .ays_finish.action-button{\n                margin: 10px 5px;\n            }\n\n            #ays-quiz-container-46 .ays-share-btn.ays-share-btn-branded {\n                color: #fff;\n                display: inline-block;\n            }\n\n            #ays-quiz-container-46 .ays_quiz_results .ays-field.checked_answer_div.correct_div input:checked+label {\n                background-color: transparent;\n            }\n                        \n            \/* Question answers *\/\n            #ays-quiz-container-46 .ays-field {\n                    border-color: #444;\n                    border-style: solid;\n                    border-width: 2px;\n                    box-shadow: none;flex-direction: row-reverse;\n            }\n            \n\n            \/* Answer maximum length of a text field *\/\n            #ays-quiz-container-46 .ays_quiz_question_text_message{\n                color: #000;\n                text-align: left;\n                font-size: 12px;\n            }\n\n            div#ays-quiz-container-46 div.ays_quiz_question_text_error_message {\n                color: #ff0000;\n            }\n\n            \/* Questions answer image *\/\n            #ays-quiz-container-46 .ays-answer-image {\n                width:15em;\n                height:150px;\n                object-fit: cover;\n            }\n            \n            #ays-quiz-container-46 .ays-quiz-answers .ays-field:hover:not(.ays-answered-text-input){\n                opacity: 1;\n            }\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-field label.ays_answer_caption[for^='ays-answer-'] {\n                z-index: 1;\n                position:initial;bottom:0;}\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-field input~label[for^='ays-answer-'] {\n                padding: 5px;\n            }\n\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-field {\n                margin-bottom: 13px;\n            }\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-field.ays_grid_view_item {\n                width: calc(50% - 6.5px);\n            }\n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-field.ays_grid_view_item:nth-child(odd) {\n                margin-right: 6.5px;\n            }\n            \n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-field input:checked+label:before {\n                border-color: rgba(118,0,244,0.63);\n                background: rgba(118,0,244,0.63);\n                background-clip: content-box;\n            }\n            #ays-quiz-container-46 .ays-quiz-answers div.ays-text-right-answer {\n                color: #000;\n            }\n                        \n            \/* Questions answer right\/wrong icons *\/\n            #ays-quiz-container-46 .ays-field input~label.answered.correct:after{\n                content: url('https:\/\/aiyoit.com\/tutorial\/wp-content\/plugins\/quiz-maker\/public\/images\/correct.png');          }\n            #ays-quiz-container-46 .ays-field input~label.answered.wrong:after{\n                content: url('https:\/\/aiyoit.com\/tutorial\/wp-content\/plugins\/quiz-maker\/public\/images\/wrong.png');\n            }\n            #ays-quiz-container-46 .ays-field label.answered:last-of-type:after{\n                display: none;\n                height: auto;\n                left: 10px;top: 10px;}\n            \/* Dropdown questions *\/            \n            #ays-quiz-container-46 #ays_finish_quiz_46 .ays-field .select2-container--default .select2-selection--single {\n                border-bottom: 2px solid rgba(118,0,244,0.63);\n                background-color: rgba(118,0,244,0.63);\n            }\n            \n            #ays-quiz-container-46 .ays-field .select2-container--default .select2-selection--single .select2-selection__placeholder,\n            #ays-quiz-container-46 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered,\n            #ays-quiz-container-46 .ays-field .select2-container--default .select2-selection--single .select2-selection__arrow {\n                color: #ffffff;\n            }\n\n            #ays-quiz-container-46 .select2-container--default .select2-search--dropdown .select2-search__field:focus,\n            #ays-quiz-container-46 .select2-container--default .select2-search--dropdown .select2-search__field {\n                outline: unset;\n                padding: 0.75rem;\n            }\n\n            #ays-quiz-container-46 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered,\n            #ays-quiz-container-46 .select2-container--default .select2-results__option--highlighted[aria-selected] {\n                background-color: rgba(118,0,244,0.63);\n            }\n\n            #ays-quiz-container-46 .ays-field .select2-container--default,\n            #ays-quiz-container-46 .ays-field .select2-container--default .selection,\n            #ays-quiz-container-46 .ays-field .select2-container--default .dropdown-wrapper,\n            #ays-quiz-container-46 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered,\n            #ays-quiz-container-46 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered .select2-selection__placeholder,\n            #ays-quiz-container-46 .ays-field .select2-container--default .select2-selection--single .select2-selection__arrow,\n            #ays-quiz-container-46 .ays-field .select2-container--default .select2-selection--single .select2-selection__arrow b[role='presentation'] {\n                font-size: 16px !important;\n            }\n\n            #ays-quiz-container-46 .select2-container--default .select2-results__option {\n                padding: 6px;\n            }\n            \n            \/* Dropdown questions scroll bar *\/\n            #ays-quiz-container-46 .select2-results__options::-webkit-scrollbar {\n                width: 7px;\n            }\n            #ays-quiz-container-46 .select2-results__options::-webkit-scrollbar-track {\n                background-color: rgba(212,120,226,0.31);\n            }\n            #ays-quiz-container-46 .select2-results__options::-webkit-scrollbar-thumb {\n                transition: .3s ease-in-out;\n                background-color: rgba(0,0,0,0.55);\n            }\n            #ays-quiz-container-46 .select2-results__options::-webkit-scrollbar-thumb:hover {\n                transition: .3s ease-in-out;\n                background-color: rgba(0,0,0,0.85);\n            }\n\n            \/* Audio \/ Video *\/\n            #ays-quiz-container-46 .mejs-container .mejs-time{\n                box-sizing: unset;\n            }\n            #ays-quiz-container-46 .mejs-container .mejs-time-rail {\n                padding-top: 15px;\n            }\n\n            #ays-quiz-container-46 .mejs-container .mejs-mediaelement video {\n                margin: 0;\n            }\n\n            \/* Limitation *\/\n            #ays-quiz-container-46 .ays-quiz-limitation-count-of-takers {\n                padding: 50px;\n            }\n\n            #ays-quiz-container-46 div.ays-quiz-results-toggle-block span.ays-show-res-toggle.ays-res-toggle-show,\n            #ays-quiz-container-46 div.ays-quiz-results-toggle-block span.ays-show-res-toggle.ays-res-toggle-hide{\n                color: #000;\n            }\n\n            #ays-quiz-container-46 div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle {\n                border: 1px solid #000;\n            }\n\n            #ays-quiz-container-46 div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle {\n                border: 1px solid #000;\n            }\n\n            #ays-quiz-container-46 div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle:after{\n                background: #000;\n            }\n\n            #ays-quiz-container-46.ays_quiz_elegant_dark div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle:after,\n            #ays-quiz-container-46.ays_quiz_rect_dark div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle:after{\n                background: #000;\n            }\n\n            \/* Hestia theme (Version: 3.0.16) | Start *\/\n            #ays-quiz-container-46 .mejs-container .mejs-inner .mejs-controls .mejs-button > button:hover,\n            #ays-quiz-container-46 .mejs-container .mejs-inner .mejs-controls .mejs-button > button {\n                box-shadow: unset;\n                background-color: transparent;\n            }\n            #ays-quiz-container-46 .mejs-container .mejs-inner .mejs-controls .mejs-button > button {\n                margin: 10px 6px;\n            }\n            \/* Hestia theme (Version: 3.0.16) | End *\/\n\n            \/* Go theme (Version: 1.4.3) | Start *\/\n            #ays-quiz-container-46 label[for^='ays-answer']:before,\n            #ays-quiz-container-46 label[for^='ays-answer']:before {\n                -webkit-mask-image: unset;\n                mask-image: unset;\n            }\n\n            #ays-quiz-container-46.ays_quiz_classic_light .ays-field input:checked+label.answered.correct:before,\n            #ays-quiz-container-46.ays_quiz_classic_dark .ays-field input:checked+label.answered.correct:before {\n                background-color: rgba(118,0,244,0.63) !important;\n                background-color: rgba(39,174,96, 1) !important;\n            }\n            \/* Go theme (Version: 1.4.3) | End *\/\n\n            #ays-quiz-container-46 .ays_quiz_results fieldset.ays_fieldset .ays_quiz_question .wp-video {\n                width: 100% !important;\n                max-width: 100%;\n            }\n\n            \/* Classic Dark \/ Classic Light *\/\n            \/* Dropdown questions right\/wrong styles *\/\n            #ays-quiz-container-46.ays_quiz_classic_dark .correct_div,\n            #ays-quiz-container-46.ays_quiz_classic_light .correct_div{\n                border-color:green !important;\n                opacity: 1 !important;\n                background-color: rgba(39,174,96,0.4) !important;\n            }\n            #ays-quiz-container-46.ays_quiz_classic_dark .correct_div .selected-field,\n            #ays-quiz-container-46.ays_quiz_classic_light .correct_div .selected-field {\n                padding: 0px 10px 0px 10px;\n                color: green !important;\n            }\n\n            #ays-quiz-container-46.ays_quiz_classic_dark .wrong_div,\n            #ays-quiz-container-46.ays_quiz_classic_light .wrong_div{\n                border-color:red !important;\n                opacity: 1 !important;\n                background-color: rgba(243,134,129,0.4) !important;\n            }\n            #ays-quiz-container-46.ays_quiz_classic_dark .ays-field.checked_answer_div.wrong_div input:checked~label,\n            #ays-quiz-container-46.ays_quiz_classic_light .ays-field.checked_answer_div.wrong_div input:checked~label {\n                background-color: rgba(243,134,129,0.4) !important;\n            }\n            #ays-quiz-container-46.ays_quiz_classic_dark .ays-field,\n            #ays-quiz-container-46.ays_quiz_classic_light .ays-field {\n                text-align: left;\n                \/*margin-bottom: 10px;*\/\n                padding: 0;\n                transition: .3s ease-in-out;\n            }\n\n            #ays-quiz-container-46 .ays-quiz-close-full-screen {\n                fill: #000;\n            }\n\n            #ays-quiz-container-46 .ays-quiz-open-full-screen {\n                fill: #000;\n            }\n\n            #ays-quiz-container-46 .ays_quiz_login_form p{\n                color: #000;\n            }\n\n            \/* report questions modal start *\/\n            .ays-modal-reports {\n                display: none;\n                position: fixed;\n                z-index: 9999;\n                left: 0;\n                top: 0;\n                width: 100%;\n                height: 100%;\n                overflow: auto;\n                background-color: rgba(0, 0, 0, 0.4);\n                animation-duration: .5s;\n                background-color: rgba(0, 0, 0, 0.4);\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-modal-content-reports {\n                background-color: #fefefe;\n                margin: 10% auto;\n                border: 1px solid #888;\n                max-width: 500px;\n                width: 100%;\n                border-radius: 10px;\n                padding: 20px;\n                box-sizing: border-box;\n                position: relative;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-modal-content-reports label{\n                display: block;\n                margin-bottom: 10px;\n                font-weight: bold;\n                letter-spacing: normal;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-modal-content-reports textarea {\n                display: block;\n                width: 100%;\n                height: 100px;\n                padding: 5px;\n                box-sizing: border-box;\n                border-radius: 5px;\n                border: 1px solid #ccc;\n                max-width: 100%;\n                max-height: 500px;\n                resize: vertical;\n                transition: unset;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-modal-content-reports input.ays-quiz-submit-question-report {\n                background-color: #0073aa;\n                color: #fff !important;\n                border: none;\n                border-radius: 5px;\n                padding: 10px 20px;\n                cursor: pointer;\n                margin-top: 20px;\n                line-height: normal;\n                letter-spacing: normal;\n                box-shadow: unset;\n                background-image: unset;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-close-reports-window {\n                color: #aaa;\n                font-weight: bold;\n                position: absolute;\n                top: 1%;\n                right: 1%;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-close-reports-window img {\n                box-shadow: unset;\n            }\n            \n            #ays-quiz-question-report-modal-46 .ays-quiz-preloader img {\n                box-shadow: unset;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-close-reports-window img:hover,\n            #ays-quiz-question-report-modal-46 .ays-close-reports-window img:focus {\n                cursor: pointer;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-quiz-question-report-error {\n                display: none;\n                font-size: 13px;\n                color: #f00;\n                text-align: left;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-quiz-question-report-textarea-label,\n            #ays-quiz-question-report-modal-46 .ays-quiz-question-report-title {\n                text-align: left;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays_quiz_modal_overlay {\n                width: 100%;\n                height: 100%;\n                position: fixed;\n                top: 0;\n                left: 0;\n                position: absolute;\n                z-index: 1000000000;\n                flex-direction: column;\n            }\n\n            #ays-quiz-question-report-modal-46 .ays-quiz-container .ays-quiz-user-c\u0570oosing-anonymous-assessment {\n                margin: 10px 0;\n            }\n\n            \/* report questions modal end *\/\n\n            @media screen and (max-width: 768px){\n                #ays-quiz-container-46{\n                    max-width: 100%;\n                }\n\n                div#ays-quiz-container-46 [id^='ays_finish_quiz_'] div.step div.ays-abs-fs {\n                    width: 90%;\n                }\n\n                #ays-quiz-container-46 .ays_quiz_question p {\n                    font-size: 18px;\n                }\n\n                #ays-quiz-container-46 .select2-container,\n                #ays-quiz-container-46 .ays-field * {\n                    font-size: 18px !important;\n                }\n\n                div#ays-quiz-container-46 input#ays-submit,\n                div#ays-quiz-container-46 #ays_finish_quiz_46 .action-button,\n                div#ays-quiz-container-46 #ays_finish_quiz_46 .action-button.ays_restart_button,\n                #ays-quiz-container-46 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn,\n                #ays-quiz-container-46 .ays-quiz-category-selective-submit-bttn {\n                    font-size: 20px;\n                }\n\n                \/* Quiz title \/ mobile font size *\/\n                div#ays-quiz-container-46 .ays-fs-title {\n                    font-size: 22px;\n                }\n\n                \/* Question explanation \/ mobile font size *\/\n                #ays-quiz-container-46 .ays_questtion_explanation p {\n                    font-size:18px;\n                }\n\n                \/* Wrong answers \/ mobile font size *\/\n                #ays-quiz-container-46 .wrong_answer_text p {\n                    font-size:18px;\n                }\n\n                \/* Right answers \/ mobile font size *\/\n                #ays-quiz-container-46 .right_answer_text p {\n                    font-size:16px;\n                }\n\n                \/* Note text \/ mobile font size *\/\n                #ays-quiz-container-46 .ays-quiz-question-note-message-box p {\n                    font-size:14px;\n                }\n\n                div#ays-quiz-container-46 .ays-quiz-question-note-message-box *:not(strong) {\n                    text-transform:none;\n                    text-decoration: none;\n                    letter-spacing: 0px;\n                    font-weight: normal;\n                }\n\n                div#ays-quiz-container-46 .ays_questtion_explanation *:not(strong) {\n                    text-transform:none;\n                    text-decoration: none;\n                    letter-spacing: 0px;\n                    font-weight: normal;\n                }\n\n                div#ays-quiz-container-46 .right_answer_text *:not(strong) {\n                    text-transform:none;\n                    text-decoration: none;\n                    letter-spacing: 0px;\n                    font-weight: normal;\n                }\n\n                div#ays-quiz-container-46 .wrong_answer_text *:not(strong) {\n                    text-transform:none;\n                    text-decoration: none;\n                    letter-spacing: 0px;\n                    font-weight: normal;\n                }\n            }\n            \/* Custom css styles *\/\n            \n            \n            \/* RTL direction styles *\/\n            \n        <\/style>\n            <style>\n                #ays-quiz-container-46 p {\n                    margin: 0.625em;\n                }\n                \n                #ays-quiz-container-46 .ays-field.checked_answer_div input:checked~label {\n                    background-color: rgba(118,0,244,0.63);\n                }\n\n                #ays-quiz-container-46.ays_quiz_classic_light  .ays_quiz_results .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-46.ays_quiz_classic_dark  .ays_quiz_results .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-46.ays_quiz_classic_light  .enable_correction .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-46.ays_quiz_classic_dark  .enable_correction .ays-field.checked_answer_div input:checked~label {\n                    background-color: transparent;\n                }\n\n                #ays-quiz-container-46.ays_quiz_classic_light  .ays_quiz_results .not_influence_to_score .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-46.ays_quiz_classic_dark  .ays_quiz_results .not_influence_to_score .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-46.ays_quiz_classic_light  .enable_correction .not_influence_to_score .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-46.ays_quiz_classic_dark  .enable_correction .not_influence_to_score .ays-field.checked_answer_div input:checked~label {\n                    background-color: rgba(118,0,244,0.63);\n                }\n                \n                #ays-quiz-container-46 .ays-field.checked_answer_div input:checked~label:hover {\n                    background-color: rgba(118,0,244,0.63);\n                }\n\n                #ays-quiz-container-46.ays-quiz-container.ays_quiz_classic_light .ays-questions-container .ays-field:hover label[for^='ays-answer-'],\n                #ays-quiz-container-46 .ays-field:hover:not(.ays-answered-text-input){\n                    background: rgba(118,0,244,0.63);\n                    \/* border-radius: 4px; *\/\n                    color: #fff;\n                    transition: all .3s;\n                }\n                #ays-quiz-container-46 #ays_finish_quiz_46 .action-button:hover,\n                #ays-quiz-container-46 #ays_finish_quiz_46 .action-button:focus,\n                #ays-quiz-container-46 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn:hover,\n                #ays-quiz-container-46 .ays-quiz-category-selective-submit-bttn:focus {\n                    box-shadow: 0 0 0 2px white, 0 0 0 3px rgba(118,0,244,0.63);\n                    background: rgba(118,0,244,0.63);\n                }\n            <\/style><script>\n                if(typeof aysQuizOptions === 'undefined'){\n                    var aysQuizOptions = [];\n                }\n                aysQuizOptions['46']  = 'eyJxdWl6X3ZlcnNpb24iOiI2LjMuOS45IiwiY29yZV92ZXJzaW9uIjoiNi4xLjciLCJwaHBfdmVyc2lvbiI6IjguMi4yNyIsImNvbG9yIjoicmdiYSgxMTgsMCwyNDQsMC42MykiLCJiZ19jb2xvciI6InJnYmEoMjEyLDEyMCwyMjYsMC4zMSkiLCJ0ZXh0X2NvbG9yIjoiIzAwMCIsImhlaWdodCI6NDAwLCJ3aWR0aCI6MCwiZW5hYmxlX2xvZ2dlZF91c2VycyI6Im9mZiIsImluZm9ybWF0aW9uX2Zvcm0iOiJiZWZvcmUiLCJmb3JtX25hbWUiOiJvbiIsImZvcm1fZW1haWwiOiJvbiIsImZvcm1fcGhvbmUiOiJvbiIsImltYWdlX3dpZHRoIjoiIiwiaW1hZ2VfaGVpZ2h0IjoiIiwiZW5hYmxlX2NvcnJlY3Rpb24iOiJvZmYiLCJlbmFibGVfcHJvZ3Jlc3NfYmFyIjoib24iLCJlbmFibGVfcXVlc3Rpb25zX3Jlc3VsdCI6Im9uIiwicmFuZG9taXplX3F1ZXN0aW9ucyI6Im9uIiwicmFuZG9taXplX2Fuc3dlcnMiOiJvZmYiLCJlbmFibGVfcXVlc3Rpb25zX2NvdW50ZXIiOiJvbiIsImVuYWJsZV9yZXN0cmljdGlvbl9wYXNzIjoib2ZmIiwicmVzdHJpY3Rpb25fcGFzc19tZXNzYWdlIjoiIiwidXNlcl9yb2xlIjpbXSwiY3VzdG9tX2NzcyI6IiIsImxpbWl0X3VzZXJzIjoib2ZmIiwibGltaXRhdGlvbl9tZXNzYWdlIjoiIiwicmVkaXJlY3RfdXJsIjoiIiwicmVkaXJlY3Rpb25fZGVsYXkiOjAsImFuc3dlcnNfdmlldyI6Imxpc3QiLCJlbmFibGVfcnRsX2RpcmVjdGlvbiI6Im9mZiIsImVuYWJsZV9sb2dnZWRfdXNlcnNfbWVzc2FnZSI6IiIsInF1ZXN0aW9uc19jb3VudCI6IiIsImVuYWJsZV9xdWVzdGlvbl9iYW5rIjoib2ZmIiwiZW5hYmxlX2xpdmVfcHJvZ3Jlc3NfYmFyIjoib2ZmIiwiZW5hYmxlX3BlcmNlbnRfdmlldyI6Im9mZiIsImVuYWJsZV9hdmVyYWdlX3N0YXRpc3RpY2FsIjoib24iLCJlbmFibGVfbmV4dF9idXR0b24iOiJvbiIsImVuYWJsZV9wcmV2aW91c19idXR0b24iOiJvbiIsImVuYWJsZV9hcnJvd3MiOiJvZmYiLCJ0aW1lcl90ZXh0IjoiRG8gbm90IHdhc3RlIHlvdXIgdGltZSBvbiBvbmx5IG9uZSBxdWVzdGlvbiIsInF1aXpfdGhlbWUiOiJjbGFzc2ljX2xpZ2h0IiwiZW5hYmxlX3NvY2lhbF9idXR0b25zIjoib2ZmIiwicmVzdWx0X3RleHQiOiIiLCJlbmFibGVfcGFzc19jb3VudCI6Im9mZiIsImhpZGVfc2NvcmUiOiJvZmYiLCJyYXRlX2Zvcm1fdGl0bGUiOiIiLCJib3hfc2hhZG93X2NvbG9yIjoiIzAwMCIsInF1aXpfYm9yZGVyX3JhZGl1cyI6IjAiLCJxdWl6X2JnX2ltYWdlIjoiIiwicXVpel9ib3JkZXJfd2lkdGgiOiIxIiwicXVpel9ib3JkZXJfc3R5bGUiOiJzb2xpZCIsInF1aXpfYm9yZGVyX2NvbG9yIjoiIzAwMCIsInF1aXpfbG9hZGVyIjoiZGVmYXVsdCIsImNyZWF0ZV9kYXRlIjpudWxsLCJhdXRob3IiOiJ7XCJpZFwiOlwiM1wiLFwibmFtZVwiOlwiVmluYXkgU2luZ2hcIn0iLCJxdWVzdF9hbmltYXRpb24iOiJub25lIiwiZm9ybV90aXRsZSI6IlBsZWFzZSBmaWxsIHlvdXIgcmVxdWlyZWQqIGluZm9ybWF0aW9uIiwiZW5hYmxlX2JnX211c2ljIjoib2ZmIiwicXVpel9iZ19tdXNpYyI6IiIsImFuc3dlcnNfZm9udF9zaXplIjoxOCwic2hvd19jcmVhdGVfZGF0ZSI6Im9mZiIsInNob3dfYXV0aG9yIjoib2ZmIiwiZW5hYmxlX2Vhcmx5X2ZpbmlzaCI6Im9mZiIsImFuc3dlcnNfcndfdGV4dHMiOiJvbl9wYXNzaW5nIiwiZGlzYWJsZV9zdG9yZV9kYXRhIjoib2ZmIiwiZW5hYmxlX2JhY2tncm91bmRfZ3JhZGllbnQiOiJvbiIsImJhY2tncm91bmRfZ3JhZGllbnRfY29sb3JfMSI6InJnYmEoMTY1LDEwNCwyMjYsMC4yNikiLCJiYWNrZ3JvdW5kX2dyYWRpZW50X2NvbG9yXzIiOiIjZmZmIiwicXVpel9ncmFkaWVudF9kaXJlY3Rpb24iOiJ2ZXJ0aWNhbCIsInJlZGlyZWN0X2FmdGVyX3N1Ym1pdCI6Im9mZiIsInN1Ym1pdF9yZWRpcmVjdF91cmwiOiIiLCJzdWJtaXRfcmVkaXJlY3RfZGVsYXkiOiIwIiwicHJvZ3Jlc3NfYmFyX3N0eWxlIjoiZmlyc3QiLCJlbmFibGVfZXhpdF9idXR0b24iOiJvZmYiLCJleGl0X3JlZGlyZWN0X3VybCI6IiIsImltYWdlX3NpemluZyI6ImNvdmVyIiwicXVpel9iZ19pbWFnZV9wb3NpdGlvbiI6ImNlbnRlciBjZW50ZXIiLCJjdXN0b21fY2xhc3MiOiIiLCJlbmFibGVfc29jaWFsX2xpbmtzIjoib2ZmIiwic29jaWFsX2xpbmtzIjp7ImxpbmtlZGluX2xpbmsiOiIiLCJmYWNlYm9va19saW5rIjoiIiwidHdpdHRlcl9saW5rIjoiIiwidmtvbnRha3RlX2xpbmsiOiIiLCJpbnN0YWdyYW1fbGluayI6IiIsInlvdXR1YmVfbGluayI6IiIsImJlaGFuY2VfbGluayI6IiJ9LCJzaG93X3F1aXpfdGl0bGUiOiJvbiIsInNob3dfcXVpel9kZXNjIjoib24iLCJzaG93X2xvZ2luX2Zvcm0iOiJvZmYiLCJtb2JpbGVfbWF4X3dpZHRoIjoiIiwibGltaXRfdXNlcnNfYnkiOiJpcCIsImFjdGl2ZV9kYXRlX2NoZWNrIjoib2ZmIiwiYWN0aXZlSW50ZXJ2YWwiOiIyMDI1LTAyLTA3IDE1OjE3OjU4IiwiZGVhY3RpdmVJbnRlcnZhbCI6IjIwMjUtMDItMDcgMTU6MTc6NTgiLCJhY3RpdmVfZGF0ZV9wcmVfc3RhcnRfbWVzc2FnZSI6IlRoZSBxdWl6IHdpbGwgYmUgYXZhaWxhYmxlIHNvb24hIiwiYWN0aXZlX2RhdGVfbWVzc2FnZSI6IlRoZSBxdWl6IGhhcyBleHBpcmVkISIsImV4cGxhbmF0aW9uX3RpbWUiOiI0IiwiZW5hYmxlX2NsZWFyX2Fuc3dlciI6Im9mZiIsInNob3dfY2F0ZWdvcnkiOiJvZmYiLCJzaG93X3F1ZXN0aW9uX2NhdGVnb3J5Ijoib2ZmIiwiZGlzcGxheV9zY29yZSI6ImJ5X2NvcnJlY3RuZXNzIiwiZW5hYmxlX3J3X2FzbndlcnNfc291bmRzIjoib2ZmIiwiYW5zX3JpZ2h0X3dyb25nX2ljb24iOiJkZWZhdWx0IiwicXVpel9iZ19pbWdfaW5fZmluaXNoX3BhZ2UiOiJvZmYiLCJmaW5pc2hfYWZ0ZXJfd3JvbmdfYW5zd2VyIjoib2ZmIiwiYWZ0ZXJfdGltZXJfdGV4dCI6IiIsImVuYWJsZV9lbnRlcl9rZXkiOiJvbiIsImJ1dHRvbnNfdGV4dF9jb2xvciI6IiMwMDAwMDAiLCJidXR0b25zX3Bvc2l0aW9uIjoiY2VudGVyIiwic2hvd19xdWVzdGlvbnNfZXhwbGFuYXRpb24iOiJvbl9yZXN1bHRzX3BhZ2UiLCJlbmFibGVfYXVkaW9fYXV0b3BsYXkiOiJvZmYiLCJidXR0b25zX3NpemUiOiJsYXJnZSIsImJ1dHRvbnNfZm9udF9zaXplIjoiMjAiLCJidXR0b25zX3dpZHRoIjoiIiwiYnV0dG9uc19sZWZ0X3JpZ2h0X3BhZGRpbmciOiIzMCIsImJ1dHRvbnNfdG9wX2JvdHRvbV9wYWRkaW5nIjoiMTMiLCJidXR0b25zX2JvcmRlcl9yYWRpdXMiOiIxNCIsImVuYWJsZV9sZWF2ZV9wYWdlIjoib24iLCJlbmFibGVfdGFja2Vyc19jb3VudCI6Im9mZiIsInRhY2tlcnNfY291bnQiOiIiLCJwYXNzX3Njb3JlIjo0MCwicGFzc19zY29yZV9tZXNzYWdlIjoiPGg0IHN0eWxlPVwidGV4dC1hbGlnbjogY2VudGVyXCI+Q29uZ3JhdHVsYXRpb25zITxcL2g0PlxyXG48cCBzdHlsZT1cInRleHQtYWxpZ246IGNlbnRlclwiPllvdSBwYXNzZWQgdGhlIHF1aXohPFwvcD4iLCJmYWlsX3Njb3JlX21lc3NhZ2UiOiI8aDQgc3R5bGU9XCJ0ZXh0LWFsaWduOiBjZW50ZXJcIj5Pb3BzITxcL2g0PlxyXG48cCBzdHlsZT1cInRleHQtYWxpZ246IGNlbnRlclwiPllvdSBoYXZlIG5vdCBwYXNzZWQgdGhlIHF1aXohXHJcblRyeSBhZ2FpbiE8XC9wPiIsInF1ZXN0aW9uX2ZvbnRfc2l6ZSI6MTgsInF1aXpfd2lkdGhfYnlfcGVyY2VudGFnZV9weCI6InBlcmNlbnRhZ2UiLCJxdWVzdGlvbnNfaGludF9pY29uX29yX3RleHQiOiJkZWZhdWx0IiwicXVlc3Rpb25zX2hpbnRfdmFsdWUiOiIiLCJlbmFibGVfZWFybHlfZmluc2hfY29tZmlybV9ib3giOiJvbiIsImVuYWJsZV9xdWVzdGlvbnNfb3JkZXJpbmdfYnlfY2F0Ijoib2ZmIiwic2hvd19zY2hlZHVsZV90aW1lciI6Im9mZiIsInNob3dfdGltZXJfdHlwZSI6ImNvdW50ZG93biIsInF1aXpfbG9hZGVyX3RleHRfdmFsdWUiOiIiLCJoaWRlX2NvcnJlY3RfYW5zd2VycyI6Im9mZiIsInNob3dfaW5mb3JtYXRpb25fZm9ybSI6Im9uIiwicXVpel9sb2FkZXJfY3VzdG9tX2dpZiI6IiIsImRpc2FibGVfaG92ZXJfZWZmZWN0Ijoib2ZmIiwicXVpel9sb2FkZXJfY3VzdG9tX2dpZl93aWR0aCI6MTAwLCJwcm9ncmVzc19saXZlX2Jhcl9zdHlsZSI6ImRlZmF1bHQiLCJxdWl6X3RpdGxlX3RyYW5zZm9ybWF0aW9uIjoiY2FwaXRhbGl6ZSIsInNob3dfYW5zd2Vyc19udW1iZXJpbmciOiJhLiIsInF1aXpfaW1hZ2Vfd2lkdGhfYnlfcGVyY2VudGFnZV9weCI6InBpeGVscyIsInF1aXpfaW1hZ2VfaGVpZ2h0IjoiIiwicXVpel9iZ19pbWdfb25fc3RhcnRfcGFnZSI6Im9mZiIsInF1aXpfYm94X3NoYWRvd194X29mZnNldCI6MCwicXVpel9ib3hfc2hhZG93X3lfb2Zmc2V0IjowLCJxdWl6X2JveF9zaGFkb3dfel9vZmZzZXQiOjE1LCJxdWl6X3F1ZXN0aW9uX3RleHRfYWxpZ25tZW50IjoiY2VudGVyIiwicXVpel9hcnJvd190eXBlIjoiZGVmYXVsdCIsInF1aXpfc2hvd193cm9uZ19hbnN3ZXJzX2ZpcnN0Ijoib24iLCJxdWl6X2Rpc3BsYXlfYWxsX3F1ZXN0aW9ucyI6Im9mZiIsInF1aXpfdGltZXJfcmVkX3dhcm5pbmciOiJvZmYiLCJxdWl6X3NjaGVkdWxlX3RpbWV6b25lIjoiVVRDKzUuNSIsInF1ZXN0aW9uc19oaW50X2J1dHRvbl92YWx1ZSI6IiIsInF1aXpfdGFja2Vyc19tZXNzYWdlIjoiVGhpcyBxdWl6IGlzIGV4cGlyZWQhIiwicXVpel9lbmFibGVfbGlua2VkaW5fc2hhcmVfYnV0dG9uIjoib24iLCJxdWl6X2VuYWJsZV9mYWNlYm9va19zaGFyZV9idXR0b24iOiJvbiIsInF1aXpfZW5hYmxlX3R3aXR0ZXJfc2hhcmVfYnV0dG9uIjoib24iLCJxdWl6X21ha2VfcmVzcG9uc2VzX2Fub255bW91cyI6Im9mZiIsInF1aXpfbWFrZV9hbGxfcmV2aWV3X2xpbmsiOiJvZmYiLCJzaG93X3F1ZXN0aW9uc19udW1iZXJpbmciOiIxLiIsInF1aXpfbWVzc2FnZV9iZWZvcmVfdGltZXIiOiIiLCJlbmFibGVfcGFzc3dvcmQiOiJvZmYiLCJwYXNzd29yZF9xdWl6IjoiIiwicXVpel9wYXNzd29yZF9tZXNzYWdlIjoiIiwiZW5hYmxlX3NlZV9yZXN1bHRfY29uZmlybV9ib3giOiJvZmYiLCJkaXNwbGF5X2ZpZWxkc19sYWJlbHMiOiJvZmYiLCJlbmFibGVfZnVsbF9zY3JlZW5fbW9kZSI6Im9uIiwicXVpel9lbmFibGVfcGFzc3dvcmRfdmlzaWJpbGl0eSI6Im9mZiIsInF1ZXN0aW9uX21vYmlsZV9mb250X3NpemUiOjE4LCJhbnN3ZXJzX21vYmlsZV9mb250X3NpemUiOjE4LCJzb2NpYWxfYnV0dG9uc19oZWFkaW5nIjoiIiwicXVpel9lbmFibGVfdmtvbnRha3RlX3NoYXJlX2J1dHRvbiI6Im9uIiwiYW5zd2Vyc19ib3JkZXIiOiJvbiIsImFuc3dlcnNfYm9yZGVyX3dpZHRoIjoyLCJhbnN3ZXJzX2JvcmRlcl9zdHlsZSI6InNvbGlkIiwiYW5zd2Vyc19ib3JkZXJfY29sb3IiOiIjNDQ0Iiwic29jaWFsX2xpbmtzX2hlYWRpbmciOiIiLCJxdWl6X2VuYWJsZV9xdWVzdGlvbl9jYXRlZ29yeV9kZXNjcmlwdGlvbiI6Im9mZiIsImFuc3dlcnNfbWFyZ2luIjoxMywicXVpel9tZXNzYWdlX2JlZm9yZV9yZWRpcmVjdF90aW1lciI6IiIsImJ1dHRvbnNfbW9iaWxlX2ZvbnRfc2l6ZSI6MjAsImFuc3dlcnNfYm94X3NoYWRvdyI6Im9mZiIsImFuc3dlcnNfYm94X3NoYWRvd19jb2xvciI6IiMwMDAiLCJxdWl6X2Fuc3dlcl9ib3hfc2hhZG93X3hfb2Zmc2V0IjowLCJxdWl6X2Fuc3dlcl9ib3hfc2hhZG93X3lfb2Zmc2V0IjowLCJxdWl6X2Fuc3dlcl9ib3hfc2hhZG93X3pfb2Zmc2V0IjoxMCwicXVpel9jcmVhdGVfYXV0aG9yIjozLCJxdWl6X2VuYWJsZV90aXRsZV90ZXh0X3NoYWRvdyI6Im9mZiIsInF1aXpfdGl0bGVfdGV4dF9zaGFkb3dfY29sb3IiOiIjMzMzIiwicXVpel90aXRsZV90ZXh0X3NoYWRvd194X29mZnNldCI6MiwicXVpel90aXRsZV90ZXh0X3NoYWRvd195X29mZnNldCI6MiwicXVpel90aXRsZV90ZXh0X3NoYWRvd196X29mZnNldCI6MiwicXVpel9zaG93X29ubHlfd3JvbmdfYW5zd2VycyI6Im9mZiIsInF1aXpfdGl0bGVfZm9udF9zaXplIjoyMiwicXVpel90aXRsZV9tb2JpbGVfZm9udF9zaXplIjoyMiwicXVpel9wYXNzd29yZF93aWR0aCI6IiIsInF1aXpfcmV2aWV3X3BsYWNlaG9sZGVyX3RleHQiOiIiLCJxdWl6X21ha2VfcmV2aWV3X3JlcXVpcmVkIjoib2ZmIiwicXVpel9lbmFibGVfcmVzdWx0c190b2dnbGUiOiJvZmYiLCJxdWl6X3Jldmlld190aGFua195b3VfbWVzc2FnZSI6IiIsInF1aXpfcmV2aWV3X2VuYWJsZV9jb21tZW50X2ZpZWxkIjoib24iLCJxdWVzdF9leHBsYW5hdGlvbl9mb250X3NpemUiOjE4LCJxdWVzdF9leHBsYW5hdGlvbl9tb2JpbGVfZm9udF9zaXplIjoxOCwicXVpel93YWl0aW5nX3RpbWUiOiJvZmYiLCJ3cm9uZ19hbnN3ZXJzX2ZvbnRfc2l6ZSI6MTgsIndyb25nX2Fuc3dlcnNfbW9iaWxlX2ZvbnRfc2l6ZSI6MTgsInJlcXVpcmVkX2ZpZWxkcyI6WyJheXNfdXNlcl9uYW1lIiwiYXlzX3VzZXJfcGhvbmUiXSwiZW5hYmxlX3RpbWVyIjoib24iLCJlbmFibGVfcXVpel9yYXRlIjoib2ZmIiwiZW5hYmxlX3JhdGVfYXZnIjoib2ZmIiwiZW5hYmxlX2JveF9zaGFkb3ciOiJvbiIsImVuYWJsZV9ib3JkZXIiOiJvZmYiLCJxdWl6X3RpbWVyX2luX3RpdGxlIjoib2ZmIiwiZW5hYmxlX3JhdGVfY29tbWVudHMiOiJvZmYiLCJlbmFibGVfcmVzdGFydF9idXR0b24iOiJvbiIsImF1dG9maWxsX3VzZXJfZGF0YSI6Im9uIiwidGltZXIiOjMwMDAsInF1aXpfYmdfaW1nX2R1cmluZ190aGVfcXVpeiI6Im9mZiIsInNob3dfYW5zd2Vyc19jYXB0aW9uIjoib24iLCJxdWl6X2VuYWJsZV9rZXlib2FyZF9uYXZpZ2F0aW9uIjoib24iLCJzaG93X3F1aXpfaW1hZ2UiOiJvbiIsInF1aXpfZW5hYmxlX3F1aXpfY2F0ZWdvcnlfZGVzY3JpcHRpb24iOiJvZmYiLCJxdWl6X2VuYWJsZV91c2VyX2NcdTA1NzBvb3NpbmdfYW5vbnltb3VzX2Fzc2Vzc21lbnQiOiJvZmYiLCJzdWJtaXRfcmVkaXJlY3RfYWZ0ZXIiOiIiLCJyd19hbnN3ZXJzX3NvdW5kcyI6ZmFsc2UsImlkIjoiNDYiLCJ0aXRsZSI6IkZ1bmRhbWVudGFsLCBXb3JkIGFuZCBFeGNlbCAtIFF1aXoiLCJkZXNjcmlwdGlvbiI6IkhlbGxvIGZyaWVuZCwgd2VsY29tZSB0byB0aGlzIGNvbXB1dGVyIHF1aXogXHUyMDEzIEFJWU8gSVQgLFlvdSBoYXZlIDEwMCBxdWVzdGlvbnMgYW5kIDUwIG1pbnV0ZXMgZm9yIHRoZSB3aG9sZSBxdWVzdGlvbnMsIEhvcGUgeW91IGhhdmUgY29tZSBwcmVwYXJlZCBiZWZvcmVoYW5kLCBJIHdpc2ggeW91IGdvb2QgbHVjaywgeW91IHdpbGwgZG8gd2VsbC4uIiwicXVpel9pbWFnZSI6Imh0dHBzOlwvXC9haXlvaXQuY29tXC90dXRvcmlhbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMTJcL2Nyb3BwZWQtRmF2ZS1JY29uLnBuZyIsInF1aXpfY2F0ZWdvcnlfaWQiOiIxIiwicXVlc3Rpb25faWRzIjoiNzczLDc3Miw3NzEsNzcwLDc2OCw3NjcsNzY2LDc2NSw3NjQsNjk5LDY5Nyw2OTUsNjkzLDY5MSw2ODksNjg4LDY4Niw2ODUsNjgyLDY4MSw2ODAsNjc5LDY1Myw2NDcsNjQ2LDY0NSw2NDQsNjQzLDY0Miw2NDEsNjQwLDYzOSw2MzgsNjM3LDYzMSw2MzAsNjI5LDYyOCw2MjcsNjI2LDYyNSw2MTksNjE4LDYxNyw2MTYsNjE0LDYxMiw0Miw0MSw0MCwzOSwzOCwzNywzNiwzMywzMiwzMSwzMCwyOSwyOCwyNywyNiwyNSwyNCwyMywyMiwyMSwyMCwxOSwxOCwxNywxNiwxNSwxNCwxMywxMiwxMSwxMCw5LDgsNyw2LDEwNTcsMTA1OCwxMDU5LDEwNTYsMTA1NCwxMDUzLDEwNTIsMTA1MSwxMDQ0LDEwNDIsMTA0MywxMDQxLDEwMzQsMTAzMCwxMDMxLDEwMjMsMTAyMiwxMDIxIiwib3JkZXJpbmciOiI0NiIsInB1Ymxpc2hlZCI6IjEiLCJpbnRlcnZhbHMiOm51bGwsImF1dGhvcl9pZCI6IjAiLCJxdWl6X3VybCI6bnVsbCwiY3VzdG9tX3Bvc3RfaWQiOm51bGwsInF1aXpfYW5pbWF0aW9uX3RvcCI6MTAwLCJxdWl6X2VuYWJsZV9hbmltYXRpb25fdG9wIjoib24ifQ==';\n        <\/script>\n                    <input type='hidden' name='quiz_id' value='46'\/>\n                    <input type='hidden' name='start_date' class='ays-start-date'\/>\n                <\/form><\/div>\n                            <\/div>\n                            \n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":8028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[282],"tags":[9,985,2203,2205,497,2208,2200,2209,2207,2206,2204,2201,2202],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts\/11617"}],"collection":[{"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/comments?post=11617"}],"version-history":[{"count":1,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts\/11617\/revisions"}],"predecessor-version":[{"id":11618,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts\/11617\/revisions\/11618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/media\/8028"}],"wp:attachment":[{"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/media?parent=11617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/categories?post=11617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/tags?post=11617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}