{"id":9296,"date":"2023-11-11T10:10:26","date_gmt":"2023-11-11T04:40:26","guid":{"rendered":"https:\/\/aiyoit.com\/tutorial\/?p=9296"},"modified":"2023-11-30T09:09:16","modified_gmt":"2023-11-30T03:39:16","slug":"upp-uttar-pradesh-police","status":"publish","type":"post","link":"https:\/\/aiyoit.com\/tutorial\/upp-uttar-pradesh-police\/","title":{"rendered":"UPP- (Uttar Pradesh Police)"},"content":{"rendered":"\n<p>Computer \u0938\u0947 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0935\u094b \u0938\u092d\u0940 Question \u091c\u094b \u092c\u0939\u0941\u0924 \u0939\u0940 \u092e\u0939\u0924\u094d\u0935\u092a\u0942\u0930\u094d\u0923 \u0939\u0948 \u0914\u0930 \u0938\u092d\u0940 \u092a\u094d\u0930\u0915\u093e\u0930 \u0915\u0940 \u092a\u094d\u0930\u0924\u093f\u092f\u094b\u0917\u0940 \u092a\u0930\u0940\u0915\u094d\u0937\u093e \u0915\u0947 \u0932\u093f\u092f\u0947 \u0909\u092a\u092f\u094b\u0917\u0940 \u0939\u0948\u0902\u0964 \u0938\u092d\u0940 \u092a\u094d\u0930\u0915\u093e\u0930 \u0915\u0940 \u092a\u094d\u0930\u0924\u093f\u092f\u094b\u0917\u0940 \u092a\u0930\u0940\u0915\u094d\u0937\u093e \u091c\u0948\u0938\u0947 SSC, IBPS Clerk, IBPS PO, RBI, TET, CTET,CCC,UPP etc. \u092e\u0947\u0902 \u092a\u0942\u091b\u0947 \u0917\u090f Computer \u0915\u093e Questions \u0915\u093e \u0938\u0902\u0917\u094d\u0930\u0939 \u0964<\/p>\n\n\n\n            <div class='ays-quiz-container ays_quiz_classic_light   ays-quiz-keyboard-active' data-quest-effect='none'  data-bg-gradient='linear-gradient(to bottom, rgba(165,104,226,0.26), #fff)'  data-hide-bg-image='false' id='ays-quiz-container-37'>\n                \n                \n                <div class='ays-questions-container'>\n                    <div class=\"ays-quiz-full-screen-wrap\">\n                <a class=\"ays-quiz-full-screen-container\">\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24\" fill=\"#fff\" viewBox=\"0 0 24 24\" width=\"24\" class=\"ays-quiz-close-full-screen\">\n                        <path d=\"M0 0h24v24H0z\" fill=\"none\"\/>\n                        <path d=\"M5 16h3v3h2v-5H5v2zm3-8H5v2h5V5H8v3zm6 11h2v-3h3v-2h-5v5zm2-11V5h-2v5h5V8h-3z\"\/>\n                    <\/svg>\n                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"24\" fill=\"#fff\" viewBox=\"0 0 24 24\" width=\"24\" class=\"ays-quiz-open-full-screen\">\n                        <path d=\"M0 0h24v24H0z\" fill=\"none\"\/>\n                        <path d=\"M7 14H5v5h5v-2H7v-3zm-2-4h2V7h3V5H5v5zm12 7h-3v2h5v-5h-2v3zM14 5v2h3v3h2V5h-5z\"\/>\n                    <\/svg>\n                <\/a>\n            <\/div>\n                    \n                    \n                    <form action='' method='post' id='ays_finish_quiz_37' \n                        class='ays-quiz-form  enable_questions_result '\n                    >\n            <input type='hidden' value='list' class='answer_view_class'>\n            <input type='hidden' value='' class='ays_qm_enable_arrows'><section  class='ays_quiz_timer_container'>\n                <div class='ays-quiz-timer ' data-timer='3000'><p>Do not waste your time on only one question<\/p>\n<\/div>\n                <div class='ays-quiz-after-timer  empty_after_timer_text '><\/div>\n                <hr style='height:1px;'>\n            <\/section>\n            \n            \n            <div class='step active-step'>\n                <div class='ays-abs-fs ays-start-page'>\n                    \n                    <img src='https:\/\/aiyoit.com\/tutorial\/wp-content\/uploads\/2022\/12\/cropped-Fave-Icon.png' alt='Test_1' class='ays_quiz_image'>\n                    <p class='ays-fs-title'>UPP<\/p>\n                    <div class='ays-fs-subtitle'><p>Hello friend, welcome to this computer quiz \u2013 AIYO IT ,You have 50 questions and 50 minutes for the whole questions, Hope you have come prepared beforehand, I wish you good luck, you will do well..<\/p>\n<\/div>\n                    <input type='hidden' name='ays_quiz_id' value='37'\/>\n                    <input type='hidden' name='ays_quiz_finish_nonce' value='f85f6be96a'>\n                    <input type='hidden' name='ays_quiz_curent_page_link' class='ays-quiz-curent-page-link' value='https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts\/9296'\/>\n                    <input type='hidden' name='ays_quiz_questions' value='748,747,746,745,744,742,743,741,740,739,738,737,736,735,734,733,732,731,730,729,728,727,726,725,724,723,722,721,720,719,718,717,716,715,714,713,712,710,711,709,708,707,706,705,704,703,702,701,700,644'>\n                    \n                    \n                    <input type='button'   class='ays_next start_button action-button ays-quiz-keyboard-active' value='Start' data-enable-leave-page=\"false\" \/>\n                    \n                    <\/div>\n                <\/div><div class='step'>\n                                    <div class='ays-abs-fs ays-start-page information_form'>\n                                    <div class='ays-form-title'><p>Please fill your required* information<\/p>\n<\/div>\n                                        <input type='text' id='ays_form_field_user_name_37' name='ays_user_name' placeholder='Name' class='ays_quiz_form_input ays_animated_x5ms' required><input type='text' id='ays_form_field_user_email_37' name='ays_user_email' placeholder='Email' class='ays_quiz_form_input ays_animated_x5ms' ><input type='text' id='ays_form_field_user_phone_37' name='ays_user_phone' placeholder='Phone Number' class='ays_quiz_form_input ays_animated_x5ms' required>\n                                        <div class='ays_buttons_div'>\n                                            <i class='ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none'><\/i>\n                                            <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                                        <\/div>\n                                    <\/div>\n                                  <\/div><div class='step ' data-question-id='728' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>1 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>1. 3\/7, 2\/9, 4\/13, 6\/11, 7\/9 \u092e\u0947 \u0938\u0947 \u0938\u092c\u0938\u0947 \u092c\u095c\u0940 \u092d\u093f\u0928\u094d\u0928 \u0915\u094c\u0928 \u0938\u0940 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-728]' id='ays-answer-2728-37' value='2728'\/>\n\n                <label for='ays-answer-2728-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 3\/7<\/label><label for='ays-answer-2728-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-728]' id='ays-answer-2729-37' value='2729'\/>\n\n                <label for='ays-answer-2729-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 4\/13<\/label><label for='ays-answer-2729-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-728]' id='ays-answer-2730-37' value='2730'\/>\n\n                <label for='ays-answer-2730-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 7\/9<\/label><label for='ays-answer-2730-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-728]' id='ays-answer-2731-37' value='2731'\/>\n\n                <label for='ays-answer-2731-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 6\/11<\/label><label for='ays-answer-2731-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['728'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='720' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>2 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>2. \u091c\u0939\u093e\u091c \u091c\u0948\u0938\u0947 \u0915\u092a\u094d\u0924\u093e\u0928 \u0938\u0947 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0939\u0948 | \u0935\u0948\u0938\u0947 \u0939\u0940 \u0905\u0915\u092c\u093e\u0930 \u0915\u093f\u0938 \u0938\u0947 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0939\u0948 |<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-720]' id='ays-answer-2696-37' value='2696'\/>\n\n                <label for='ays-answer-2696-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092a\u093e\u0920\u0915<\/label><label for='ays-answer-2696-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-720]' id='ays-answer-2697-37' value='2697'\/>\n\n                <label for='ays-answer-2697-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092e\u0941\u0926\u094d\u0930\u0915<\/label><label for='ays-answer-2697-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-720]' id='ays-answer-2698-37' value='2698'\/>\n\n                <label for='ays-answer-2698-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u092a\u094d\u0930\u0915\u093e\u0938\u0928<\/label><label for='ays-answer-2698-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-720]' id='ays-answer-2699-37' value='2699'\/>\n\n                <label for='ays-answer-2699-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0938\u092e\u094d\u092a\u093e\u0926\u0915<\/label><label for='ays-answer-2699-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['720'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='706' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>3 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>3. \u0915\u093f\u0938\u0940 \u0935\u094d\u092f\u0915\u094d\u0924\u093f \u0915\u0940 \u0905\u0935\u0948\u0927 \u0939\u093f\u0930\u093e\u0938\u0924 \u0915\u0947 \u0916\u093f\u0932\u093e\u092b \u0928\u093f\u092e\u094d\u0928 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928-\u0938\u0940 \u0930\u0940\u0924 \u0932\u093e\u0917\u0942 \u0939\u094b\u0917\u0940 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-706]' id='ays-answer-2639-37' value='2639'\/>\n\n                <label for='ays-answer-2639-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092c\u0902\u0926\u0940 \u092a\u094d\u0930\u0924\u094d\u092f\u0915\u094d\u0937\u0940\u0915\u0930\u0923 ( Habeas corpus )<\/label><label for='ays-answer-2639-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-706]' id='ays-answer-2640-37' value='2640'\/>\n\n                <label for='ays-answer-2640-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092a\u0930\u092e\u093e\u0926\u0947\u0936 ( Mandamus )<\/label><label for='ays-answer-2640-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-706]' id='ays-answer-2641-37' value='2641'\/>\n\n                <label for='ays-answer-2641-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0909\u0924\u094d\u0924\u092a\u094d\u0930\u0947\u0937\u0923- \u0932\u0947\u0916 ( Certiorari )<\/label><label for='ays-answer-2641-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-706]' id='ays-answer-2642-37' value='2642'\/>\n\n                <label for='ays-answer-2642-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0905\u0927\u093f\u0915\u093e\u0930 \u092a\u0943\u091a\u094d\u091b\u093e ( Quo warranto )<\/label><label for='ays-answer-2642-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['706'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='721' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>4 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>4. \u0928\u093f\u092e\u094d\u0928 \u092a\u094d\u0930\u0936\u094d\u0928\u094b\u0902 \u092e\u0947 \u0926\u093f\u090f \u0917\u090f \u0935\u093f\u0915\u0932\u094d\u092a\u094b\u0902 \u092e\u0947 \u0938\u0947 \u0935\u093f\u0937\u092e \u0905\u0915\u094d\u0937\u0930 | \u0938\u0902\u0916\u094d\u092f\u093e \u0936\u092c\u094d\u0926 \u091a\u0941\u0928\u093f\u092f\u0947 |<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-721]' id='ays-answer-2700-37' value='2700'\/>\n\n                <label for='ays-answer-2700-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092a\u094d\u0932\u0947\u091f\u094b\u0902<\/label><label for='ays-answer-2700-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-721]' id='ays-answer-2701-37' value='2701'\/>\n\n                <label for='ays-answer-2701-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u094d\u091f\u093e\u0930<\/label><label for='ays-answer-2701-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-721]' id='ays-answer-2702-37' value='2702'\/>\n\n                <label for='ays-answer-2702-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u092e\u093e\u0909\u0902\u091f\u0947\u0928<\/label><label for='ays-answer-2702-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-721]' id='ays-answer-2703-37' value='2703'\/>\n\n                <label for='ays-answer-2703-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092b\u0949\u0930\u0947\u0938\u094d\u091f<\/label><label for='ays-answer-2703-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['721'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='734' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>5 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>5. <\/p>\n\n                            <\/div>\n                            <div class=\"ays-image-question-img\"><img src=\"http:\/\/aiyoit.com\/tutorial\/wp-content\/uploads\/2023\/11\/Math5-300x74.png\"   alt=\"Math Question\" style='width:100%;height:auto;object-fit:cover;border-radius:0px;object-position:center center;' class=\" ays-quiz-keyboard-active\" tabindex='0'><\/div>\n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-734]' id='ays-answer-2752-37' value='2752'\/>\n\n                <label for='ays-answer-2752-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 226<\/label><label for='ays-answer-2752-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-734]' id='ays-answer-2753-37' value='2753'\/>\n\n                <label for='ays-answer-2753-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 328<\/label><label for='ays-answer-2753-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-734]' id='ays-answer-2754-37' value='2754'\/>\n\n                <label for='ays-answer-2754-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 322<\/label><label for='ays-answer-2754-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-734]' id='ays-answer-2755-37' value='2755'\/>\n\n                <label for='ays-answer-2755-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 324<\/label><label for='ays-answer-2755-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['734'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='715' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>6 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>6. \u092e\u094c\u0932\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930\u0940 \u090f\u0935\u0902 \u0930\u093e\u091c\u094d\u092f \u0915\u0947 \u0928\u0940\u0924\u093f \u2013 \u0928\u093f\u0926\u0947\u0936\u0915 \u0924\u0924\u094d\u0935\u094b\u0902 \u0915\u0947 \u0935\u093f\u0937\u092f \u092e\u0947 \u0915\u094c\u0928 \u2013 \u0938\u093e \u0915\u0925\u0928 \u0938\u0939\u0940 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-715]' id='ays-answer-2675-37' value='2675'\/>\n\n                <label for='ays-answer-2675-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0935\u0947 \u092a\u0930\u0938\u094d\u092a\u0930 \u0935\u093f\u0930\u094b\u0927\u0940 \u0939\u0948<\/label><label for='ays-answer-2675-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-715]' id='ays-answer-2676-37' value='2676'\/>\n\n                <label for='ays-answer-2676-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0935\u0947 \u090f\u0915 - \u0926\u0942\u0938\u0930\u0947 \u0915\u0947 \u092a\u0942\u0930\u0915 \u0939\u0948<\/label><label for='ays-answer-2676-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-715]' id='ays-answer-2677-37' value='2677'\/>\n\n                <label for='ays-answer-2677-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0926\u094b\u0928\u094b\u0902 \u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0905\u0902\u0924\u0930 \u0928\u0939\u0940\u0902 \u0939\u0948<\/label><label for='ays-answer-2677-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-715]' id='ays-answer-2678-37' value='2678'\/>\n\n                <label for='ays-answer-2678-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0935\u0947 \u0905\u0938\u092e\u093e\u0928\u094d\u092f \u0939\u0948<\/label><label for='ays-answer-2678-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-715]' id='ays-answer-2679-37' value='2679'\/>\n\n                <label for='ays-answer-2679-37' class='  ays_position_initial  ays-quiz-keyboard-label'>e. \u0909\u092a\u092f\u0941\u0915\u094d\u0924 \u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902 | \u0909\u092a\u092f\u0941\u0915\u094d\u0924 \u092e\u0947 \u0938\u0947 \u090f\u0915 \u0938\u0947 \u0905\u0927\u093f\u0915<\/label><label for='ays-answer-2679-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['715'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='718' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>7 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>7. \u0938\u0902\u0935\u093f\u0927\u093e\u0928 \u092e\u0947 \u092e\u094c\u0932\u093f\u0915 \u0915\u0930\u094d\u0924\u0935\u094d\u092f\u094b\u0902 \u0915\u094b \u0915\u092c \u0938\u092e\u094d\u092e\u093f\u0932\u093f\u0924 \u0915\u093f\u092f\u093e \u0917\u092f\u093e ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-718]' id='ays-answer-2688-37' value='2688'\/>\n\n                <label for='ays-answer-2688-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1975 \u092e\u0947<\/label><label for='ays-answer-2688-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-718]' id='ays-answer-2689-37' value='2689'\/>\n\n                <label for='ays-answer-2689-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1976 \u092e\u0947<\/label><label for='ays-answer-2689-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-718]' id='ays-answer-2690-37' value='2690'\/>\n\n                <label for='ays-answer-2690-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 1978 \u092e\u0947<\/label><label for='ays-answer-2690-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-718]' id='ays-answer-2691-37' value='2691'\/>\n\n                <label for='ays-answer-2691-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 1979 \u092e\u0947<\/label><label for='ays-answer-2691-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['718'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='702' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>8 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>8. \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928-\u0938\u093e \u092e\u0942\u0932\u092d\u0942\u0924 \u0905\u0927\u093f\u0915\u093e\u0930 \u0928\u0939\u0940\u0902 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-702]' id='ays-answer-2623-37' value='2623'\/>\n\n                <label for='ays-answer-2623-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0938\u0902\u0935\u0948\u0927\u093e\u0928\u093f\u0915 \u092a\u094d\u0930\u0924\u093f\u0915\u093e\u0930 \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2623-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-702]' id='ays-answer-2624-37' value='2624'\/>\n\n                <label for='ays-answer-2624-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u0902\u092a\u0924\u094d\u0924\u093f \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2624-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-702]' id='ays-answer-2625-37' value='2625'\/>\n\n                <label for='ays-answer-2625-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0936\u093e\u0902\u0924\u093f\u092a\u0942\u0930\u094d\u0935\u0915 \u090f\u0915\u0924\u094d\u0930 \u0939\u094b\u0928\u0947 \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2625-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-702]' id='ays-answer-2626-37' value='2626'\/>\n\n                <label for='ays-answer-2626-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0926\u0947\u0936 \u092d\u0930 \u092e\u0947\u0902 \u0906\u091c\u093e\u0926\u0940 \u0915\u0947 \u0938\u093e\u0925 \u0906\u0928\u0947-\u091c\u093e\u0928\u0947 \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2626-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['702'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='739' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>9 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>9. \u092d\u093e\u0930\u0924 \u0915\u0947 \u0938\u0935\u093f\u0927\u093e\u0928 \u0915\u093e \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928-\u0938\u093e \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 \u092a\u094d\u0930\u0947\u0938 \u0915\u0940 \u0938\u094d\u0935\u0924\u0902\u0924\u094d\u0930\u0924\u093e \u0938\u0947 \u0938\u0902\u092c\u0927\u093f\u0924 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-739]' id='ays-answer-2772-37' value='2772'\/>\n\n                <label for='ays-answer-2772-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-19<\/label><label for='ays-answer-2772-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-739]' id='ays-answer-2773-37' value='2773'\/>\n\n                <label for='ays-answer-2773-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-20<\/label><label for='ays-answer-2773-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-739]' id='ays-answer-2774-37' value='2774'\/>\n\n                <label for='ays-answer-2774-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-21<\/label><label for='ays-answer-2774-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-739]' id='ays-answer-2775-37' value='2775'\/>\n\n                <label for='ays-answer-2775-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-22<\/label><label for='ays-answer-2775-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['739'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='726' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>10 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>10. \u092f\u0926\u093f \u0926\u094b \u0938\u0902\u0916\u094d\u092f\u093e\u0913 \u0915\u093e \u0905\u0928\u0941\u092a\u093e\u0924 3:2 \u0939\u0948 \u0924\u0925\u093e \u0909\u0928\u0915\u093e LCM ,42 \u0939\u0948 \u0924\u094b \u092c\u095c\u0940 \u0938\u0902\u0916\u094d\u092f\u093e ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-726]' id='ays-answer-2720-37' value='2720'\/>\n\n                <label for='ays-answer-2720-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 27<\/label><label for='ays-answer-2720-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-726]' id='ays-answer-2721-37' value='2721'\/>\n\n                <label for='ays-answer-2721-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 23<\/label><label for='ays-answer-2721-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-726]' id='ays-answer-2722-37' value='2722'\/>\n\n                <label for='ays-answer-2722-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 24<\/label><label for='ays-answer-2722-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-726]' id='ays-answer-2723-37' value='2723'\/>\n\n                <label for='ays-answer-2723-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 21<\/label><label for='ays-answer-2723-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['726'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='742' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>11 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>11. \u090f\u0915 \u0924\u0938\u094d\u0935\u0940\u0930 \u0915\u0940 \u0913\u0930 \u0907\u0936\u093e\u0930\u093e \u0915\u0930\u0924\u0947 \u0939\u0941\u090f , \u092a\u094d\u0930\u092d\u093e\u0924 \u0928\u0947\u0939\u093e \u0938\u0947 \u092c\u094b\u0932\u093e , \u201c \u0909\u0938\u0915\u0940 \u092a\u094b\u0924\u0940 \u0936\u0940\u0932\u093e , \u092e\u0947\u0930\u0940 \u092d\u0924\u0940\u091c\u0940 \u0939\u0948 |\u201d \u0924\u094b \u0935\u0939 \u0914\u0930\u0924 , \u091c\u093f\u0938\u0915\u0940 \u0924\u0938\u094d\u0935\u0940\u0930 \u0939\u0948 , \u092a\u094d\u0930\u092d\u093e\u0924 \u0938\u0947 \u0915\u093f\u0938 \u092a\u094d\u0930\u0915\u093e\u0930 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-742]' id='ays-answer-2784-37' value='2784'\/>\n\n                <label for='ays-answer-2784-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0938\u093e\u0938<\/label><label for='ays-answer-2784-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-742]' id='ays-answer-2785-37' value='2785'\/>\n\n                <label for='ays-answer-2785-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u091a\u093e\u091a\u0940<\/label><label for='ays-answer-2785-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-742]' id='ays-answer-2786-37' value='2786'\/>\n\n                <label for='ays-answer-2786-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0938\u093e\u0932\u0940<\/label><label for='ays-answer-2786-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-742]' id='ays-answer-2787-37' value='2787'\/>\n\n                <label for='ays-answer-2787-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0907\u0928\u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940<\/label><label for='ays-answer-2787-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['742'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='735' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>12 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>12. 4 \u0915\u0948\u092e\u0930\u094b\u0902 \u0924\u0925\u093e 6 \u0938\u0947\u0932\u092b\u094b\u0928\u094b\u0902 \u0915\u093e \u092e\u0942\u0932\u094d\u092f \u20b9 51365 \u0939\u0948 , \u0924\u094b 12 \u0915\u0948\u092e\u0930\u094b\u0902 \u0924\u0925\u093e 18 \u0938\u0947\u0932\u092b\u094b\u0928\u094b\u0902 \u0915\u093e \u092e\u0942\u0932\u094d\u092f \u0915\u093f\u0924\u0928\u093e \u0939\u094b\u0917\u093e ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-735]' id='ays-answer-2756-37' value='2756'\/>\n\n                <label for='ays-answer-2756-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 150791<\/label><label for='ays-answer-2756-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-735]' id='ays-answer-2757-37' value='2757'\/>\n\n                <label for='ays-answer-2757-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 154095<\/label><label for='ays-answer-2757-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-735]' id='ays-answer-2758-37' value='2758'\/>\n\n                <label for='ays-answer-2758-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 164091<\/label><label for='ays-answer-2758-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-735]' id='ays-answer-2759-37' value='2759'\/>\n\n                <label for='ays-answer-2759-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 134095<\/label><label for='ays-answer-2759-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['735'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='717' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>13 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>13. \u092e\u094c\u0932\u093f\u0915 \u0915\u0930\u094d\u0924\u0935\u094d\u092f\u094b\u0902 \u0915\u094b \u0928\u093f\u0930\u094d\u0927\u093e\u0930\u093f\u0924 \u0915\u093f\u092f\u093e \u0917\u092f\u093e \u2013<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-717]' id='ays-answer-2684-37' value='2684'\/>\n\n                <label for='ays-answer-2684-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 40 \u0935\u0947 \u0938\u0902\u0936\u094b\u0927\u0928 \u0926\u094d\u0935\u093e\u0930\u093e<\/label><label for='ays-answer-2684-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-717]' id='ays-answer-2685-37' value='2685'\/>\n\n                <label for='ays-answer-2685-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 43 \u0935\u0947 \u0938\u0902\u0936\u094b\u0927\u0928 \u0926\u094d\u0935\u093e\u0930\u093e<\/label><label for='ays-answer-2685-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-717]' id='ays-answer-2686-37' value='2686'\/>\n\n                <label for='ays-answer-2686-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 42 \u0935\u0947 \u0938\u0902\u0936\u094b\u0927\u0928 \u0926\u094d\u0935\u093e\u0930\u093e<\/label><label for='ays-answer-2686-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-717]' id='ays-answer-2687-37' value='2687'\/>\n\n                <label for='ays-answer-2687-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 39 \u0935\u0947 \u0938\u0902\u0936\u094b\u0927\u0928 \u0926\u094d\u0935\u093e\u0930\u093e<\/label><label for='ays-answer-2687-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['717'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='700' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>14 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>14. \u092d\u093e\u0930\u0924 \u0915\u0947 \u0938\u0935\u093f\u0927\u093e\u0928 \u0915\u093e \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928-\u0938\u093e \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 \u092a\u094d\u0930\u0947\u0938 \u0915\u0940 \u0938\u094d\u0935\u0924\u0902\u0924\u094d\u0930\u0924\u093e \u0938\u0947 \u0938\u0902\u092c\u0927\u093f\u0924 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-700]' id='ays-answer-2615-37' value='2615'\/>\n\n                <label for='ays-answer-2615-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-19<\/label><label for='ays-answer-2615-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-700]' id='ays-answer-2616-37' value='2616'\/>\n\n                <label for='ays-answer-2616-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-20<\/label><label for='ays-answer-2616-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-700]' id='ays-answer-2617-37' value='2617'\/>\n\n                <label for='ays-answer-2617-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-21<\/label><label for='ays-answer-2617-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-700]' id='ays-answer-2618-37' value='2618'\/>\n\n                <label for='ays-answer-2618-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-22<\/label><label for='ays-answer-2618-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['700'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='744' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>15 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>15. \u092f\u0926\u093f \u2013 \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 \u00d7 , \u00d7 \u0915\u093e \u0905\u0930\u094d\u0925 + ,+ \u0915\u093e \u0905\u0930\u094d\u0925 \u00f7 \u0914\u0930 \u00f7 \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 \u2013 \u0924\u094b 40\u00a0 \u00d7 12 + 3 - 6 \u00f7 60 = ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-744]' id='ays-answer-2792-37' value='2792'\/>\n\n                <label for='ays-answer-2792-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 44<\/label><label for='ays-answer-2792-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-744]' id='ays-answer-2793-37' value='2793'\/>\n\n                <label for='ays-answer-2793-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 16<\/label><label for='ays-answer-2793-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-744]' id='ays-answer-2794-37' value='2794'\/>\n\n                <label for='ays-answer-2794-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 7.95<\/label><label for='ays-answer-2794-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-744]' id='ays-answer-2795-37' value='2795'\/>\n\n                <label for='ays-answer-2795-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 4<\/label><label for='ays-answer-2795-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['744'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='709' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>16 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>16. \u092d\u093e\u0930\u0924\u0940\u092f \u0938\u0935\u093f\u0927\u093e\u0928 \u0915\u0947 \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-17 \u0915\u093e \u0938\u092e\u094d\u092c\u0926\u094d\u0927 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-709]' id='ays-answer-2651-37' value='2651'\/>\n\n                <label for='ays-answer-2651-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0936\u093f\u0915\u094d\u0937\u093e \u0938\u0947<\/label><label for='ays-answer-2651-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-709]' id='ays-answer-2652-37' value='2652'\/>\n\n                <label for='ays-answer-2652-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u094d\u0935\u093e\u0938\u094d\u0925\u094d\u092f<\/label><label for='ays-answer-2652-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-709]' id='ays-answer-2653-37' value='2653'\/>\n\n                <label for='ays-answer-2653-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0938\u094d\u092a\u0943\u0936\u094d\u092f\u0924\u093e \u0909\u0928\u094d\u092e\u0942\u0932\u0928 \u0938\u0947<\/label><label for='ays-answer-2653-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-709]' id='ays-answer-2654-37' value='2654'\/>\n\n                <label for='ays-answer-2654-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0916\u093e\u0918 \u0938\u0941\u0930\u0915\u094d\u0937\u093e<\/label><label for='ays-answer-2654-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['709'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='703' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>17 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>17. \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u093f\u0938\u0947 \u092d\u093e\u0930\u0924\u0940\u092f \u0938\u0935\u093f\u0927\u093e\u0928 \u0915\u0940 \u0906\u0924\u094d\u092e\u093e \u0915\u0939\u093e \u091c\u093e\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-703]' id='ays-answer-2627-37' value='2627'\/>\n\n                <label for='ays-answer-2627-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092e\u094c\u0932\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2627-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-703]' id='ays-answer-2628-37' value='2628'\/>\n\n                <label for='ays-answer-2628-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0930\u093e\u091c\u094d\u092f \u0915\u0947 \u0928\u0940\u0924\u093f \u0928\u093f\u0926\u0947\u0936\u0915 \u0938\u093f\u0926\u094d\u0927\u093e\u0902\u0924<\/label><label for='ays-answer-2628-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-703]' id='ays-answer-2629-37' value='2629'\/>\n\n                <label for='ays-answer-2629-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0938\u0935\u093f\u0927\u093e\u0928 \u0915\u0940 \u092a\u094d\u0930\u0938\u094d\u0924\u093e\u0935\u0928\u093e<\/label><label for='ays-answer-2629-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-703]' id='ays-answer-2630-37' value='2630'\/>\n\n                <label for='ays-answer-2630-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0938\u0902\u0935\u0948\u0927\u093e\u0928\u093f\u0915 \u0909\u092a\u091a\u093e\u0930\u094b\u0902 \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2630-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['703'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='745' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>18 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>18. \u2018\u092e\u091b\u0932\u0940\u2019 \u091c\u0948\u0938\u0947 \u2018\u091c\u0932\u2019 \u0938\u0947 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0939\u0948 \u0935\u0948\u0938\u0947 \u0939\u0940 \u2018\u091a\u093f\u095c\u093f\u092f\u093e\u2019 \u0915\u093f\u0938\u0938\u0947 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-745]' id='ays-answer-2796-37' value='2796'\/>\n\n                <label for='ays-answer-2796-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u091c\u0932<\/label><label for='ays-answer-2796-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-745]' id='ays-answer-2797-37' value='2797'\/>\n\n                <label for='ays-answer-2797-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092d\u094b\u091c\u0928<\/label><label for='ays-answer-2797-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-745]' id='ays-answer-2798-37' value='2798'\/>\n\n                <label for='ays-answer-2798-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0906\u0915\u093e\u0936<\/label><label for='ays-answer-2798-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-745]' id='ays-answer-2799-37' value='2799'\/>\n\n                <label for='ays-answer-2799-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0935\u093e\u092f\u0941<\/label><label for='ays-answer-2799-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['745'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='713' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>19 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>19. \u090f\u0915 \u0915\u0932\u094d\u092f\u093e\u0923\u0915\u093e\u0930\u0940 \u0930\u093e\u091c\u094d\u092f \u0915\u0947 \u0928\u093f\u0930\u094d\u0926\u0947\u0936\u0915 \u0906\u0926\u0930\u094d\u0936 \u0935\u093e\u0923\u093f\u0924 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-713]' id='ays-answer-2667-37' value='2667'\/>\n\n                <label for='ays-answer-2667-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0930\u093e\u091c\u094d\u092f \u0915\u0940 \u0928\u0940\u0924\u093f \u0928\u093f\u0930\u094d\u0926\u0947\u0936\u0915 \u0924\u0924\u094d\u0935\u094b\u0902 \u092e\u0947\u0902<\/label><label for='ays-answer-2667-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-713]' id='ays-answer-2668-37' value='2668'\/>\n\n                <label for='ays-answer-2668-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092e\u094c\u0932\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930\u094b\u0902 \u0915\u0947 \u0905\u0927\u094d\u092f\u092f\u0928 \u092e\u0947\u0902<\/label><label for='ays-answer-2668-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-713]' id='ays-answer-2669-37' value='2669'\/>\n\n                <label for='ays-answer-2669-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0938\u0902\u0935\u093f\u0927\u093e\u0928  \u0915\u0940 \u0938\u093e\u0924\u0935\u0940 \u0905\u0928\u0941\u0938\u0942\u091a\u0940 \u092e\u0947\u0902<\/label><label for='ays-answer-2669-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-713]' id='ays-answer-2670-37' value='2670'\/>\n\n                <label for='ays-answer-2670-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0915\u093f\u0938\u0940 \u092d\u0940 \u0930\u093e\u091c\u094d\u092f \u0915\u0947 \u0915\u093e\u0928\u0942\u0928 \u0915\u094b \u0905\u0935\u0948\u0927 \u0918\u094b\u0937\u093f\u0924 \u0915\u0930 \u0938\u0915\u0924\u093e \u0939\u0948\u0964<\/label><label for='ays-answer-2670-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['713'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='740' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>20 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>20. \u091c\u0939\u093e\u091c \u091c\u0948\u0938\u0947 \u0915\u092a\u094d\u0924\u093e\u0928 \u0938\u0947 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0939\u0948 | \u0935\u0948\u0938\u0947 \u0939\u0940 \u0905\u0916\u092c\u093e\u0930 \u0915\u093f\u0938 \u0938\u0947 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0939\u0948 |<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-740]' id='ays-answer-2776-37' value='2776'\/>\n\n                <label for='ays-answer-2776-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092a\u093e\u0920\u0915<\/label><label for='ays-answer-2776-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-740]' id='ays-answer-2777-37' value='2777'\/>\n\n                <label for='ays-answer-2777-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u092e\u0941\u0926\u094d\u0930\u0915<\/label><label for='ays-answer-2777-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-740]' id='ays-answer-2778-37' value='2778'\/>\n\n                <label for='ays-answer-2778-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u092a\u094d\u0930\u0915\u093e\u0938\u0928<\/label><label for='ays-answer-2778-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-740]' id='ays-answer-2779-37' value='2779'\/>\n\n                <label for='ays-answer-2779-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0938\u092e\u094d\u092a\u093e\u0926\u0915<\/label><label for='ays-answer-2779-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['740'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='710' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>21 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>21. \u092e\u0942\u0932 \u0905\u0927\u093f\u0915\u093e\u0930 \u0915\u094d\u092f\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-710]' id='ays-answer-2655-37' value='2655'\/>\n\n                <label for='ays-answer-2655-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0935\u093e\u0926 \u092f\u094b\u0917\u094d\u092f<\/label><label for='ays-answer-2655-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-710]' id='ays-answer-2656-37' value='2656'\/>\n\n                <label for='ays-answer-2656-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0935\u093e\u0926 \u092f\u094b\u0917\u094d\u092f \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-2656-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-710]' id='ays-answer-2657-37' value='2657'\/>\n\n                <label for='ays-answer-2657-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0932\u091a\u0940\u0932\u0947<\/label><label for='ays-answer-2657-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-710]' id='ays-answer-2658-37' value='2658'\/>\n\n                <label for='ays-answer-2658-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0915\u0920\u094b\u0930<\/label><label for='ays-answer-2658-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['710'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='737' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>22 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>22. 31 \u092e\u0948\u091a\u094b\u0902 \u092e\u0947 \u0927\u094b\u0928\u0940 \u0915\u093e \u0914\u0938\u0924 31 \u0930\u0928 \u0939\u0948 | \u0905\u092a\u0928\u0947 \u0914\u0938\u0924 \u092e\u0947 \u0926\u094b \u0930\u0928\u094b\u0902 \u0915\u0940 \u0935\u0943\u0926\u094d\u0927\u093f \u0915\u0947 \u0932\u093f\u090f \u0909\u0938\u0947 \u0905\u0917\u0932\u0947 \u092e\u0948\u091a \u092e\u0947 \u0915\u093f\u0924\u0928\u0947 \u0930\u0928 \u092c\u0928\u093e\u0928\u0947 \u0939\u094b\u0902\u0917\u0947 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-737]' id='ays-answer-2764-37' value='2764'\/>\n\n                <label for='ays-answer-2764-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 101<\/label><label for='ays-answer-2764-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-737]' id='ays-answer-2765-37' value='2765'\/>\n\n                <label for='ays-answer-2765-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 95<\/label><label for='ays-answer-2765-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-737]' id='ays-answer-2766-37' value='2766'\/>\n\n                <label for='ays-answer-2766-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 92<\/label><label for='ays-answer-2766-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-737]' id='ays-answer-2767-37' value='2767'\/>\n\n                <label for='ays-answer-2767-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 98<\/label><label for='ays-answer-2767-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['737'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='707' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>23 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>23. \u092e\u094c\u0932\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930\u094b\u0902 \u0915\u0940 \u092e\u0942\u0932 \u0938\u0942\u091a\u0940 \u092e\u0947\u0902 \u0938\u0947 \u0915\u093f\u0938\u0947 \u091c\u094b\u095c\u093e \u0917\u092f\u093e ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-707]' id='ays-answer-2643-37' value='2643'\/>\n\n                <label for='ays-answer-2643-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0938\u0902\u092a\u0924\u094d\u0924\u093f \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2643-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-707]' id='ays-answer-2644-37' value='2644'\/>\n\n                <label for='ays-answer-2644-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u0902\u0935\u0948\u0927\u093e\u0928\u093f\u0915 \u0909\u092a\u091a\u093e\u0930\u094b\u0902 \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2644-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-707]' id='ays-answer-2645-37' value='2645'\/>\n\n                <label for='ays-answer-2645-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0927\u093e\u0930\u094d\u092e\u093f\u0915 \u0938\u094d\u0935\u0924\u0902\u0924\u094d\u0930\u0924\u093e \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2645-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-707]' id='ays-answer-2646-37' value='2646'\/>\n\n                <label for='ays-answer-2646-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0928\u093f:\u0936\u0941\u0932\u094d\u0915 \u090f\u0935\u0902 \u0905\u0928\u093f\u0935\u093e\u0930\u094d\u092f \u092a\u094d\u0930\u093e\u0925\u093e\u092e\u093f\u0915 \u0936\u093f\u0915\u094d\u0937\u093e \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2646-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['707'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='725' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>24 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>24. \u092f\u0926\u093f \u0926\u094b \u0938\u0902\u0916\u094d\u092f\u093e\u0913 \u0915\u093e \u0905\u0928\u0941\u092a\u093e\u0924 4:5 \u0939\u0948 \u0924\u0925\u093e \u0909\u0928\u0915\u093e HCF ,8 \u0939\u0948 \u0924\u094b \u092c\u095c\u0940 \u0938\u0902\u0916\u094d\u092f\u093e \u091c\u094d\u091e\u093e\u0924 \u0915\u0940\u091c\u093f\u090f<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-725]' id='ays-answer-2716-37' value='2716'\/>\n\n                <label for='ays-answer-2716-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 32<\/label><label for='ays-answer-2716-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-725]' id='ays-answer-2717-37' value='2717'\/>\n\n                <label for='ays-answer-2717-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 48<\/label><label for='ays-answer-2717-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-725]' id='ays-answer-2718-37' value='2718'\/>\n\n                <label for='ays-answer-2718-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 40<\/label><label for='ays-answer-2718-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-725]' id='ays-answer-2719-37' value='2719'\/>\n\n                <label for='ays-answer-2719-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 60<\/label><label for='ays-answer-2719-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['725'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='729' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>25 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>25. 18.484848 . . . . . . . . \u0915\u094b p\/q \u0915\u0947 \u0930\u0942\u092a \u092e\u0947 \u0928\u093f\u0930\u0942\u092a\u093f\u0924 \u0915\u0930\u0928\u0947 \u092a\u0930 \u0932\u093f\u0916\u0947\u0902\u0917\u0947 |<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-729]' id='ays-answer-2732-37' value='2732'\/>\n\n                <label for='ays-answer-2732-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 462\/25<\/label><label for='ays-answer-2732-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-729]' id='ays-answer-2733-37' value='2733'\/>\n\n                <label for='ays-answer-2733-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 610\/33<\/label><label for='ays-answer-2733-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-729]' id='ays-answer-2734-37' value='2734'\/>\n\n                <label for='ays-answer-2734-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 200\/11<\/label><label for='ays-answer-2734-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-729]' id='ays-answer-2735-37' value='2735'\/>\n\n                <label for='ays-answer-2735-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 600\/33<\/label><label for='ays-answer-2735-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['729'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='730' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>26 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>26. <\/p>\n\n                            <\/div>\n                            <div class=\"ays-image-question-img\"><img src=\"http:\/\/aiyoit.com\/tutorial\/wp-content\/uploads\/2023\/11\/Math1.png\"   alt=\"Math\" style='width:100%;height:auto;object-fit:cover;border-radius:0px;object-position:center center;' class=\" ays-quiz-keyboard-active\" tabindex='0'><\/div>\n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-730]' id='ays-answer-2736-37' value='2736'\/>\n\n                <label for='ays-answer-2736-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1010<\/label><label for='ays-answer-2736-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-730]' id='ays-answer-2737-37' value='2737'\/>\n\n                <label for='ays-answer-2737-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 110<\/label><label for='ays-answer-2737-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-730]' id='ays-answer-2738-37' value='2738'\/>\n\n                <label for='ays-answer-2738-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 101<\/label><label for='ays-answer-2738-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-730]' id='ays-answer-2739-37' value='2739'\/>\n\n                <label for='ays-answer-2739-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 100<\/label><label for='ays-answer-2739-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['730'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='701' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>27 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>27. \u092d\u093e\u0930\u0924\u0940\u092f \u0938\u0935\u093f\u0927\u093e\u0928 \u092e\u0947\u0902 \u0915\u093f\u0938 \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 \u0915\u0947 \u0905\u0902\u0924\u0930\u094d\u0917\u0924 \u0928\u093e\u0917\u0930\u093f\u0915\u094b\u0902 \u0915\u094b \u092e\u094c\u0932\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930 \u092a\u094d\u0930\u0926\u093e\u0928 \u0915\u093f\u092f\u0947 \u0917\u090f \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-701]' id='ays-answer-2619-37' value='2619'\/>\n\n                <label for='ays-answer-2619-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-112 \u0938\u0947 135<\/label><label for='ays-answer-2619-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-701]' id='ays-answer-2620-37' value='2620'\/>\n\n                <label for='ays-answer-2620-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-12 \u0938\u0947 35<\/label><label for='ays-answer-2620-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-701]' id='ays-answer-2621-37' value='2621'\/>\n\n                <label for='ays-answer-2621-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-222 \u0938\u0947 235<\/label><label for='ays-answer-2621-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-701]' id='ays-answer-2622-37' value='2622'\/>\n\n                <label for='ays-answer-2622-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-22 \u0938\u0947 35<\/label><label for='ays-answer-2622-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['701'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='711' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>28 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>28. \u092d\u093e\u0930\u0924\u0940\u092f \u0938\u0935\u093f\u0927\u093e\u0928 \u0915\u093e \u0915\u094c\u0928 \u0938\u093e \u092d\u093e\u0917 \u0930\u093e\u091c\u094d\u092f \u0915\u0947 \u0932\u093f\u092f\u0947 \u0928\u0940\u0924\u093f - \u0928\u093f\u0926\u0947\u0936\u093f\u0924 \u0915\u0930\u0928\u0947 \u0935\u093e\u0932\u0947 \u0924\u0924\u094d\u0924\u094d\u0935\u094b\u0902 \u0915\u093e \u0909\u0932\u094d\u0932\u0947\u0916 \u0915\u0930\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-711]' id='ays-answer-2659-37' value='2659'\/>\n\n                <label for='ays-answer-2659-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. I<\/label><label for='ays-answer-2659-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-711]' id='ays-answer-2660-37' value='2660'\/>\n\n                <label for='ays-answer-2660-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. II<\/label><label for='ays-answer-2660-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-711]' id='ays-answer-2661-37' value='2661'\/>\n\n                <label for='ays-answer-2661-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. III<\/label><label for='ays-answer-2661-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-711]' id='ays-answer-2662-37' value='2662'\/>\n\n                <label for='ays-answer-2662-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. IV<\/label><label for='ays-answer-2662-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['711'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='732' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>29 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>29. <\/p>\n\n                            <\/div>\n                            <div class=\"ays-image-question-img\"><img src=\"http:\/\/aiyoit.com\/tutorial\/wp-content\/uploads\/2023\/11\/Math3-300x50.png\"   alt=\"Math Question\" style='width:100%;height:auto;object-fit:cover;border-radius:0px;object-position:center center;' class=\" ays-quiz-keyboard-active\" tabindex='0'><\/div>\n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-732]' id='ays-answer-2744-37' value='2744'\/>\n\n                <label for='ays-answer-2744-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 0<\/label><label for='ays-answer-2744-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-732]' id='ays-answer-2745-37' value='2745'\/>\n\n                <label for='ays-answer-2745-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1\/25<\/label><label for='ays-answer-2745-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-732]' id='ays-answer-2746-37' value='2746'\/>\n\n                <label for='ays-answer-2746-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 1\/50<\/label><label for='ays-answer-2746-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-732]' id='ays-answer-2747-37' value='2747'\/>\n\n                <label for='ays-answer-2747-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 1\/100<\/label><label for='ays-answer-2747-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['732'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='727' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>30 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>30. \u091a\u093e\u0930 \u0905\u0902\u0915\u094b\u0902 \u0915\u0940 \u092c\u095c\u0940 \u0938\u0947 \u092c\u095c\u0940 \u0938\u0902\u0916\u094d\u092f\u093e \u0915\u094c\u0928 - \u0938\u0940 \u0939\u0948 \u091c\u094b 12,15,18,27 \u092e\u0947 \u0938\u0947 \u092a\u094d\u0930\u0924\u094d\u092f\u0947\u0915 \u0938\u0947 \u092a\u0942\u0930\u094d\u0923\u0924\u092f\u093e \u0935\u093f\u092d\u0915\u094d\u0924 \u0939\u094b?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-727]' id='ays-answer-2724-37' value='2724'\/>\n\n                <label for='ays-answer-2724-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 9690<\/label><label for='ays-answer-2724-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-727]' id='ays-answer-2725-37' value='2725'\/>\n\n                <label for='ays-answer-2725-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 9720<\/label><label for='ays-answer-2725-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-727]' id='ays-answer-2726-37' value='2726'\/>\n\n                <label for='ays-answer-2726-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 9930<\/label><label for='ays-answer-2726-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-727]' id='ays-answer-2727-37' value='2727'\/>\n\n                <label for='ays-answer-2727-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 9960<\/label><label for='ays-answer-2727-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['727'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='724' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>31 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>31. 14\/33, 42\/55, 21\/22 \u0915\u093e HCF \u091c\u094d\u091e\u093e\u0924 \u0915\u0940\u091c\u093f\u090f<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-724]' id='ays-answer-2712-37' value='2712'\/>\n\n                <label for='ays-answer-2712-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 7\/330<\/label><label for='ays-answer-2712-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-724]' id='ays-answer-2713-37' value='2713'\/>\n\n                <label for='ays-answer-2713-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 7\/37<\/label><label for='ays-answer-2713-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-724]' id='ays-answer-2714-37' value='2714'\/>\n\n                <label for='ays-answer-2714-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 11\/27<\/label><label for='ays-answer-2714-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-724]' id='ays-answer-2715-37' value='2715'\/>\n\n                <label for='ays-answer-2715-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 7\/30<\/label><label for='ays-answer-2715-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['724'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='716' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>32 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>32. \u092d\u093e\u0930\u0924\u0940\u092f \u0938\u0902\u0935\u093f\u0927\u093e\u0928 \u092e\u0947 \u0938\u092e\u094d\u092e\u093f\u0932\u093f\u0924 \u0928\u0940\u0924\u093f \u2013 \u0928\u093f\u0930\u094d\u0926\u0947\u0936\u0915 \u0924\u0924\u094d\u0935\u094b\u0902 \u0915\u0940 \u092a\u094d\u0930\u0947\u0930\u0923\u093e \u0939\u092e\u0947 \u0915\u093f\u0938 \u0938\u0902\u0935\u093f\u0927\u093e\u0928 \u0938\u0947 \u092a\u094d\u0930\u093e\u092a\u094d\u0924 \u0939\u0941\u0908 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-716]' id='ays-answer-2680-37' value='2680'\/>\n\n                <label for='ays-answer-2680-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0911\u0938\u094d\u091f\u094d\u0930\u0947\u0932\u093f\u092f\u093e<\/label><label for='ays-answer-2680-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-716]' id='ays-answer-2681-37' value='2681'\/>\n\n                <label for='ays-answer-2681-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0905\u092e\u0947\u0930\u093f\u0915\u093e<\/label><label for='ays-answer-2681-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-716]' id='ays-answer-2682-37' value='2682'\/>\n\n                <label for='ays-answer-2682-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u092b\u094d\u0930\u093e\u0902\u0938<\/label><label for='ays-answer-2682-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-716]' id='ays-answer-2683-37' value='2683'\/>\n\n                <label for='ays-answer-2683-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0906\u092f\u0930\u0932\u0948\u0902\u0921<\/label><label for='ays-answer-2683-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['716'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='705' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>33 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>33. \u0938\u0902\u0935\u0948\u0927\u093e\u0928\u093f\u0915 \u0909\u092a\u091a\u093e\u0930 \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930 \u0915\u093f\u0938\u0915\u0947 \u0905\u0902\u0924\u0930\u094d\u0917\u0924 \u0906\u0924\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-705]' id='ays-answer-2635-37' value='2635'\/>\n\n                <label for='ays-answer-2635-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092e\u094c\u0932\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2635-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-705]' id='ays-answer-2636-37' value='2636'\/>\n\n                <label for='ays-answer-2636-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0915\u093e\u0928\u0942\u0928\u0940 \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2636-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-705]' id='ays-answer-2637-37' value='2637'\/>\n\n                <label for='ays-answer-2637-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0938\u0902\u0935\u0948\u0927\u093e\u0928\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2637-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-705]' id='ays-answer-2638-37' value='2638'\/>\n\n                <label for='ays-answer-2638-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092a\u094d\u0930\u093e\u0915\u0943\u0924\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2638-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['705'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='738' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>34 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>34. \u0915\u093f\u0938\u0940 \u0938\u092a\u094d\u0924\u093e\u0939 \u0938\u094b\u092e\u0935\u093e\u0930 , \u092e\u0902\u0917\u0932\u0935\u093e\u0930 \u0924\u0925\u093e \u092c\u0941\u0927\u0935\u093e\u0930 \u0915\u093e \u0914\u0938\u0924 \u0924\u093e\u092a\u092e\u093e\u0928 30<sup>o <\/sup>c \u00a0\u0925\u093e | \u091c\u092c\u0915\u093f \u092e\u0902\u0917\u0932\u0935\u093e\u0930, \u092c\u0941\u0927\u0935\u093e\u0930 \u0924\u0925\u093e \u0935\u0943\u0939\u0938\u094d\u092a\u0924\u093f\u0935\u093e\u0930 \u0915\u093e \u0914\u0938\u0924 \u0924\u093e\u092a\u092e\u093e\u0928 33<sup>o<\/sup>c \u00a0\u0925\u093e | \u092f\u0926\u093f \u0938\u094b\u092e\u0935\u093e\u0930 \u0915\u0947 \u0926\u093f\u0928 \u0924\u093e\u092a\u092e\u093e\u0928 32<sup>o <\/sup>c \u00a0\u0925\u093e, \u0924\u094b \u0935\u0943\u0939\u0938\u094d\u092a\u0924\u093f\u0935\u093e\u0930 \u0915\u093e \u0924\u093e\u092a\u092e\u093e\u0928 \u0915\u093f\u0924\u0928\u093e \u0925\u093e ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-738]' id='ays-answer-2768-37' value='2768'\/>\n\n                <label for='ays-answer-2768-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 33C<\/label><label for='ays-answer-2768-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-738]' id='ays-answer-2769-37' value='2769'\/>\n\n                <label for='ays-answer-2769-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 30C<\/label><label for='ays-answer-2769-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-738]' id='ays-answer-2770-37' value='2770'\/>\n\n                <label for='ays-answer-2770-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 41C<\/label><label for='ays-answer-2770-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-738]' id='ays-answer-2771-37' value='2771'\/>\n\n                <label for='ays-answer-2771-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 32C<\/label><label for='ays-answer-2771-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['738'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='731' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>35 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>35. <\/p>\n\n                            <\/div>\n                            <div class=\"ays-image-question-img\"><img src=\"http:\/\/aiyoit.com\/tutorial\/wp-content\/uploads\/2023\/11\/Math2-300x52.png\"   alt=\"Math question\" style='width:100%;height:auto;object-fit:cover;border-radius:0px;object-position:center center;' class=\" ays-quiz-keyboard-active\" tabindex='0'><\/div>\n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-731]' id='ays-answer-2740-37' value='2740'\/>\n\n                <label for='ays-answer-2740-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 1<\/label><label for='ays-answer-2740-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-731]' id='ays-answer-2741-37' value='2741'\/>\n\n                <label for='ays-answer-2741-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 1\/2<\/label><label for='ays-answer-2741-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-731]' id='ays-answer-2742-37' value='2742'\/>\n\n                <label for='ays-answer-2742-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 3\/2<\/label><label for='ays-answer-2742-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-731]' id='ays-answer-2743-37' value='2743'\/>\n\n                <label for='ays-answer-2743-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 3<\/label><label for='ays-answer-2743-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['731'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='708' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>36 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>36. \u0938\u0930\u094d\u0935\u094b\u091a\u094d\u091a \u0928\u094d\u092f\u093e\u092f\u093e\u0932\u092f \u0928\u0947 \u0928\u093f\u091c\u0924\u093e \u0915\u0947 \u0905\u0927\u093f\u0915\u093e\u0930 \u0915\u094b \u0938\u0935\u093f\u0927\u093e\u0928 \u0915\u0947 \u0915\u093f\u0938 \u092e\u0942\u0932\u092d\u0942\u0924 \u0905\u0927\u093f\u0915\u093e\u0930 \u0915\u0947 \u0905\u0927\u0940\u0928 \u0930\u0916\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-708]' id='ays-answer-2647-37' value='2647'\/>\n\n                <label for='ays-answer-2647-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-19<\/label><label for='ays-answer-2647-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-708]' id='ays-answer-2648-37' value='2648'\/>\n\n                <label for='ays-answer-2648-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-14<\/label><label for='ays-answer-2648-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-708]' id='ays-answer-2649-37' value='2649'\/>\n\n                <label for='ays-answer-2649-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-20<\/label><label for='ays-answer-2649-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-708]' id='ays-answer-2650-37' value='2650'\/>\n\n                <label for='ays-answer-2650-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926-21<\/label><label for='ays-answer-2650-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['708'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='733' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>37 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>37. <\/p>\n\n                            <\/div>\n                            <div class=\"ays-image-question-img\"><img src=\"http:\/\/aiyoit.com\/tutorial\/wp-content\/uploads\/2023\/11\/Math-4-300x53.png\"   alt=\"Math Question\" style='width:100%;height:auto;object-fit:cover;border-radius:0px;object-position:center center;' class=\" ays-quiz-keyboard-active\" tabindex='0'><\/div>\n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-733]' id='ays-answer-2748-37' value='2748'\/>\n\n                <label for='ays-answer-2748-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 7<\/label><label for='ays-answer-2748-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-733]' id='ays-answer-2749-37' value='2749'\/>\n\n                <label for='ays-answer-2749-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 8<\/label><label for='ays-answer-2749-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-733]' id='ays-answer-2750-37' value='2750'\/>\n\n                <label for='ays-answer-2750-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 9<\/label><label for='ays-answer-2750-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-733]' id='ays-answer-2751-37' value='2751'\/>\n\n                <label for='ays-answer-2751-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 11<\/label><label for='ays-answer-2751-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['733'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='644' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>38 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>38. \u0915\u0902\u092a\u094d\u092f\u0942\u091f\u0930 \u0915\u093e \u0939\u093f\u0928\u094d\u0926\u0940 \u0928\u093e\u092e \u0915\u094d\u092f\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-644]' id='ays-answer-2391-37' value='2391'\/>\n\n                <label for='ays-answer-2391-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0917\u0923\u0928\u093e \u0915\u0930\u0928\u0947\u0935\u093e\u0932\u093e<\/label><label for='ays-answer-2391-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-644]' id='ays-answer-2392-37' value='2392'\/>\n\n                <label for='ays-answer-2392-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u0902\u0917\u0923\u0915<\/label><label for='ays-answer-2392-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-644]' id='ays-answer-2393-37' value='2393'\/>\n\n                <label for='ays-answer-2393-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0939\u093f\u0938\u093e\u092c \u0932\u0917\u093e\u0928\u0947\u0935\u093e\u0932\u093e<\/label><label for='ays-answer-2393-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-644]' id='ays-answer-2394-37' value='2394'\/>\n\n                <label for='ays-answer-2394-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092a\u0930\u093f\u0917\u0923\u0915<\/label><label for='ays-answer-2394-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['644'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='736' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>39 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>39. \u0924\u0940\u0928 \u0915\u094d\u0930\u092e\u093e\u0917\u0924 \u0938\u0902\u0916\u094d\u092f\u093e\u0913 \u0915\u093e \u0914\u0938\u0924 \u092a\u0939\u0932\u0940 \u0938\u0902\u0916\u094d\u092f\u093e \u0915\u0947 \u090f\u0915 \u0924\u093f\u0939\u093e\u0908 \u0938\u0947 15 \u091c\u094d\u092f\u093e\u0926\u093e \u0939\u0948, \u0938\u092c\u0938\u0947 \u092c\u095c\u0940 \u0938\u0902\u0916\u094d\u092f\u093e \u091c\u094d\u091e\u093e\u0924 \u0915\u0930\u0947 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-736]' id='ays-answer-2760-37' value='2760'\/>\n\n                <label for='ays-answer-2760-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 22<\/label><label for='ays-answer-2760-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-736]' id='ays-answer-2761-37' value='2761'\/>\n\n                <label for='ays-answer-2761-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 21<\/label><label for='ays-answer-2761-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-736]' id='ays-answer-2762-37' value='2762'\/>\n\n                <label for='ays-answer-2762-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 23<\/label><label for='ays-answer-2762-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-736]' id='ays-answer-2763-37' value='2763'\/>\n\n                <label for='ays-answer-2763-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 19<\/label><label for='ays-answer-2763-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['736'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='743' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>40 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>40. \u0915\u093f\u0938\u0940 \u0915\u094b\u0921 \u092d\u093e\u0937\u093e \u092e\u0947 Sue Re Nik \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 She is Brave , Pi Sor Ri Nik \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 Shi is always Smiling \u0914\u0930 Sor Re Zni \u00a0\u00a0\u00a0\u00a0\u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 Is always Cheerful . Smiling \u0936\u092c\u094d\u0926 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0938 \u0915\u094b\u0921 \u0915\u093e \u092a\u094d\u0930\u092f\u094b\u0917 \u0915\u093f\u092f\u093e \u0917\u092f\u093e \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-743]' id='ays-answer-2788-37' value='2788'\/>\n\n                <label for='ays-answer-2788-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. Sor<\/label><label for='ays-answer-2788-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-743]' id='ays-answer-2789-37' value='2789'\/>\n\n                <label for='ays-answer-2789-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. Re<\/label><label for='ays-answer-2789-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-743]' id='ays-answer-2790-37' value='2790'\/>\n\n                <label for='ays-answer-2790-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. Nik<\/label><label for='ays-answer-2790-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-743]' id='ays-answer-2791-37' value='2791'\/>\n\n                <label for='ays-answer-2791-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. Pi<\/label><label for='ays-answer-2791-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['743'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='719' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>41 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>41. \u0935\u0930\u094d\u0924\u092e\u093e\u0928 \u092e\u0947 \u0938\u0902\u0935\u093f\u0927\u093e\u0928 \u092e\u0947 \u0915\u0941\u0932 \u0915\u093f\u0924\u0928\u0947 \u092e\u0942\u0932 \u0915\u0930\u094d\u0924\u0935\u094d\u092f\u094b\u0902 \u0915\u093e \u0909\u0932\u094d\u0932\u0947\u0916\u00a0 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-719]' id='ays-answer-2692-37' value='2692'\/>\n\n                <label for='ays-answer-2692-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0928\u094c<\/label><label for='ays-answer-2692-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-719]' id='ays-answer-2693-37' value='2693'\/>\n\n                <label for='ays-answer-2693-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0926\u0938<\/label><label for='ays-answer-2693-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-719]' id='ays-answer-2694-37' value='2694'\/>\n\n                <label for='ays-answer-2694-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0917\u094d\u092f\u093e\u0930\u0939<\/label><label for='ays-answer-2694-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-719]' id='ays-answer-2695-37' value='2695'\/>\n\n                <label for='ays-answer-2695-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092c\u093e\u0930\u0939<\/label><label for='ays-answer-2695-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['719'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='723' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>42 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>42. 2\/3, 8\/7, 12\/5 \u0915\u093e LCM \u091c\u094d\u091e\u093e\u0924 \u0915\u0940\u091c\u093f\u090f<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-723]' id='ays-answer-2708-37' value='2708'\/>\n\n                <label for='ays-answer-2708-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 24<\/label><label for='ays-answer-2708-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-723]' id='ays-answer-2709-37' value='2709'\/>\n\n                <label for='ays-answer-2709-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 22<\/label><label for='ays-answer-2709-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-723]' id='ays-answer-2710-37' value='2710'\/>\n\n                <label for='ays-answer-2710-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 26<\/label><label for='ays-answer-2710-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-723]' id='ays-answer-2711-37' value='2711'\/>\n\n                <label for='ays-answer-2711-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 28<\/label><label for='ays-answer-2711-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['723'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='747' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>43 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>43. \u0915\u093f\u0938\u0940 \u0938\u093e\u0902\u0915\u0947\u0924\u093f\u0915 \u092d\u093e\u0937\u093e \u092e\u0947 \u2018ASTROLOGER\u2019 \u0915\u094b \u2018GELORTRASO\u2019 \u0932\u093f\u0916\u093e \u091c\u093e\u0924\u093e \u0939\u0948 , \u0924\u094b \u0909\u0938\u0940 \u092d\u093e\u0937\u093e \u092e\u0947 \u2018TELEVISION\u2019 \u0915\u094b \u0915\u0948\u0938\u0947 \u0932\u093f\u0916\u093e \u091c\u093e\u090f\u0917\u093e ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-747]' id='ays-answer-2804-37' value='2804'\/>\n\n                <label for='ays-answer-2804-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. IOINLETVES<\/label><label for='ays-answer-2804-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-747]' id='ays-answer-2805-37' value='2805'\/>\n\n                <label for='ays-answer-2805-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. IOINLETEVS<\/label><label for='ays-answer-2805-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-747]' id='ays-answer-2806-37' value='2806'\/>\n\n                <label for='ays-answer-2806-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. IOINSLETEV<\/label><label for='ays-answer-2806-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-747]' id='ays-answer-2807-37' value='2807'\/>\n\n                <label for='ays-answer-2807-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0909\u092a\u092f\u0941\u0915\u094d\u0924 \u092e\u0947 \u0938\u0947 \u0915\u094b\u0908 \u0928\u0939\u0940\u0902<\/label><label for='ays-answer-2807-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['747'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='712' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>44 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>44. \u0928\u093f\u092e\u094d\u0928\u0932\u093f\u0916\u093f\u0924 \u092e\u0947\u0902 \u0938\u0947 \u0915\u094c\u0928 \u090f\u0915 \u0938\u0941\u092e\u0947\u0932\u093f\u0924 \u0928\u0939\u0940\u0902 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-712]' id='ays-answer-2663-37' value='2663'\/>\n\n                <label for='ays-answer-2663-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 - 23 \u2013 \u092e\u093e\u0928\u0935 \u0915\u0947 \u0926\u0941\u0930\u094d\u0935\u094d\u092f\u093e\u092a\u093e\u0930 \u090f\u0935\u0902 \u092c\u0932\u093e\u0924 \u0936\u094d\u0930\u092e \u0915\u093e \u092a\u094d\u0930\u0924\u093f\u092c\u0932<\/label><label for='ays-answer-2663-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-712]' id='ays-answer-2664-37' value='2664'\/>\n\n                <label for='ays-answer-2664-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 - 24 - \u0915\u093e\u0930\u0916\u093e\u0928\u094b \u0906\u0926\u093f \u092e\u0947\u0902 \u092c\u093e\u0932\u0915\u094b \u0915\u0947 \u0928\u093f\u092f\u094b\u091c\u0928 \u0915\u093e<\/label><label for='ays-answer-2664-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-712]' id='ays-answer-2665-37' value='2665'\/>\n\n                <label for='ays-answer-2665-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 - 26 \u2013 \u0927\u093e\u0930\u094d\u092e\u093f\u0915 \u0915\u093e\u0930\u094d\u092f\u094b\u0902 \u0915\u0947 \u092a\u094d\u0930\u092c\u0928\u094d\u0927 \u0915\u0940 \u0938\u094d\u0935\u0924\u0902\u0924\u094d\u0930\u0924\u093e<\/label><label for='ays-answer-2665-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-712]' id='ays-answer-2666-37' value='2666'\/>\n\n                <label for='ays-answer-2666-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 - 29 \u2013 \u0936\u093f\u0915\u094d\u0937\u0923 \u0938\u0902\u0938\u094d\u0925\u093e\u0928\u094b\u0902 \u0915\u0940 \u0938\u094d\u0925\u093e\u092a\u0928 \u0914\u0930 \u092a\u094d\u0930\u0936\u093e\u0938\u0928 \u0915\u0930\u0928\u0947 \u0915\u093e \u0905\u0932\u092a\u0938\u0902\u0916\u094d\u092f\u0915 \u0935\u0930\u094d\u0917\u094b\u0902 \u0915\u093e \u0905\u0927\u093f\u0915\u093e\u0930<\/label><label for='ays-answer-2666-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['712'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='746' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>45 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>45. \u090f\u0915 \u0938\u093e\u0902\u0915\u0947\u0924\u093f\u0915 \u092d\u093e\u0937\u093e \u0915\u0947 \u0915\u0941\u091b \u0924\u0925\u094d\u092f \u0928\u0940\u091a\u0947 \u0926\u093f\u090f \u0917\u092f\u0947 \u0939\u0948 \u2013<\/p>\n<p>123 \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 \u2013 It is black.<\/p>\n<p>345 \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 \u2013 Dog is running.<\/p>\n<p>356 \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 \u2013 Is running good.<\/p>\n<p>728 \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 \u2013 Black pet cow.<\/p>\n<p>637 \u0915\u093e \u0905\u0930\u094d\u0925 \u0939\u0948 \u2013 Cow is good<\/p>\n<p>Black cow is running \u0915\u093e \u0938\u0902\u0915\u0947\u0924 \u0909\u0915\u094d\u0924 \u092d\u093e\u0937\u093e \u092e\u0947 \u0915\u094d\u092f\u093e \u0939\u094b\u0917\u093e<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-746]' id='ays-answer-2800-37' value='2800'\/>\n\n                <label for='ays-answer-2800-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 5342<\/label><label for='ays-answer-2800-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-746]' id='ays-answer-2801-37' value='2801'\/>\n\n                <label for='ays-answer-2801-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 2735<\/label><label for='ays-answer-2801-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-746]' id='ays-answer-2802-37' value='2802'\/>\n\n                <label for='ays-answer-2802-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 6321<\/label><label for='ays-answer-2802-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-746]' id='ays-answer-2803-37' value='2803'\/>\n\n                <label for='ays-answer-2803-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. d)\t7435<\/label><label for='ays-answer-2803-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['746'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='741' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>46 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>46. \u0928\u093f\u092e\u094d\u0928 \u092a\u094d\u0930\u0936\u094d\u0928\u094b\u0902 \u092e\u0947 \u0926\u093f\u090f \u0917\u090f \u0935\u093f\u0915\u0932\u094d\u092a\u094b\u0902 \u092e\u0947 \u0938\u0947 \u0935\u093f\u0937\u092e \u0905\u0915\u094d\u0937\u0930 | \u0938\u0902\u0916\u094d\u092f\u093e \u0936\u092c\u094d\u0926 \u091a\u0941\u0928\u093f\u092f\u0947 |<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-741]' id='ays-answer-2780-37' value='2780'\/>\n\n                <label for='ays-answer-2780-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u092a\u094d\u0932\u0947\u091f\u094b\u0902<\/label><label for='ays-answer-2780-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-741]' id='ays-answer-2781-37' value='2781'\/>\n\n                <label for='ays-answer-2781-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u094d\u091f\u093e\u0930<\/label><label for='ays-answer-2781-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-741]' id='ays-answer-2782-37' value='2782'\/>\n\n                <label for='ays-answer-2782-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u092e\u093e\u0909\u0902\u091f\u0947\u0928<\/label><label for='ays-answer-2782-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-741]' id='ays-answer-2783-37' value='2783'\/>\n\n                <label for='ays-answer-2783-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u092b\u0949\u0930\u0947\u0938\u094d\u091f<\/label><label for='ays-answer-2783-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['741'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='722' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>47 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>47. 83462*704 , 3 \u0938\u0947 \u0935\u093f\u092d\u093e\u091c\u094d\u092f \u0939\u0948 , \u0924\u094b * \u0915\u0947 \u0938\u094d\u0925\u093e\u0928 \u092a\u0930 \u0938\u0902\u092d\u093e\u0935\u093f\u0924 \u0905\u0902\u0915\u094b\u0902 \u092f\u094b\u0917 \u0939\u0948<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-722]' id='ays-answer-2704-37' value='2704'\/>\n\n                <label for='ays-answer-2704-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 17<\/label><label for='ays-answer-2704-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-722]' id='ays-answer-2705-37' value='2705'\/>\n\n                <label for='ays-answer-2705-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 15<\/label><label for='ays-answer-2705-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-722]' id='ays-answer-2706-37' value='2706'\/>\n\n                <label for='ays-answer-2706-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 16<\/label><label for='ays-answer-2706-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-722]' id='ays-answer-2707-37' value='2707'\/>\n\n                <label for='ays-answer-2707-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 19<\/label><label for='ays-answer-2707-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['722'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='714' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>48 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>48. \u092d\u093e\u0930\u0924\u0940\u092f \u0938\u0902\u0935\u093f\u0927\u093e\u0928 \u0915\u0947 \u0915\u093f\u0938 \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 \u092e\u0947\u0902 \u0930\u093e\u091c\u094d\u092f \u0915\u0947 \u0928\u0940\u0924\u093f \u0928\u093f\u0926\u0947\u0936\u0915 \u0924\u0924\u094d\u0935\u094b\u0902 \u0915\u093e \u0909\u0932\u094d\u0932\u0947\u0916 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-714]' id='ays-answer-2671-37' value='2671'\/>\n\n                <label for='ays-answer-2671-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 -34 \u0938\u0947 46<\/label><label for='ays-answer-2671-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-714]' id='ays-answer-2672-37' value='2672'\/>\n\n                <label for='ays-answer-2672-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 -36 \u0938\u0947 51<\/label><label for='ays-answer-2672-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-714]' id='ays-answer-2673-37' value='2673'\/>\n\n                <label for='ays-answer-2673-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 -34 \u0938\u0947 52<\/label><label for='ays-answer-2673-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-714]' id='ays-answer-2674-37' value='2674'\/>\n\n                <label for='ays-answer-2674-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 -37 \u0938\u0947 51<\/label><label for='ays-answer-2674-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['714'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='704' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>49 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>49. \u092d\u093e\u0930\u0924\u0940\u092f \u0928\u093e\u0917\u0930\u093f\u0915\u094b\u0902 \u0915\u0947 \u092e\u094c\u0932\u093f\u0915 \u0905\u0927\u093f\u0915\u093e\u0930\u094b\u0902 \u0915\u093e \u0935\u0930\u094d\u0923\u0928 \u0939\u0948 ?<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-704]' id='ays-answer-2631-37' value='2631'\/>\n\n                <label for='ays-answer-2631-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. \u0938\u0902\u0935\u093f\u0927\u093e\u0928  \u0915\u0947 \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 12 \u0938\u0947 35 \u0924\u0915<\/label><label for='ays-answer-2631-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-704]' id='ays-answer-2632-37' value='2632'\/>\n\n                <label for='ays-answer-2632-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. \u0938\u0902\u0935\u093f\u0927\u093e\u0928 \u0915\u0947 \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 13 \u0938\u0947 36 \u0924\u0915<\/label><label for='ays-answer-2632-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-704]' id='ays-answer-2633-37' value='2633'\/>\n\n                <label for='ays-answer-2633-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. \u0938\u0902\u0935\u093f\u0927\u093e\u0928 \u0915\u0947 \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 15 \u0938\u0947 39 \u0924\u0915<\/label><label for='ays-answer-2633-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-704]' id='ays-answer-2634-37' value='2634'\/>\n\n                <label for='ays-answer-2634-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. \u0938\u0902\u0935\u093f\u0927\u093e\u0928 \u0915\u0947 \u0905\u0928\u0941\u091a\u094d\u091b\u0947\u0926 16 \u0938\u0947 40 \u0924\u0915<\/label><label for='ays-answer-2634-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['704'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_previous action-button ays-quiz-keyboard-active ' value='Prev' \/>\n                        \n                        <i class=\"ays_fa ays_fa_arrow_right ays_next action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                        <input type='button' class='ays_next action-button ays-quiz-keyboard-active ' value='Next' \/>\n                    <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ' data-question-id='748' data-type='radio'>\n                    \n                    \n                    <p class='ays-question-counter animated'>50 \/ 50<\/p>\n                    <div class='ays-abs-fs'>\n                        \n                        <div class='ays_quiz_question'>\n                                <p>50. \u090f\u0915 \u0926\u093f\u0928 \u0928\u0940\u0924\u093e \u0918\u0930 \u0938\u0947 \u0928\u093f\u0915\u0932 \u0915\u0930 10 \u0915\u093f\u092e\u0940 \u0938\u093e\u0907\u0915\u093f\u0932 \u0938\u0947 \u0926\u0915\u094d\u0937\u093f\u0923 \u0915\u0940 \u0914\u0930 \u0917\u0908 , \u0926\u093e\u090f \u092e\u0941\u095c\u0915\u0930 5 \u0915\u093f\u092e\u0940 \u091a\u0932\u0940 , \u092b\u093f\u0930 \u0926\u093e\u090f \u092e\u0941\u095c\u0915\u0930 10 \u0915\u093f\u092e\u0940 \u091a\u0932\u0940 \u0914\u0930 \u092b\u093f\u0930 \u092c\u093e\u090f \u092e\u0941\u095c\u0915\u0930 10 \u0915\u093f\u092e\u0940 \u091a\u0932\u0940 | \u0909\u0938\u0947 \u0938\u0940\u0927\u0947 \u0905\u092a\u0928\u0947 \u0918\u0930 \u092a\u0939\u0941\u091a\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0915\u093f\u0924\u0928\u0947 \u0915\u093f\u092e\u0940 \u0938\u093e\u0907\u0915\u093f\u0932 \u091a\u0932\u093e\u0928\u0940 \u092a\u095c\u0947\u0917\u0940<\/p>\n\n                            <\/div>\n                            \n                        <div class='ays-quiz-answers ays_list_view_container  '>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-748]' id='ays-answer-2808-37' value='2808'\/>\n\n                <label for='ays-answer-2808-37' class='  ays_position_initial  ays-quiz-keyboard-label'>a. 10 \u0915\u093f\u092e\u0940<\/label><label for='ays-answer-2808-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-748]' id='ays-answer-2809-37' value='2809'\/>\n\n                <label for='ays-answer-2809-37' class='  ays_position_initial  ays-quiz-keyboard-label'>b. 15 \u0915\u093f\u092e\u0940<\/label><label for='ays-answer-2809-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-748]' id='ays-answer-2810-37' value='2810'\/>\n\n                <label for='ays-answer-2810-37' class='  ays_position_initial  ays-quiz-keyboard-label'>c. 20 \u0915\u093f\u092e\u0940<\/label><label for='ays-answer-2810-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div>\n            <div class='ays-field ays_list_view_item ays-quiz-keyboard-active' tabindex='0' >\n                <input type='hidden' name='ays_answer_correct[]' value='0'\/>\n\n                <input type='radio' name='ays_questions[ays-question-748]' id='ays-answer-2811-37' value='2811'\/>\n\n                <label for='ays-answer-2811-37' class='  ays_position_initial  ays-quiz-keyboard-label'>d. 25 \u0915\u093f\u092e\u0940<\/label><label for='ays-answer-2811-37' class='ays_answer_image ays_answer_image_class ays_empty_before_content'><\/label>\n\n            <\/div><script>\n            if(typeof window.quizOptions_37 === 'undefined'){\n                window.quizOptions_37 = [];\n            }\n            window.quizOptions_37['748'] = 'W10=';<\/script><\/div>                        \n                        \n                        \n                        <div class='ays_buttons_div'>\n                            \n                            <i class=\"ays_fa ays_fa_arrow_left ays_previous action-button ays_arrow ays-quiz-keyboard-active ays_display_none\" tabindex='0'><\/i>\n                            <input type='button' class='ays_previous action-button ays-quiz-keyboard-active '  value='Prev' \/>\n                            <i class='ays_display_none ays_fa ays_fa_flag_checkered ays_finish action-button ays_arrow ays_next_arrow ays-quiz-keyboard-active' tabindex='0'><\/i><input type='submit' name='ays_finish_quiz' class='  ays_next ays_finish action-button ays-quiz-keyboard-active' value='See Result'\/>\n                        <\/div>\n                        \n                        <div class='wrong_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='right_answer_text ays_do_not_show' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays_questtion_explanation' style='display:none'>\n                            \n                        <\/div>\n                        <div class='ays-quiz-additonal-box'>\n                            \n                        <\/div>   \n                        \n                        \n                    <\/div>\n                <\/div><div class='step ays_thank_you_fs'>\n            <div class='ays-abs-fs ays-end-page'><div data-class='lds-hourglass' data-role='loader' class='ays-loader'><\/div><div class='ays_quiz_results_page'><div class='ays_score_message'><\/div><div class='ays_message'><\/div><div class='ays-progress first'>\n                <span class='ays-progress-value first'>0%<\/span>\n                <div class='ays-progress-bg first'>\n                    <div class='ays-progress-bar first' style='width:0%;'><\/div>\n                <\/div>\n            <\/div><p class='ays_restart_button_p'><\/p><\/div>\n            <\/div>\n        <\/div><style>\n            div#ays-quiz-container-37 * {\n                box-sizing: border-box;\n            }\n\n            #ays-quiz-container-37 [id^='ays_finish_quiz_'] div.step div.ays-abs-fs {\n                width: 90%;\n            }\n\n            \/* Styles for Internet Explorer start *\/\n            #ays-quiz-container-37 #ays_finish_quiz_37 {\n                \n            }\n\n            \/* Styles for Quiz container *\/\n            #ays-quiz-container-37{\n                min-height: 400px;\n                width:100%;\n                background-color:rgba(212,120,226,0.31);\n                background-position:center center;background-image: linear-gradient(to bottom, rgba(165,104,226,0.26), #fff);border-radius:0px;box-shadow: 0px 0px 15px  1px rgba(0,0,0,0.4);border: none;}\n\n            \/* Styles for questions *\/\n            #ays-quiz-container-37 #ays_finish_quiz_37 div.step {\n                min-height: 400px;\n            }\n\n            \/* Styles for text inside quiz container *\/\n            #ays-quiz-container-37 .ays-start-page *:not(input):not([class^='enlighter']),\n            #ays-quiz-container-37 .ays_question_hint,\n            #ays-quiz-container-37 label[for^=\"ays-answer-\"],\n            #ays-quiz-container-37 #ays_finish_quiz_37 p,\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-fs-title,\n            #ays-quiz-container-37 .ays-fs-subtitle,\n            #ays-quiz-container-37 .logged_in_message,\n            #ays-quiz-container-37 .ays_score_message,\n            #ays-quiz-container-37 .ays_message{\n               color: #000;\n               outline: none;\n            }\n\n            div#ays-quiz-container-37 .ays_question_hint.ays-quiz-keyboard-active,\n            div#ays-quiz-container-37 .ays_restart_button.ays-quiz-keyboard-active {\n                outline: revert;\n            }\n\n            #ays-quiz-container-37 .ays-quiz-password-message-box,\n            #ays-quiz-container-37 .ays-quiz-question-note-message-box,\n            #ays-quiz-container-37 .ays_quiz_question,\n            #ays-quiz-container-37 .ays-quiz-question-category-box,\n            #ays-quiz-container-37 .ays_quiz_question *:not([class^='enlighter']) {\n                color: #000;\n            }\n\n            #ays-quiz-container-37 .ays-quiz-question-category-box em {\n                color: #000;\n            }\n\n            #ays-quiz-container-37 textarea,\n            #ays-quiz-container-37 input::first-letter,\n            #ays-quiz-container-37 select::first-letter,\n            #ays-quiz-container-37 option::first-letter {\n                color: initial !important;\n            }\n            \n            #ays-quiz-container-37 p::first-letter:not(.ays_no_questions_message) {\n                color: #000 !important;\n                background-color: transparent !important;\n                font-size: inherit !important;\n                font-weight: inherit !important;\n                float: none !important;\n                line-height: inherit !important;\n                margin: 0 !important;\n                padding: 0 !important;\n            }\n            \n            \n            #ays-quiz-container-37 .select2-container,\n            #ays-quiz-container-37 .ays-field * {\n                font-size: 18px !important;\n            }\n    \n            #ays-quiz-container-37 .ays_quiz_question p {\n                font-size: 18px;\n                text-align: inherit;\n            }\n\n            #ays-quiz-container-37 .ays-fs-subtitle p {\n                text-align:  center ;\n            }\n\n            #ays-quiz-container-37 .ays_quiz_question {\n                text-align:  center ;\n                margin-bottom: 10px;\n            }\n\n            #ays-quiz-container-37 .ays_quiz_question pre {\n                max-width: 100%;\n                white-space: break-spaces;\n            }\n\n            \/* Mango theme (Version: 1.4.202301041836) | tid=32449 | Start *\/\n            #ays-quiz-container-37 .ays_quiz_question img {\n                float: unset;\n                margin: 0;\n            }\n            \/* Mango theme (Version: 1.4.202301041836) | End *\/\n\n            #ays-quiz-container-37 .ays-quiz-timer p {\n                font-size: 16px;\n            }\n\n            #ays-quiz-container-37 section.ays_quiz_redirection_timer_container hr,\n            #ays-quiz-container-37 section.ays_quiz_timer_container hr {\n                margin: 0;\n            }\n\n            #ays-quiz-container-37 section.ays_quiz_timer_container.ays_quiz_timer_red_warning .ays-quiz-timer {\n                color: #ff0000;\n            }\n\n            #ays-quiz-container-37 .ays_thank_you_fs p {\n                text-align: center;\n            }\n\n            #ays-quiz-container-37 .ays_quiz_results_page .ays_score span {\n                visibility: visible;\n            }\n\n            #ays-quiz-container-37 input[type='button'],\n            #ays-quiz-container-37 input[type='submit'] {\n                color: #000000 !important;\n            }\n\n            #ays-quiz-container-37 input[type='button']{\n                outline: none;\n            }\n\n            #ays-quiz-container-37 .information_form input[type='text'],\n            #ays-quiz-container-37 .information_form input[type='url'],\n            #ays-quiz-container-37 .information_form input[type='number'],\n            #ays-quiz-container-37 .information_form input[type='email'],\n            #ays-quiz-container-37 .information_form input[type='checkbox'],\n            #ays-quiz-container-37 .information_form input[type='tel'],\n            #ays-quiz-container-37 .information_form textarea,\n            #ays-quiz-container-37 .information_form select,\n            #ays-quiz-container-37 .information_form option {\n                color: initial !important;\n                outline: none;\n                background-image: unset;\n            }\n\n            #ays-quiz-container-37 .wrong_answer_text{\n                color:#ff4d4d;\n            }\n            #ays-quiz-container-37 .right_answer_text{\n                color:#33cc33;\n            }\n\n            #ays-quiz-container-37 .wrong_answer_text p {\n                font-size:18px;\n            }\n\n            #ays-quiz-container-37 .ays_questtion_explanation p {\n                font-size:18px;\n            }\n\n            #ays-quiz-container-37 .wrong_answer_text *:not(strong) {\n                text-transform:none;\n                text-decoration: none;\n                letter-spacing: 0px;\n                font-weight: normal;\n            }\n\n            #ays-quiz-container-37 .ays_questtion_explanation *:not(strong) {\n                text-transform:none;\n                text-decoration: none;\n                letter-spacing: 0px;\n                font-weight: normal;\n            }\n\n            #ays-quiz-container-37 .right_answer_text *:not(strong) {\n                text-transform:none;\n                text-decoration: none;\n                letter-spacing: 0px;\n                font-weight: normal;\n            }\n\n            #ays-quiz-container-37 .right_answer_text p {\n                font-size:16px;\n            }\n\n            #ays-quiz-container-37 .ays-quiz-question-note-message-box p {\n                font-size:14px;\n            }\n\n            #ays-quiz-container-37 .ays-quiz-question-note-message-box *:not(strong) {\n                text-transform:none;\n                text-decoration: none;\n                letter-spacing: 0px;\n                font-weight: normal;\n            }\n            \n            #ays-quiz-container-37 .ays_cb_and_a,\n            #ays-quiz-container-37 .ays_cb_and_a * {\n                color: rgb(0,0,0);\n                text-align: center;\n            }\n\n            \/* Quiz textarea height *\/\n            #ays-quiz-container-37 textarea {\n                height: 100px;\n                min-height: 100px;\n            }\n\n            \/* Quiz rate and passed users count *\/\n            #ays-quiz-container-37 .ays_quizn_ancnoxneri_qanak,\n            #ays-quiz-container-37 .ays_quiz_rete_avg {\n                color:rgba(212,120,226,0.31) !important;\n                background-color:#000;   \n            }\n\n            #ays-quiz-container-37 .ays-questions-container > .ays_quizn_ancnoxneri_qanak {\n                padding: 5px 20px;\n            }\n            #ays-quiz-container-37 div.for_quiz_rate.ui.star.rating .icon {\n                color: rgba(0,0,0,0.35);\n            }\n            #ays-quiz-container-37 .ays_quiz_rete_avg div.for_quiz_rate_avg.ui.star.rating .icon {\n                color: rgba(212,120,226,0.31);\n            }\n\n            #ays-quiz-container-37 .ays_quiz_rete .ays-quiz-rate-link-box .ays-quiz-rate-link {\n                color: #000;\n            }\n\n            \/* Loaders *\/            \n            #ays-quiz-container-37 div.lds-spinner,\n            #ays-quiz-container-37 div.lds-spinner2 {\n                color: #000;\n            }\n            #ays-quiz-container-37 div.lds-spinner div:after,\n            #ays-quiz-container-37 div.lds-spinner2 div:after {\n                background-color: #000;\n            }\n            #ays-quiz-container-37 .lds-circle,\n            #ays-quiz-container-37 .lds-facebook div,\n            #ays-quiz-container-37 .lds-ellipsis div{\n                background: #000;\n            }\n            #ays-quiz-container-37 .lds-ripple div{\n                border-color: #000;\n            }\n            #ays-quiz-container-37 .lds-dual-ring::after,\n            #ays-quiz-container-37 .lds-hourglass::after{\n                border-color: #000 transparent #000 transparent;\n            }\n\n            \/* Stars *\/\n            #ays-quiz-container-37 .ui.rating .icon,\n            #ays-quiz-container-37 .ui.rating .icon:before {\n                font-family: Rating !important;\n            }\n\n            \/* Progress bars *\/\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-progress {\n                border-color: rgba(0,0,0,0.8);\n            }\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-progress-bg {\n                background-color: rgba(0,0,0,0.3);\n            }    \n            #ays-quiz-container-37 .ays-progress-value {\n                color: #000;\n                text-align: center;\n            }\n            #ays-quiz-container-37 .ays-progress-bar {\n                background-color: rgba(118,0,244,0.63);\n            }\n            #ays-quiz-container-37 .ays-question-counter .ays-live-bar-wrap {\n                direction:ltr !important;\n            }\n            #ays-quiz-container-37 .ays-live-bar-fill{\n                color: #000;\n                border-bottom: 2px solid rgba(0,0,0,0.8);\n                text-shadow: 0px 0px 5px rgba(212,120,226,0.31);\n            }\n            #ays-quiz-container-37 .ays-live-bar-fill.ays-live-fourth,\n            #ays-quiz-container-37 .ays-live-bar-fill.ays-live-third,\n            #ays-quiz-container-37 .ays-live-bar-fill.ays-live-second {\n                text-shadow: unset;\n            }\n            #ays-quiz-container-37 .ays-live-bar-percent{\n                display:none;\n            }\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays_average {\n                text-align: center;\n            }\n            \n            \/* Music, Sound *\/\n            #ays-quiz-container-37 .ays_music_sound {\n                color:rgb(0,0,0);\n            }\n\n            \/* Dropdown questions scroll bar *\/\n            #ays-quiz-container-37 blockquote {\n                border-left-color: #000 !important;                                      \n            }\n\n            \/* Quiz Password *\/\n            #ays-quiz-container-37 .ays-start-page > input[id^='ays_quiz_password_val_'],\n            #ays-quiz-container-37 .ays-quiz-password-toggle-visibility-box {\n                width: 100%;\n            }\n\n\n            \/* Question hint *\/\n            #ays-quiz-container-37 .ays_question_hint_container .ays_question_hint_text {\n                background-color:rgba(212,120,226,0.31);\n                box-shadow: 0 0 15px 3px rgba(0,0,0,0.6);\n                max-width: 270px;\n            }\n\n            #ays-quiz-container-37 .ays_question_hint_container .ays_question_hint_text p {\n                max-width: unset;\n            }\n\n            #ays-quiz-container-37 .ays-quiz-additonal-box {\n                display: flex;\n                justify-content: flex-end;\n                align-items: center;\n                position: relative;  \n            }\n\n            #ays-quiz-container-37 .ays_questions_hint_max_width_class {\n                max-width: 80%;\n            }\n\n            \/* Information form *\/\n            #ays-quiz-container-37 .ays-form-title{\n                color:rgb(0,0,0);\n            }\n\n            \/* Quiz timer *\/\n            #ays-quiz-container-37 div.ays-quiz-redirection-timer,\n            #ays-quiz-container-37 div.ays-quiz-timer{\n                color: #000;\n                text-align: center;\n            }\n\n            #ays-quiz-container-37 div.ays-quiz-timer.ays-quiz-message-before-timer:before {\n                font-weight: 500;\n            }\n\n            \/* Quiz title \/ transformation *\/\n            #ays-quiz-container-37 .ays-fs-title{\n                text-transform: capitalize;\n                font-size: 22px;\n                text-align: center;\n                    text-shadow: none;\n            }\n            \n            \/* Quiz buttons *\/\n            #ays-quiz-container-37 .ays_arrow {\n                color:#000000!important;\n            }\n            #ays-quiz-container-37 input#ays-submit,\n            #ays-quiz-container-37 #ays_finish_quiz_37 .action-button,\n            div#ays-quiz-container-37 #ays_finish_quiz_37 .action-button.ays_restart_button,\n            #ays-quiz-container-37 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn,\n            #ays-quiz-container-37 .ays-quiz-category-selective-submit-bttn {\n                background: none;\n                background-color: rgba(118,0,244,0.63);\n                color:#000000;\n                font-size: 20px;\n                padding: 13px 30px;\n                border-radius: 14px;\n                height: auto;\n                letter-spacing: 0;\n                box-shadow: unset;\n                width: auto;\n                \/* border: unset; *\/\n                min-height: unset;\n                line-height: normal;\n                text-shadow: unset;\n            }\n            #ays-quiz-container-37 input#ays-submit,\n            #ays-quiz-container-37 #ays_finish_quiz_37 input.action-button,\n            #ays-quiz-container-37 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn,\n            #ays-quiz-container-37 .ays-quiz-category-selective-submit-bttn {\n                \n            }\n\n            #ays-quiz-container-37 #ays_finish_quiz_37 .action-button.ays_check_answer {\n                padding: 5px 10px;\n                font-size: 20px !important;\n            }\n            #ays-quiz-container-37 #ays_finish_quiz_37 .action-button.ays_restart_button {\n                white-space: nowrap;\n                padding: 5px 10px;\n                white-space: normal;\n            }\n            #ays-quiz-container-37 input#ays-submit:hover,\n            #ays-quiz-container-37 input#ays-submit:focus,\n            #ays-quiz-container-37 #ays_finish_quiz_37 .action-button:hover,\n            #ays-quiz-container-37 #ays_finish_quiz_37 .action-button:focus,\n            #ays-quiz-container-37 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn:hover,\n            #ays-quiz-container-37 .ays-quiz-category-selective-submit-bttn:hover {\n                background: none;\n                box-shadow: 0 0 0 2px #000000;\n                background-color: rgba(118,0,244,0.63);\n            }\n            #ays-quiz-container-37 .ays_restart_button {\n                color: #000000;\n            }\n            \n            #ays-quiz-container-37 .ays_restart_button_p,\n            #ays-quiz-container-37 .ays_buttons_div {\n                justify-content: center;\n            }\n\n            #ays-quiz-container-37 .ays_finish.action-button{\n                margin: 10px 5px;\n            }\n\n            #ays-quiz-container-37 .ays-share-btn.ays-share-btn-branded {\n                color: #fff;\n                display: inline-block;\n            }\n\n            #ays-quiz-container-37 .ays_quiz_results .ays-field.checked_answer_div.correct_div input:checked+label {\n                background-color: transparent;\n            }\n                        \n            \/* Question answers *\/\n            #ays-quiz-container-37 .ays-field {\n                    border-color: #444;\n                    border-style: solid;\n                    border-width: 2px;\n                    box-shadow: none;flex-direction: row-reverse;\n            }\n            \n\n            \/* Answer maximum length of a text field *\/\n            #ays-quiz-container-37 .ays_quiz_question_text_message{\n                color: #000;\n                text-align: left;\n                font-size: 12px;\n            }\n\n            div#ays-quiz-container-37 div.ays_quiz_question_text_error_message {\n                color: #ff0000;\n            }\n\n            \/* Questions answer image *\/\n            #ays-quiz-container-37 .ays-answer-image {\n                width:15em;\n                height:150px;\n                object-fit: cover;\n            }\n            \n            #ays-quiz-container-37 .ays-quiz-answers .ays-field:hover:not(.ays-answered-text-input){\n                opacity: 1;\n            }\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-field label.ays_answer_caption[for^='ays-answer-'] {\n                z-index: 1;\n                position:initial;bottom:0;}\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-field input~label[for^='ays-answer-'] {\n                padding: 5px;\n            }\n\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-field {\n                margin-bottom: 13px;\n            }\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-field.ays_grid_view_item {\n                width: calc(50% - 6.5px);\n            }\n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-field.ays_grid_view_item:nth-child(odd) {\n                margin-right: 6.5px;\n            }\n            \n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-field input:checked+label:before {\n                border-color: rgba(118,0,244,0.63);\n                background: rgba(118,0,244,0.63);\n                background-clip: content-box;\n            }\n            #ays-quiz-container-37 .ays-quiz-answers div.ays-text-right-answer {\n                color: #000;\n            }\n                        \n            \/* Questions answer right\/wrong icons *\/\n            #ays-quiz-container-37 .ays-field input~label.answered.correct:after{\n                content: url('https:\/\/aiyoit.com\/tutorial\/wp-content\/plugins\/quiz-maker\/public\/images\/correct.png');          }\n            #ays-quiz-container-37 .ays-field input~label.answered.wrong:after{\n                content: url('https:\/\/aiyoit.com\/tutorial\/wp-content\/plugins\/quiz-maker\/public\/images\/wrong.png');\n            }\n            #ays-quiz-container-37 .ays-field label.answered:last-of-type:after{\n                display: none;\n                height: auto;\n                left: 10px;top: 10px;}\n            \/* Dropdown questions *\/            \n            #ays-quiz-container-37 #ays_finish_quiz_37 .ays-field .select2-container--default .select2-selection--single {\n                border-bottom: 2px solid rgba(118,0,244,0.63);\n                background-color: rgba(118,0,244,0.63);\n            }\n            \n            #ays-quiz-container-37 .ays-field .select2-container--default .select2-selection--single .select2-selection__placeholder,\n            #ays-quiz-container-37 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered,\n            #ays-quiz-container-37 .ays-field .select2-container--default .select2-selection--single .select2-selection__arrow {\n                color: #ffffff;\n            }\n\n            #ays-quiz-container-37 .select2-container--default .select2-search--dropdown .select2-search__field:focus,\n            #ays-quiz-container-37 .select2-container--default .select2-search--dropdown .select2-search__field {\n                outline: unset;\n                padding: 0.75rem;\n            }\n\n            #ays-quiz-container-37 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered,\n            #ays-quiz-container-37 .select2-container--default .select2-results__option--highlighted[aria-selected] {\n                background-color: rgba(118,0,244,0.63);\n            }\n\n            #ays-quiz-container-37 .ays-field .select2-container--default,\n            #ays-quiz-container-37 .ays-field .select2-container--default .selection,\n            #ays-quiz-container-37 .ays-field .select2-container--default .dropdown-wrapper,\n            #ays-quiz-container-37 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered,\n            #ays-quiz-container-37 .ays-field .select2-container--default .select2-selection--single .select2-selection__rendered .select2-selection__placeholder,\n            #ays-quiz-container-37 .ays-field .select2-container--default .select2-selection--single .select2-selection__arrow,\n            #ays-quiz-container-37 .ays-field .select2-container--default .select2-selection--single .select2-selection__arrow b[role='presentation'] {\n                font-size: 16px !important;\n            }\n\n            #ays-quiz-container-37 .select2-container--default .select2-results__option {\n                padding: 6px;\n            }\n            \n            \/* Dropdown questions scroll bar *\/\n            #ays-quiz-container-37 .select2-results__options::-webkit-scrollbar {\n                width: 7px;\n            }\n            #ays-quiz-container-37 .select2-results__options::-webkit-scrollbar-track {\n                background-color: rgba(212,120,226,0.31);\n            }\n            #ays-quiz-container-37 .select2-results__options::-webkit-scrollbar-thumb {\n                transition: .3s ease-in-out;\n                background-color: rgba(0,0,0,0.55);\n            }\n            #ays-quiz-container-37 .select2-results__options::-webkit-scrollbar-thumb:hover {\n                transition: .3s ease-in-out;\n                background-color: rgba(0,0,0,0.85);\n            }\n\n            \/* Audio \/ Video *\/\n            #ays-quiz-container-37 .mejs-container .mejs-time{\n                box-sizing: unset;\n            }\n            #ays-quiz-container-37 .mejs-container .mejs-time-rail {\n                padding-top: 15px;\n            }\n\n            #ays-quiz-container-37 .mejs-container .mejs-mediaelement video {\n                margin: 0;\n            }\n\n            \/* Limitation *\/\n            #ays-quiz-container-37 .ays-quiz-limitation-count-of-takers {\n                padding: 50px;\n            }\n\n            #ays-quiz-container-37 div.ays-quiz-results-toggle-block span.ays-show-res-toggle.ays-res-toggle-show,\n            #ays-quiz-container-37 div.ays-quiz-results-toggle-block span.ays-show-res-toggle.ays-res-toggle-hide{\n                color: #000;\n            }\n\n            #ays-quiz-container-37 div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle {\n                border: 1px solid #000;\n            }\n\n            #ays-quiz-container-37 div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle {\n                border: 1px solid #000;\n            }\n\n            #ays-quiz-container-37 div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle:after{\n                background: #000;\n            }\n\n            #ays-quiz-container-37.ays_quiz_elegant_dark div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle:after,\n            #ays-quiz-container-37.ays_quiz_rect_dark div.ays-quiz-results-toggle-block input:checked + label.ays_switch_toggle:after{\n                background: #000;\n            }\n\n            \/* Hestia theme (Version: 3.0.16) | Start *\/\n            #ays-quiz-container-37 .mejs-container .mejs-inner .mejs-controls .mejs-button > button:hover,\n            #ays-quiz-container-37 .mejs-container .mejs-inner .mejs-controls .mejs-button > button {\n                box-shadow: unset;\n                background-color: transparent;\n            }\n            #ays-quiz-container-37 .mejs-container .mejs-inner .mejs-controls .mejs-button > button {\n                margin: 10px 6px;\n            }\n            \/* Hestia theme (Version: 3.0.16) | End *\/\n\n            \/* Go theme (Version: 1.4.3) | Start *\/\n            #ays-quiz-container-37 label[for^='ays-answer']:before,\n            #ays-quiz-container-37 label[for^='ays-answer']:before {\n                -webkit-mask-image: unset;\n                mask-image: unset;\n            }\n\n            #ays-quiz-container-37.ays_quiz_classic_light .ays-field input:checked+label.answered.correct:before,\n            #ays-quiz-container-37.ays_quiz_classic_dark .ays-field input:checked+label.answered.correct:before {\n                background-color: rgba(118,0,244,0.63) !important;\n                background-color: rgba(39,174,96, 1) !important;\n            }\n            \/* Go theme (Version: 1.4.3) | End *\/\n\n            #ays-quiz-container-37 .ays_quiz_results fieldset.ays_fieldset .ays_quiz_question .wp-video {\n                width: 100% !important;\n                max-width: 100%;\n            }\n\n            \/* Classic Dark \/ Classic Light *\/\n            \/* Dropdown questions right\/wrong styles *\/\n            #ays-quiz-container-37.ays_quiz_classic_dark .correct_div,\n            #ays-quiz-container-37.ays_quiz_classic_light .correct_div{\n                border-color:green !important;\n                opacity: 1 !important;\n                background-color: rgba(39,174,96,0.4) !important;\n            }\n            #ays-quiz-container-37.ays_quiz_classic_dark .correct_div .selected-field,\n            #ays-quiz-container-37.ays_quiz_classic_light .correct_div .selected-field {\n                padding: 0px 10px 0px 10px;\n                color: green !important;\n            }\n\n            #ays-quiz-container-37.ays_quiz_classic_dark .wrong_div,\n            #ays-quiz-container-37.ays_quiz_classic_light .wrong_div{\n                border-color:red !important;\n                opacity: 1 !important;\n                background-color: rgba(243,134,129,0.4) !important;\n            }\n            #ays-quiz-container-37.ays_quiz_classic_dark .ays-field.checked_answer_div.wrong_div input:checked~label,\n            #ays-quiz-container-37.ays_quiz_classic_light .ays-field.checked_answer_div.wrong_div input:checked~label {\n                background-color: rgba(243,134,129,0.4) !important;\n            }\n            #ays-quiz-container-37.ays_quiz_classic_dark .ays-field,\n            #ays-quiz-container-37.ays_quiz_classic_light .ays-field {\n                text-align: left;\n                \/*margin-bottom: 10px;*\/\n                padding: 0;\n                transition: .3s ease-in-out;\n            }\n\n            #ays-quiz-container-37 .ays-quiz-close-full-screen {\n                fill: #000;\n            }\n\n            #ays-quiz-container-37 .ays-quiz-open-full-screen {\n                fill: #000;\n            }\n\n            #ays-quiz-container-37 .ays_quiz_login_form p{\n                color: #000;\n            }\n\n            \/* report questions modal start *\/\n            .ays-modal-reports {\n                display: none;\n                position: fixed;\n                z-index: 9999;\n                left: 0;\n                top: 0;\n                width: 100%;\n                height: 100%;\n                overflow: auto;\n                background-color: rgba(0, 0, 0, 0.4);\n                animation-duration: .5s;\n                background-color: rgba(0, 0, 0, 0.4);\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-modal-content-reports {\n                background-color: #fefefe;\n                margin: 10% auto;\n                border: 1px solid #888;\n                max-width: 500px;\n                width: 100%;\n                border-radius: 10px;\n                padding: 20px;\n                box-sizing: border-box;\n                position: relative;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-modal-content-reports label{\n                display: block;\n                margin-bottom: 10px;\n                font-weight: bold;\n                letter-spacing: normal;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-modal-content-reports textarea {\n                display: block;\n                width: 100%;\n                height: 100px;\n                padding: 5px;\n                box-sizing: border-box;\n                border-radius: 5px;\n                border: 1px solid #ccc;\n                max-width: 100%;\n                max-height: 500px;\n                resize: vertical;\n                transition: unset;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-modal-content-reports input.ays-quiz-submit-question-report {\n                background-color: #0073aa;\n                color: #fff !important;\n                border: none;\n                border-radius: 5px;\n                padding: 10px 20px;\n                cursor: pointer;\n                margin-top: 20px;\n                line-height: normal;\n                letter-spacing: normal;\n                box-shadow: unset;\n                background-image: unset;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-close-reports-window {\n                color: #aaa;\n                font-weight: bold;\n                position: absolute;\n                top: 1%;\n                right: 1%;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-close-reports-window img {\n                box-shadow: unset;\n            }\n            \n            #ays-quiz-question-report-modal-37 .ays-quiz-preloader img {\n                box-shadow: unset;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-close-reports-window img:hover,\n            #ays-quiz-question-report-modal-37 .ays-close-reports-window img:focus {\n                cursor: pointer;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-quiz-question-report-error {\n                display: none;\n                font-size: 13px;\n                color: #f00;\n                text-align: left;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-quiz-question-report-textarea-label,\n            #ays-quiz-question-report-modal-37 .ays-quiz-question-report-title {\n                text-align: left;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays_quiz_modal_overlay {\n                width: 100%;\n                height: 100%;\n                position: fixed;\n                top: 0;\n                left: 0;\n                position: absolute;\n                z-index: 1000000000;\n                flex-direction: column;\n            }\n\n            #ays-quiz-question-report-modal-37 .ays-quiz-container .ays-quiz-user-c\u0570oosing-anonymous-assessment {\n                margin: 10px 0;\n            }\n\n            \/* report questions modal end *\/\n\n            @media screen and (max-width: 768px){\n                #ays-quiz-container-37{\n                    max-width: 100%;\n                }\n\n                div#ays-quiz-container-37 [id^='ays_finish_quiz_'] div.step div.ays-abs-fs {\n                    width: 90%;\n                }\n\n                #ays-quiz-container-37 .ays_quiz_question p {\n                    font-size: 18px;\n                }\n\n                #ays-quiz-container-37 .select2-container,\n                #ays-quiz-container-37 .ays-field * {\n                    font-size: 18px !important;\n                }\n\n                div#ays-quiz-container-37 input#ays-submit,\n                div#ays-quiz-container-37 #ays_finish_quiz_37 .action-button,\n                div#ays-quiz-container-37 #ays_finish_quiz_37 .action-button.ays_restart_button,\n                #ays-quiz-container-37 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn,\n                #ays-quiz-container-37 .ays-quiz-category-selective-submit-bttn {\n                    font-size: 20px;\n                }\n\n                \/* Quiz title \/ mobile font size *\/\n                div#ays-quiz-container-37 .ays-fs-title {\n                    font-size: 22px;\n                }\n\n                \/* Question explanation \/ mobile font size *\/\n                #ays-quiz-container-37 .ays_questtion_explanation p {\n                    font-size:18px;\n                }\n\n                \/* Wrong answers \/ mobile font size *\/\n                #ays-quiz-container-37 .wrong_answer_text p {\n                    font-size:18px;\n                }\n\n                \/* Right answers \/ mobile font size *\/\n                #ays-quiz-container-37 .right_answer_text p {\n                    font-size:16px;\n                }\n\n                \/* Note text \/ mobile font size *\/\n                #ays-quiz-container-37 .ays-quiz-question-note-message-box p {\n                    font-size:14px;\n                }\n\n                div#ays-quiz-container-37 .ays-quiz-question-note-message-box *:not(strong) {\n                    text-transform:none;\n                    text-decoration: none;\n                    letter-spacing: 0px;\n                    font-weight: normal;\n                }\n\n                div#ays-quiz-container-37 .ays_questtion_explanation *:not(strong) {\n                    text-transform:none;\n                    text-decoration: none;\n                    letter-spacing: 0px;\n                    font-weight: normal;\n                }\n\n                div#ays-quiz-container-37 .right_answer_text *:not(strong) {\n                    text-transform:none;\n                    text-decoration: none;\n                    letter-spacing: 0px;\n                    font-weight: normal;\n                }\n\n                div#ays-quiz-container-37 .wrong_answer_text *:not(strong) {\n                    text-transform:none;\n                    text-decoration: none;\n                    letter-spacing: 0px;\n                    font-weight: normal;\n                }\n            }\n            \/* Custom css styles *\/\n            \n            \n            \/* RTL direction styles *\/\n            \n        <\/style>\n            <style>\n                #ays-quiz-container-37 p {\n                    margin: 0.625em;\n                }\n                \n                #ays-quiz-container-37 .ays-field.checked_answer_div input:checked~label {\n                    background-color: rgba(118,0,244,0.63);\n                }\n\n                #ays-quiz-container-37.ays_quiz_classic_light  .ays_quiz_results .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-37.ays_quiz_classic_dark  .ays_quiz_results .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-37.ays_quiz_classic_light  .enable_correction .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-37.ays_quiz_classic_dark  .enable_correction .ays-field.checked_answer_div input:checked~label {\n                    background-color: transparent;\n                }\n\n                #ays-quiz-container-37.ays_quiz_classic_light  .ays_quiz_results .not_influence_to_score .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-37.ays_quiz_classic_dark  .ays_quiz_results .not_influence_to_score .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-37.ays_quiz_classic_light  .enable_correction .not_influence_to_score .ays-field.checked_answer_div input:checked~label,\n                #ays-quiz-container-37.ays_quiz_classic_dark  .enable_correction .not_influence_to_score .ays-field.checked_answer_div input:checked~label {\n                    background-color: rgba(118,0,244,0.63);\n                }\n                \n                #ays-quiz-container-37 .ays-field.checked_answer_div input:checked~label:hover {\n                    background-color: rgba(118,0,244,0.63);\n                }\n\n                #ays-quiz-container-37.ays-quiz-container.ays_quiz_classic_light .ays-questions-container .ays-field:hover label[for^='ays-answer-'],\n                #ays-quiz-container-37 .ays-field:hover:not(.ays-answered-text-input){\n                    background: rgba(118,0,244,0.63);\n                    \/* border-radius: 4px; *\/\n                    color: #fff;\n                    transition: all .3s;\n                }\n                #ays-quiz-container-37 #ays_finish_quiz_37 .action-button:hover,\n                #ays-quiz-container-37 #ays_finish_quiz_37 .action-button:focus,\n                #ays-quiz-container-37 + .ays-quiz-category-selective-main-container .ays-quiz-category-selective-restart-bttn:hover,\n                #ays-quiz-container-37 .ays-quiz-category-selective-submit-bttn:focus {\n                    box-shadow: 0 0 0 2px white, 0 0 0 3px rgba(118,0,244,0.63);\n                    background: rgba(118,0,244,0.63);\n                }\n            <\/style><script>\n                if(typeof aysQuizOptions === 'undefined'){\n                    var aysQuizOptions = [];\n                }\n                aysQuizOptions['37']  = 'eyJxdWl6X3ZlcnNpb24iOiI2LjMuOS45IiwiY29yZV92ZXJzaW9uIjoiNi4xLjQiLCJwaHBfdmVyc2lvbiI6IjcuNC4zMyIsImNvbG9yIjoicmdiYSgxMTgsMCwyNDQsMC42MykiLCJiZ19jb2xvciI6InJnYmEoMjEyLDEyMCwyMjYsMC4zMSkiLCJ0ZXh0X2NvbG9yIjoiIzAwMCIsImhlaWdodCI6NDAwLCJ3aWR0aCI6MCwiZW5hYmxlX2xvZ2dlZF91c2VycyI6Im9mZiIsImluZm9ybWF0aW9uX2Zvcm0iOiJiZWZvcmUiLCJmb3JtX25hbWUiOiJvbiIsImZvcm1fZW1haWwiOiJvbiIsImZvcm1fcGhvbmUiOiJvbiIsImltYWdlX3dpZHRoIjoiIiwiaW1hZ2VfaGVpZ2h0IjoiIiwiZW5hYmxlX2NvcnJlY3Rpb24iOiJvZmYiLCJlbmFibGVfcHJvZ3Jlc3NfYmFyIjoib24iLCJlbmFibGVfcXVlc3Rpb25zX3Jlc3VsdCI6Im9uIiwicmFuZG9taXplX3F1ZXN0aW9ucyI6Im9uIiwicmFuZG9taXplX2Fuc3dlcnMiOiJvZmYiLCJlbmFibGVfcXVlc3Rpb25zX2NvdW50ZXIiOiJvbiIsImVuYWJsZV9yZXN0cmljdGlvbl9wYXNzIjoib2ZmIiwicmVzdHJpY3Rpb25fcGFzc19tZXNzYWdlIjoiIiwidXNlcl9yb2xlIjpbXSwiY3VzdG9tX2NzcyI6IiIsImxpbWl0X3VzZXJzIjoib2ZmIiwibGltaXRhdGlvbl9tZXNzYWdlIjoiIiwicmVkaXJlY3RfdXJsIjoiIiwicmVkaXJlY3Rpb25fZGVsYXkiOjAsImFuc3dlcnNfdmlldyI6Imxpc3QiLCJlbmFibGVfcnRsX2RpcmVjdGlvbiI6Im9mZiIsImVuYWJsZV9sb2dnZWRfdXNlcnNfbWVzc2FnZSI6IiIsInF1ZXN0aW9uc19jb3VudCI6IiIsImVuYWJsZV9xdWVzdGlvbl9iYW5rIjoib2ZmIiwiZW5hYmxlX2xpdmVfcHJvZ3Jlc3NfYmFyIjoib2ZmIiwiZW5hYmxlX3BlcmNlbnRfdmlldyI6Im9mZiIsImVuYWJsZV9hdmVyYWdlX3N0YXRpc3RpY2FsIjoib2ZmIiwiZW5hYmxlX25leHRfYnV0dG9uIjoib24iLCJlbmFibGVfcHJldmlvdXNfYnV0dG9uIjoib24iLCJlbmFibGVfYXJyb3dzIjoib2ZmIiwidGltZXJfdGV4dCI6IkRvIG5vdCB3YXN0ZSB5b3VyIHRpbWUgb24gb25seSBvbmUgcXVlc3Rpb24iLCJxdWl6X3RoZW1lIjoiY2xhc3NpY19saWdodCIsImVuYWJsZV9zb2NpYWxfYnV0dG9ucyI6Im9mZiIsInJlc3VsdF90ZXh0IjoiIiwiZW5hYmxlX3Bhc3NfY291bnQiOiJvZmYiLCJoaWRlX3Njb3JlIjoib24iLCJyYXRlX2Zvcm1fdGl0bGUiOiIiLCJib3hfc2hhZG93X2NvbG9yIjoiIzAwMCIsInF1aXpfYm9yZGVyX3JhZGl1cyI6IjAiLCJxdWl6X2JnX2ltYWdlIjoiIiwicXVpel9ib3JkZXJfd2lkdGgiOiIxIiwicXVpel9ib3JkZXJfc3R5bGUiOiJzb2xpZCIsInF1aXpfYm9yZGVyX2NvbG9yIjoiIzAwMCIsInF1aXpfbG9hZGVyIjoiaG91cmdsYXNzIiwiY3JlYXRlX2RhdGUiOm51bGwsImF1dGhvciI6IntcImlkXCI6XCIzXCIsXCJuYW1lXCI6XCJWaW5heSBTaW5naFwifSIsInF1ZXN0X2FuaW1hdGlvbiI6Im5vbmUiLCJmb3JtX3RpdGxlIjoiUGxlYXNlIGZpbGwgeW91ciByZXF1aXJlZCogaW5mb3JtYXRpb24iLCJlbmFibGVfYmdfbXVzaWMiOiJvZmYiLCJxdWl6X2JnX211c2ljIjoiIiwiYW5zd2Vyc19mb250X3NpemUiOjE4LCJzaG93X2NyZWF0ZV9kYXRlIjoib2ZmIiwic2hvd19hdXRob3IiOiJvZmYiLCJlbmFibGVfZWFybHlfZmluaXNoIjoib2ZmIiwiYW5zd2Vyc19yd190ZXh0cyI6Im9uX3Bhc3NpbmciLCJkaXNhYmxlX3N0b3JlX2RhdGEiOiJvZmYiLCJlbmFibGVfYmFja2dyb3VuZF9ncmFkaWVudCI6Im9uIiwiYmFja2dyb3VuZF9ncmFkaWVudF9jb2xvcl8xIjoicmdiYSgxNjUsMTA0LDIyNiwwLjI2KSIsImJhY2tncm91bmRfZ3JhZGllbnRfY29sb3JfMiI6IiNmZmYiLCJxdWl6X2dyYWRpZW50X2RpcmVjdGlvbiI6InZlcnRpY2FsIiwicmVkaXJlY3RfYWZ0ZXJfc3VibWl0Ijoib2ZmIiwic3VibWl0X3JlZGlyZWN0X3VybCI6IiIsInN1Ym1pdF9yZWRpcmVjdF9kZWxheSI6IjAiLCJwcm9ncmVzc19iYXJfc3R5bGUiOiJmaXJzdCIsImVuYWJsZV9leGl0X2J1dHRvbiI6Im9mZiIsImV4aXRfcmVkaXJlY3RfdXJsIjoiIiwiaW1hZ2Vfc2l6aW5nIjoiY292ZXIiLCJxdWl6X2JnX2ltYWdlX3Bvc2l0aW9uIjoiY2VudGVyIGNlbnRlciIsImN1c3RvbV9jbGFzcyI6IiIsImVuYWJsZV9zb2NpYWxfbGlua3MiOiJvZmYiLCJzb2NpYWxfbGlua3MiOnsibGlua2VkaW5fbGluayI6IiIsImZhY2Vib29rX2xpbmsiOiIiLCJ0d2l0dGVyX2xpbmsiOiIiLCJ2a29udGFrdGVfbGluayI6IiIsImluc3RhZ3JhbV9saW5rIjoiIiwieW91dHViZV9saW5rIjoiIiwiYmVoYW5jZV9saW5rIjoiIn0sInNob3dfcXVpel90aXRsZSI6Im9uIiwic2hvd19xdWl6X2Rlc2MiOiJvbiIsInNob3dfbG9naW5fZm9ybSI6Im9mZiIsIm1vYmlsZV9tYXhfd2lkdGgiOiIiLCJsaW1pdF91c2Vyc19ieSI6ImlwIiwiYWN0aXZlX2RhdGVfY2hlY2siOiJvZmYiLCJhY3RpdmVJbnRlcnZhbCI6IjIwMjMtMTEtMTEgMDk6MDk6MjgiLCJkZWFjdGl2ZUludGVydmFsIjoiMjAyMy0xMS0xMSAwOTowOToyOCIsImFjdGl2ZV9kYXRlX3ByZV9zdGFydF9tZXNzYWdlIjoiVGhlIHF1aXogd2lsbCBiZSBhdmFpbGFibGUgc29vbiEiLCJhY3RpdmVfZGF0ZV9tZXNzYWdlIjoiVGhlIHF1aXogaGFzIGV4cGlyZWQhIiwiZXhwbGFuYXRpb25fdGltZSI6IjQiLCJlbmFibGVfY2xlYXJfYW5zd2VyIjoib2ZmIiwic2hvd19jYXRlZ29yeSI6Im9mZiIsInNob3dfcXVlc3Rpb25fY2F0ZWdvcnkiOiJvZmYiLCJkaXNwbGF5X3Njb3JlIjoiYnlfcGVyY2FudGFnZSIsImVuYWJsZV9yd19hc253ZXJzX3NvdW5kcyI6Im9mZiIsImFuc19yaWdodF93cm9uZ19pY29uIjoiZGVmYXVsdCIsInF1aXpfYmdfaW1nX2luX2ZpbmlzaF9wYWdlIjoib2ZmIiwiZmluaXNoX2FmdGVyX3dyb25nX2Fuc3dlciI6Im9mZiIsImFmdGVyX3RpbWVyX3RleHQiOiIiLCJlbmFibGVfZW50ZXJfa2V5Ijoib24iLCJidXR0b25zX3RleHRfY29sb3IiOiIjMDAwMDAwIiwiYnV0dG9uc19wb3NpdGlvbiI6ImNlbnRlciIsInNob3dfcXVlc3Rpb25zX2V4cGxhbmF0aW9uIjoib25fcmVzdWx0c19wYWdlIiwiZW5hYmxlX2F1ZGlvX2F1dG9wbGF5Ijoib2ZmIiwiYnV0dG9uc19zaXplIjoibGFyZ2UiLCJidXR0b25zX2ZvbnRfc2l6ZSI6IjIwIiwiYnV0dG9uc193aWR0aCI6IiIsImJ1dHRvbnNfbGVmdF9yaWdodF9wYWRkaW5nIjoiMzAiLCJidXR0b25zX3RvcF9ib3R0b21fcGFkZGluZyI6IjEzIiwiYnV0dG9uc19ib3JkZXJfcmFkaXVzIjoiMTQiLCJlbmFibGVfbGVhdmVfcGFnZSI6Im9uIiwiZW5hYmxlX3RhY2tlcnNfY291bnQiOiJvZmYiLCJ0YWNrZXJzX2NvdW50IjoiIiwicGFzc19zY29yZSI6MCwicGFzc19zY29yZV9tZXNzYWdlIjoiPGg0IHN0eWxlPVwidGV4dC1hbGlnbjogY2VudGVyXCI+Q29uZ3JhdHVsYXRpb25zITxcL2g0PlxyXG48cCBzdHlsZT1cInRleHQtYWxpZ246IGNlbnRlclwiPllvdSBwYXNzZWQgdGhlIHF1aXohPFwvcD4iLCJmYWlsX3Njb3JlX21lc3NhZ2UiOiI8aDQgc3R5bGU9XCJ0ZXh0LWFsaWduOiBjZW50ZXJcIj5Pb3BzITxcL2g0PlxyXG48cCBzdHlsZT1cInRleHQtYWxpZ246IGNlbnRlclwiPllvdSBoYXZlIG5vdCBwYXNzZWQgdGhlIHF1aXohXHJcblRyeSBhZ2FpbiE8XC9wPiIsInF1ZXN0aW9uX2ZvbnRfc2l6ZSI6MTgsInF1aXpfd2lkdGhfYnlfcGVyY2VudGFnZV9weCI6InBlcmNlbnRhZ2UiLCJxdWVzdGlvbnNfaGludF9pY29uX29yX3RleHQiOiJkZWZhdWx0IiwicXVlc3Rpb25zX2hpbnRfdmFsdWUiOiIiLCJlbmFibGVfZWFybHlfZmluc2hfY29tZmlybV9ib3giOiJvbiIsImVuYWJsZV9xdWVzdGlvbnNfb3JkZXJpbmdfYnlfY2F0Ijoib2ZmIiwic2hvd19zY2hlZHVsZV90aW1lciI6Im9mZiIsInNob3dfdGltZXJfdHlwZSI6ImNvdW50ZG93biIsInF1aXpfbG9hZGVyX3RleHRfdmFsdWUiOiIiLCJoaWRlX2NvcnJlY3RfYW5zd2VycyI6Im9mZiIsInNob3dfaW5mb3JtYXRpb25fZm9ybSI6Im9uIiwicXVpel9sb2FkZXJfY3VzdG9tX2dpZiI6IiIsImRpc2FibGVfaG92ZXJfZWZmZWN0Ijoib2ZmIiwicXVpel9sb2FkZXJfY3VzdG9tX2dpZl93aWR0aCI6MTAwLCJwcm9ncmVzc19saXZlX2Jhcl9zdHlsZSI6ImRlZmF1bHQiLCJxdWl6X3RpdGxlX3RyYW5zZm9ybWF0aW9uIjoiY2FwaXRhbGl6ZSIsInNob3dfYW5zd2Vyc19udW1iZXJpbmciOiJhLiIsInF1aXpfaW1hZ2Vfd2lkdGhfYnlfcGVyY2VudGFnZV9weCI6InBpeGVscyIsInF1aXpfaW1hZ2VfaGVpZ2h0IjoiIiwicXVpel9iZ19pbWdfb25fc3RhcnRfcGFnZSI6Im9mZiIsInF1aXpfYm94X3NoYWRvd194X29mZnNldCI6MCwicXVpel9ib3hfc2hhZG93X3lfb2Zmc2V0IjowLCJxdWl6X2JveF9zaGFkb3dfel9vZmZzZXQiOjE1LCJxdWl6X3F1ZXN0aW9uX3RleHRfYWxpZ25tZW50IjoiY2VudGVyIiwicXVpel9hcnJvd190eXBlIjoiZGVmYXVsdCIsInF1aXpfc2hvd193cm9uZ19hbnN3ZXJzX2ZpcnN0Ijoib24iLCJxdWl6X2Rpc3BsYXlfYWxsX3F1ZXN0aW9ucyI6Im9mZiIsInF1aXpfdGltZXJfcmVkX3dhcm5pbmciOiJvZmYiLCJxdWl6X3NjaGVkdWxlX3RpbWV6b25lIjoiVVRDKzUuNSIsInF1ZXN0aW9uc19oaW50X2J1dHRvbl92YWx1ZSI6IiIsInF1aXpfdGFja2Vyc19tZXNzYWdlIjoiVGhpcyBxdWl6IGlzIGV4cGlyZWQhIiwicXVpel9lbmFibGVfbGlua2VkaW5fc2hhcmVfYnV0dG9uIjoib24iLCJxdWl6X2VuYWJsZV9mYWNlYm9va19zaGFyZV9idXR0b24iOiJvbiIsInF1aXpfZW5hYmxlX3R3aXR0ZXJfc2hhcmVfYnV0dG9uIjoib24iLCJxdWl6X21ha2VfcmVzcG9uc2VzX2Fub255bW91cyI6Im9mZiIsInF1aXpfbWFrZV9hbGxfcmV2aWV3X2xpbmsiOiJvZmYiLCJzaG93X3F1ZXN0aW9uc19udW1iZXJpbmciOiIxLiIsInF1aXpfbWVzc2FnZV9iZWZvcmVfdGltZXIiOiIiLCJlbmFibGVfcGFzc3dvcmQiOiJvZmYiLCJwYXNzd29yZF9xdWl6IjoiIiwicXVpel9wYXNzd29yZF9tZXNzYWdlIjoiIiwiZW5hYmxlX3NlZV9yZXN1bHRfY29uZmlybV9ib3giOiJvZmYiLCJkaXNwbGF5X2ZpZWxkc19sYWJlbHMiOiJvZmYiLCJlbmFibGVfZnVsbF9zY3JlZW5fbW9kZSI6Im9uIiwicXVpel9lbmFibGVfcGFzc3dvcmRfdmlzaWJpbGl0eSI6Im9mZiIsInF1ZXN0aW9uX21vYmlsZV9mb250X3NpemUiOjE4LCJhbnN3ZXJzX21vYmlsZV9mb250X3NpemUiOjE4LCJzb2NpYWxfYnV0dG9uc19oZWFkaW5nIjoiIiwicXVpel9lbmFibGVfdmtvbnRha3RlX3NoYXJlX2J1dHRvbiI6Im9uIiwiYW5zd2Vyc19ib3JkZXIiOiJvbiIsImFuc3dlcnNfYm9yZGVyX3dpZHRoIjoyLCJhbnN3ZXJzX2JvcmRlcl9zdHlsZSI6InNvbGlkIiwiYW5zd2Vyc19ib3JkZXJfY29sb3IiOiIjNDQ0Iiwic29jaWFsX2xpbmtzX2hlYWRpbmciOiIiLCJxdWl6X2VuYWJsZV9xdWVzdGlvbl9jYXRlZ29yeV9kZXNjcmlwdGlvbiI6Im9mZiIsImFuc3dlcnNfbWFyZ2luIjoxMywicXVpel9tZXNzYWdlX2JlZm9yZV9yZWRpcmVjdF90aW1lciI6IiIsImJ1dHRvbnNfbW9iaWxlX2ZvbnRfc2l6ZSI6MjAsImFuc3dlcnNfYm94X3NoYWRvdyI6Im9mZiIsImFuc3dlcnNfYm94X3NoYWRvd19jb2xvciI6IiMwMDAiLCJxdWl6X2Fuc3dlcl9ib3hfc2hhZG93X3hfb2Zmc2V0IjowLCJxdWl6X2Fuc3dlcl9ib3hfc2hhZG93X3lfb2Zmc2V0IjowLCJxdWl6X2Fuc3dlcl9ib3hfc2hhZG93X3pfb2Zmc2V0IjoxMCwicXVpel9jcmVhdGVfYXV0aG9yIjozLCJxdWl6X2VuYWJsZV90aXRsZV90ZXh0X3NoYWRvdyI6Im9mZiIsInF1aXpfdGl0bGVfdGV4dF9zaGFkb3dfY29sb3IiOiIjMzMzIiwicXVpel90aXRsZV90ZXh0X3NoYWRvd194X29mZnNldCI6MiwicXVpel90aXRsZV90ZXh0X3NoYWRvd195X29mZnNldCI6MiwicXVpel90aXRsZV90ZXh0X3NoYWRvd196X29mZnNldCI6MiwicXVpel9zaG93X29ubHlfd3JvbmdfYW5zd2VycyI6Im9mZiIsInF1aXpfdGl0bGVfZm9udF9zaXplIjoyMiwicXVpel90aXRsZV9tb2JpbGVfZm9udF9zaXplIjoyMiwicXVpel9wYXNzd29yZF93aWR0aCI6IiIsInF1aXpfcmV2aWV3X3BsYWNlaG9sZGVyX3RleHQiOiIiLCJxdWl6X21ha2VfcmV2aWV3X3JlcXVpcmVkIjoib2ZmIiwicXVpel9lbmFibGVfcmVzdWx0c190b2dnbGUiOiJvZmYiLCJxdWl6X3Jldmlld190aGFua195b3VfbWVzc2FnZSI6IiIsInF1aXpfcmV2aWV3X2VuYWJsZV9jb21tZW50X2ZpZWxkIjoib24iLCJxdWVzdF9leHBsYW5hdGlvbl9mb250X3NpemUiOjE4LCJxdWVzdF9leHBsYW5hdGlvbl9tb2JpbGVfZm9udF9zaXplIjoxOCwicXVpel93YWl0aW5nX3RpbWUiOiJvZmYiLCJ3cm9uZ19hbnN3ZXJzX2ZvbnRfc2l6ZSI6MTgsIndyb25nX2Fuc3dlcnNfbW9iaWxlX2ZvbnRfc2l6ZSI6MTgsInJlcXVpcmVkX2ZpZWxkcyI6WyJheXNfdXNlcl9uYW1lIiwiYXlzX3VzZXJfcGhvbmUiXSwiZW5hYmxlX3RpbWVyIjoib24iLCJlbmFibGVfcXVpel9yYXRlIjoib2ZmIiwiZW5hYmxlX3JhdGVfYXZnIjoib2ZmIiwiZW5hYmxlX2JveF9zaGFkb3ciOiJvbiIsImVuYWJsZV9ib3JkZXIiOiJvZmYiLCJxdWl6X3RpbWVyX2luX3RpdGxlIjoib2ZmIiwiZW5hYmxlX3JhdGVfY29tbWVudHMiOiJvZmYiLCJlbmFibGVfcmVzdGFydF9idXR0b24iOiJvZmYiLCJhdXRvZmlsbF91c2VyX2RhdGEiOiJvbiIsInRpbWVyIjozMDAwLCJxdWl6X2JnX2ltZ19kdXJpbmdfdGhlX3F1aXoiOiJvZmYiLCJzaG93X2Fuc3dlcnNfY2FwdGlvbiI6Im9uIiwicXVpel9lbmFibGVfa2V5Ym9hcmRfbmF2aWdhdGlvbiI6Im9uIiwic2hvd19xdWl6X2ltYWdlIjoib24iLCJxdWl6X2VuYWJsZV9xdWl6X2NhdGVnb3J5X2Rlc2NyaXB0aW9uIjoib2ZmIiwicXVpel9lbmFibGVfdXNlcl9jXHUwNTcwb29zaW5nX2Fub255bW91c19hc3Nlc3NtZW50Ijoib2ZmIiwic3VibWl0X3JlZGlyZWN0X2FmdGVyIjoiIiwicndfYW5zd2Vyc19zb3VuZHMiOmZhbHNlLCJpZCI6IjM3IiwidGl0bGUiOiJVUFAiLCJkZXNjcmlwdGlvbiI6IkhlbGxvIGZyaWVuZCwgd2VsY29tZSB0byB0aGlzIGNvbXB1dGVyIHF1aXogXHUyMDEzIEFJWU8gSVQgLFlvdSBoYXZlIDUwIHF1ZXN0aW9ucyBhbmQgNTAgbWludXRlcyBmb3IgdGhlIHdob2xlIHF1ZXN0aW9ucywgSG9wZSB5b3UgaGF2ZSBjb21lIHByZXBhcmVkIGJlZm9yZWhhbmQsIEkgd2lzaCB5b3UgZ29vZCBsdWNrLCB5b3Ugd2lsbCBkbyB3ZWxsLi4iLCJxdWl6X2ltYWdlIjoiaHR0cHM6XC9cL2FpeW9pdC5jb21cL3R1dG9yaWFsXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8xMlwvY3JvcHBlZC1GYXZlLUljb24ucG5nIiwicXVpel9jYXRlZ29yeV9pZCI6IjIzIiwicXVlc3Rpb25faWRzIjoiNzQ4LDc0Nyw3NDYsNzQ1LDc0NCw3NDIsNzQzLDc0MSw3NDAsNzM5LDczOCw3MzcsNzM2LDczNSw3MzQsNzMzLDczMiw3MzEsNzMwLDcyOSw3MjgsNzI3LDcyNiw3MjUsNzI0LDcyMyw3MjIsNzIxLDcyMCw3MTksNzE4LDcxNyw3MTYsNzE1LDcxNCw3MTMsNzEyLDcxMCw3MTEsNzA5LDcwOCw3MDcsNzA2LDcwNSw3MDQsNzAzLDcwMiw3MDEsNzAwLDY0NCIsIm9yZGVyaW5nIjoiMzEiLCJwdWJsaXNoZWQiOiIxIiwiaW50ZXJ2YWxzIjpudWxsLCJhdXRob3JfaWQiOiIwIiwicXVpel91cmwiOm51bGwsImN1c3RvbV9wb3N0X2lkIjpudWxsLCJxdWl6X2FuaW1hdGlvbl90b3AiOjEwMCwicXVpel9lbmFibGVfYW5pbWF0aW9uX3RvcCI6Im9uIn0=';\n        <\/script>\n                    <input type='hidden' name='quiz_id' value='37'\/>\n                    <input type='hidden' name='start_date' class='ays-start-date'\/>\n                <\/form><\/div>\n                            <\/div>\n                            \n","protected":false},"excerpt":{"rendered":"<p>Computer \u0938\u0947 \u0938\u092e\u094d\u092c\u0928\u094d\u0927\u093f\u0924 \u0935\u094b \u0938\u092d\u0940 Question \u091c\u094b \u092c\u0939\u0941\u0924 \u0939\u0940 \u092e\u0939\u0924\u094d\u0935\u092a\u0942\u0930\u094d\u0923 \u0939\u0948 \u0914\u0930 \u0938\u092d\u0940 \u092a\u094d\u0930\u0915\u093e\u0930 \u0915\u0940 \u092a\u094d\u0930\u0924\u093f\u092f\u094b\u0917\u0940 \u092a\u0930\u0940\u0915\u094d\u0937\u093e \u0915\u0947 \u0932\u093f\u092f\u0947 \u0909\u092a\u092f\u094b\u0917\u0940 \u0939\u0948\u0902\u0964 \u0938\u092d\u0940 \u092a\u094d\u0930\u0915\u093e\u0930 \u0915\u0940 \u092a\u094d\u0930\u0924\u093f\u092f\u094b\u0917\u0940 \u092a\u0930\u0940\u0915\u094d\u0937\u093e \u091c\u0948\u0938\u0947 SSC, IBPS Clerk, IBPS PO, RBI, TET, CTET,CCC,UPP etc. \u092e\u0947\u0902 \u092a\u0942\u091b\u0947 \u0917\u090f Computer \u0915\u093e Questions \u0915\u093e \u0938\u0902\u0917\u094d\u0930\u0939 \u0964<\/p>\n","protected":false},"author":3,"featured_media":8135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[282],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts\/9296"}],"collection":[{"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/comments?post=9296"}],"version-history":[{"count":3,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts\/9296\/revisions"}],"predecessor-version":[{"id":9299,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/posts\/9296\/revisions\/9299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/media\/8135"}],"wp:attachment":[{"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/media?parent=9296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/categories?post=9296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aiyoit.com\/tutorial\/wp-json\/wp\/v2\/tags?post=9296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}